[{"id":9563,"date":"2025-09-18T17:50:32","date_gmt":"2025-09-18T21:50:32","guid":{"rendered":"https:\/\/dctemple.org\/?page_id=9563"},"modified":"2025-09-18T17:52:53","modified_gmt":"2025-09-18T21:52:53","slug":"email-subscription-confirmation","status":"publish","type":"page","link":"https:\/\/dctemple.org\/fr\/email-subscription-confirmation\/","title":{"rendered":"Email subscription confirmation"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"9563\" class=\"elementor elementor-9563\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1bd0b56 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1bd0b56\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0a0e97f\" data-id=\"0a0e97f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f34700e elementor-widget elementor-widget-heading\" data-id=\"f34700e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Thank you for Subscribing!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d1e7a8 elementor-widget elementor-widget-text-editor\" data-id=\"3d1e7a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>You\u2019re now subscribed to the DC Temple Visitors&#8217; Center Newsletter. We\u2019re excited to have you join our community.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Thank you for Subscribing! You\u2019re now subscribed to the DC Temple Visitors&#8217; Center Newsletter. We\u2019re excited to have you join our community.<\/p>","protected":false},"author":29,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"footnotes":""},"class_list":["post-9563","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Email subscription confirmation - DCTemple.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/fr\/email-subscription-confirmation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Email subscription confirmation - DCTemple.org\" \/>\n<meta property=\"og:description\" content=\"Thank you for Subscribing! You\u2019re now subscribed to the DC Temple Visitors&#8217; Center Newsletter. We\u2019re excited to have you join our community.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/fr\/email-subscription-confirmation\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-18T21:52:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/email-subscription-confirmation\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/email-subscription-confirmation\\\/\",\"name\":\"Email subscription confirmation - DCTemple.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"datePublished\":\"2025-09-18T21:50:32+00:00\",\"dateModified\":\"2025-09-18T21:52:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/email-subscription-confirmation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/email-subscription-confirmation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/email-subscription-confirmation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Email subscription confirmation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Email subscription confirmation - DCTemple.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/fr\/email-subscription-confirmation\/","og_locale":"fr_FR","og_type":"article","og_title":"Email subscription confirmation - DCTemple.org","og_description":"Thank you for Subscribing! You\u2019re now subscribed to the DC Temple Visitors&#8217; Center Newsletter. We\u2019re excited to have you join our community.","og_url":"https:\/\/dctemple.org\/fr\/email-subscription-confirmation\/","og_site_name":"DCTemple.org","article_modified_time":"2025-09-18T21:52:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/email-subscription-confirmation\/","url":"https:\/\/dctemple.org\/email-subscription-confirmation\/","name":"Email subscription confirmation - DCTemple.org","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"datePublished":"2025-09-18T21:50:32+00:00","dateModified":"2025-09-18T21:52:53+00:00","breadcrumb":{"@id":"https:\/\/dctemple.org\/email-subscription-confirmation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/email-subscription-confirmation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/email-subscription-confirmation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"Email subscription confirmation"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/9563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/comments?post=9563"}],"version-history":[{"count":0,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/9563\/revisions"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/media?parent=9563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":9557,"date":"2025-08-28T17:31:32","date_gmt":"2025-08-28T21:31:32","guid":{"rendered":"https:\/\/dctemple.org\/?page_id=9557"},"modified":"2026-01-07T11:28:32","modified_gmt":"2026-01-07T16:28:32","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/dctemple.org\/fr\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"9557\" class=\"elementor elementor-9557\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94d740b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"94d740b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60b1103\" data-id=\"60b1103\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fbf752 elementor-widget elementor-widget-text-editor\" data-id=\"1fbf752\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h1 class=\"wp-block-heading\" data-start=\"152\" data-end=\"168\">Privacy Policy<\/h1><p data-start=\"170\" data-end=\"203\"><strong data-start=\"170\" data-end=\"189\">Effective Date:<\/strong>\u00a08\/28\/2025<\/p><p data-start=\"354\" data-end=\"637\">The Goforth Foundation (\u201cwe,\u201d \u201cour,\u201d or \u201cus\u201d) operates a number of websites designed to provide community resources, news and updates, and information about visiting and participating in events.<br data-start=\"548\" data-end=\"551\" \/>We are committed to protecting your privacy and handling your information responsibly.<\/p><hr data-start=\"639\" data-end=\"642\" \/><h2 data-start=\"644\" data-end=\"672\">1. Information We Collect<\/h2><p data-start=\"674\" data-end=\"720\">We collect the following types of information:<\/p><p data-start=\"722\" data-end=\"781\"><strong data-start=\"722\" data-end=\"767\">Personal Information you provide directly<\/strong>, including:<\/p><ul data-start=\"782\" data-end=\"1006\"><li data-start=\"782\" data-end=\"850\"><p data-start=\"784\" data-end=\"850\">Contact information (such as name, email address, phone number).<\/p><\/li><li data-start=\"851\" data-end=\"925\"><p data-start=\"853\" data-end=\"925\">Reservation or ticketing information (such as tour or event bookings).<\/p><\/li><li data-start=\"926\" data-end=\"960\"><p data-start=\"928\" data-end=\"960\">Survey responses and feedback.<\/p><\/li><li data-start=\"961\" data-end=\"1006\"><p data-start=\"963\" data-end=\"1006\">Email subscriptions and form submissions.<\/p><\/li><\/ul><p data-start=\"1008\" data-end=\"1061\"><strong data-start=\"1008\" data-end=\"1047\">Automatically collected information<\/strong>, including:<\/p><ul data-start=\"1062\" data-end=\"1274\"><li data-start=\"1062\" data-end=\"1115\"><p data-start=\"1064\" data-end=\"1115\">IP address, browser type, and device information.<\/p><\/li><li data-start=\"1116\" data-end=\"1184\"><p data-start=\"1118\" data-end=\"1184\">Website usage data (pages visited, time spent, referral source).<\/p><\/li><li data-start=\"1185\" data-end=\"1274\"><p data-start=\"1187\" data-end=\"1274\">Cookies and similar technologies (to improve site functionality and user experience).<\/p><\/li><\/ul><hr data-start=\"1276\" data-end=\"1279\" \/><h2 data-start=\"1281\" data-end=\"1314\">2. How We Use Your Information<\/h2><p data-start=\"1316\" data-end=\"1355\">We use the information we collect to:<\/p><ul data-start=\"1356\" data-end=\"1653\"><li data-start=\"1356\" data-end=\"1415\"><p data-start=\"1358\" data-end=\"1415\">Provide, manage, and improve our websites and services.<\/p><\/li><li data-start=\"1416\" data-end=\"1500\"><p data-start=\"1418\" data-end=\"1500\">Communicate with you, including sending confirmations, updates, and newsletters.<\/p><\/li><li data-start=\"1501\" data-end=\"1560\"><p data-start=\"1503\" data-end=\"1560\">Understand usage trends and improve visitor experience.<\/p><\/li><li data-start=\"1561\" data-end=\"1618\"><p data-start=\"1563\" data-end=\"1618\">Respond to questions, feedback, and survey responses.<\/p><\/li><li data-start=\"1619\" data-end=\"1653\"><p data-start=\"1621\" data-end=\"1653\">Comply with legal obligations.<\/p><\/li><\/ul><p data-start=\"1655\" data-end=\"1725\">We do\u00a0<strong data-start=\"1661\" data-end=\"1707\">not sell or rent your personal information<\/strong>\u00a0to third parties.<\/p><hr data-start=\"1727\" data-end=\"1730\" \/><h2 data-start=\"1732\" data-end=\"1760\">3. Sharing of Information<\/h2><p data-start=\"1762\" data-end=\"1790\">We only share information:<\/p><ul data-start=\"1791\" data-end=\"2021\"><li data-start=\"1791\" data-end=\"1907\"><p data-start=\"1793\" data-end=\"1907\">With trusted service providers who help us operate our websites (such as ticketing, email, or survey platforms).<\/p><\/li><li data-start=\"1908\" data-end=\"1961\"><p data-start=\"1910\" data-end=\"1961\">If required by law, regulation, or legal process.<\/p><\/li><li data-start=\"1962\" data-end=\"2021\"><p data-start=\"1964\" data-end=\"2021\">To protect our rights, safety, or the safety of others.<\/p><\/li><\/ul><p data-start=\"2023\" data-end=\"2077\">We do not share personal information with advertisers.<\/p><hr data-start=\"2079\" data-end=\"2082\" \/><h2 data-start=\"2084\" data-end=\"2109\">4. Your Privacy Rights<\/h2><p data-start=\"2111\" data-end=\"2170\">Depending on where you live, you may have certain rights:<\/p><ul data-start=\"2172\" data-end=\"2610\"><li data-start=\"2172\" data-end=\"2412\"><p data-start=\"2174\" data-end=\"2412\"><strong data-start=\"2174\" data-end=\"2211\">California Residents (CCPA\/CPRA):<\/strong>\u00a0You have the right to know what personal information we collect, request deletion, opt-out of sale\/sharing of data (we do not sell personal data), and non-discrimination for exercising these rights.<\/p><\/li><li data-start=\"2413\" data-end=\"2610\"><p data-start=\"2415\" data-end=\"2610\"><strong data-start=\"2415\" data-end=\"2441\">European Union (GDPR):<\/strong>\u00a0You have the right to access, correct, delete, restrict processing, and request portability of your personal data. You may also object to processing in certain cases.<\/p><\/li><\/ul><p data-start=\"2612\" data-end=\"2692\">To exercise your rights, please contact us at:\u00a0<strong data-start=\"2659\" data-end=\"2692\"><a class=\"decorated-link cursor-pointer\" rel=\"noopener\" data-start=\"2661\" data-end=\"2690\">privacy@goforthfoundation.org<\/a><\/strong><\/p><hr data-start=\"2694\" data-end=\"2697\" \/><h2 data-start=\"2699\" data-end=\"2718\">5. Data Security<\/h2><p data-start=\"2720\" data-end=\"2941\">We use reasonable technical and organizational safeguards to protect your information against unauthorized access, disclosure, or misuse. However, no system is completely secure, and we cannot guarantee absolute security.<\/p><hr data-start=\"2943\" data-end=\"2946\" \/><h2 data-start=\"2948\" data-end=\"2968\">6. Data Retention<\/h2><p data-start=\"2970\" data-end=\"3116\">We keep your personal information only as long as necessary for the purposes described above, unless a longer retention period is required by law.<\/p><hr data-start=\"3118\" data-end=\"3121\" \/><h2 data-start=\"3123\" data-end=\"3147\">7. Children\u2019s Privacy<\/h2><p data-start=\"3149\" data-end=\"3339\">Our websites are not directed to children under 16. We do not knowingly collect personal information from children. If we learn that we have done so, we will delete the information promptly.<\/p><hr data-start=\"3341\" data-end=\"3344\" \/><h2 data-start=\"3346\" data-end=\"3371\">8. International Users<\/h2><p data-start=\"3373\" data-end=\"3550\">If you are accessing our sites from outside the United States, your information may be transferred and processed in the U.S. By using our websites, you consent to this transfer.<\/p><hr data-start=\"3552\" data-end=\"3555\" \/><h2 data-start=\"3557\" data-end=\"3580\">9. Third-Party Links<\/h2><p data-start=\"3582\" data-end=\"3696\">Our websites may contain links to other websites. We are not responsible for the privacy practices of those sites.<\/p><hr data-start=\"3698\" data-end=\"3701\" \/><h2 data-start=\"3703\" data-end=\"3732\">10. Changes to This Policy<\/h2><p data-start=\"3734\" data-end=\"3901\">We may update this Privacy Policy from time to time. Updates will be posted on this page with a revised effective date. We encourage you to review this page regularly.<\/p><hr data-start=\"3903\" data-end=\"3906\" \/><h2 data-start=\"3908\" data-end=\"3925\">11. Contact Us<\/h2><p data-start=\"3927\" data-end=\"4016\">If you have any questions about this Privacy Policy or your data, please contact us at:<\/p><p data-start=\"4018\" data-end=\"4132\"><strong data-start=\"4018\" data-end=\"4028\">Email:<\/strong>\u00a0<a class=\"decorated-link cursor-pointer\" rel=\"noopener\" data-start=\"4029\" data-end=\"4058\">privacy@goforthfoundation.org<\/a><br data-start=\"4058\" data-end=\"4061\" \/><strong data-start=\"4061\" data-end=\"4073\">Address:<\/strong>\u00a0GoForth Foundation, 6 W Main St, American Fork, UT 84003<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Privacy Policy Effective Date:\u00a08\/28\/2025 The Goforth Foundation (\u201cwe,\u201d \u201cour,\u201d or \u201cus\u201d) operates a number of websites designed to provide community resources, news and updates, and information about visiting and participating in events.We are committed to protecting your privacy and handling your information responsibly. 1. Information We Collect We collect the following types of information: Personal [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"footnotes":""},"class_list":["post-9557","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Policy - DCTemple.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/fr\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - DCTemple.org\" \/>\n<meta property=\"og:description\" content=\"Privacy Policy Effective Date:\u00a08\/28\/2025 The Goforth Foundation (\u201cwe,\u201d \u201cour,\u201d or \u201cus\u201d) operates a number of websites designed to provide community resources, news and updates, and information about visiting and participating in events.We are committed to protecting your privacy and handling your information responsibly. 1. Information We Collect We collect the following types of information: Personal [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/fr\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-07T16:28:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/privacy-policy\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/privacy-policy\\\/\",\"name\":\"Privacy Policy - DCTemple.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"datePublished\":\"2025-08-28T21:31:32+00:00\",\"dateModified\":\"2026-01-07T16:28:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/privacy-policy\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/privacy-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/privacy-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy Policy - DCTemple.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/fr\/privacy-policy\/","og_locale":"fr_FR","og_type":"article","og_title":"Privacy Policy - DCTemple.org","og_description":"Privacy Policy Effective Date:\u00a08\/28\/2025 The Goforth Foundation (\u201cwe,\u201d \u201cour,\u201d or \u201cus\u201d) operates a number of websites designed to provide community resources, news and updates, and information about visiting and participating in events.We are committed to protecting your privacy and handling your information responsibly. 1. Information We Collect We collect the following types of information: Personal [&hellip;]","og_url":"https:\/\/dctemple.org\/fr\/privacy-policy\/","og_site_name":"DCTemple.org","article_modified_time":"2026-01-07T16:28:32+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/privacy-policy\/","url":"https:\/\/dctemple.org\/privacy-policy\/","name":"Privacy Policy - DCTemple.org","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"datePublished":"2025-08-28T21:31:32+00:00","dateModified":"2026-01-07T16:28:32+00:00","breadcrumb":{"@id":"https:\/\/dctemple.org\/privacy-policy\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/9557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/comments?post=9557"}],"version-history":[{"count":0,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/9557\/revisions"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/media?parent=9557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":6661,"date":"2022-11-03T16:55:24","date_gmt":"2022-11-03T20:55:24","guid":{"rendered":"http:\/\/dctemple.org\/?page_id=6661"},"modified":"2025-11-06T11:16:43","modified_gmt":"2025-11-06T16:16:43","slug":"festival-of-lights","status":"publish","type":"page","link":"https:\/\/dctemple.org\/fr\/festival-of-lights\/","title":{"rendered":"Festival des lumi\u00e8res"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6661\" class=\"elementor elementor-6661\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83742de elementor-section-full_width elementor-section-stretched elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"83742de\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b4d5de9\" data-id=\"b4d5de9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ef21c52 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ef21c52\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a4bd870\" data-id=\"a4bd870\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13ad12b elementor-widget elementor-widget-heading\" data-id=\"13ad12b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Washington DC Temple Festival of Lights 2025<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df26a41 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"df26a41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ab0959 elementor-widget elementor-widget-text-editor\" data-id=\"7ab0959\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Le Festival des Lumi\u00e8res du Temple de Washington DC pr\u00e9sente plus de 500\u00a0000 illuminations et de magnifiques sapins de No\u00ebl. Le centre d&#039;accueil des visiteurs pr\u00e9sente de magnifiques cr\u00e8ches repr\u00e9sentant des cr\u00e8ches du monde entier et accueille chaque jour des spectacles de No\u00ebl gratuits et ouverts au public.<\/p><h3>Parking passes are now required. For details about the 2025 Festival of Lights, including the performance schedule and how to reserve a mandatory parking pass, please visit <a href=\"https:\/\/dctemplevisitorscenter.org\/festival-of-lights\/\">DCTempleVisitorsCenter.org.<\/a>\u00a0<\/h3><p><i>Que la F\u00eate des Lumi\u00e8res apporte l&#039;Esprit de No\u00ebl dans votre c\u0153ur !<\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ebc560 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"4ebc560\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tVenez voir la F\u00eate des Lumi\u00e8res au Temple de Washington DC. Profitez de plus de 400 000 lumi\u00e8res et d&#039;arbres de No\u00ebl magnifiquement d\u00e9cor\u00e9s. Le centre des visiteurs est ouvert de 10 h 00 \u00e0 21 h 00 tous les jours pour que vous puissiez voir de magnifiques expositions de la Cr\u00e8che pr\u00e9sentant des cr\u00e8ches du monde entier, assister \u00e0 l&#039;un des nombreux spectacles et redonner \u00e0 la communaut\u00e9 aux Light the World Giving Machines. Le stationnement et les spectacles sont gratuits, mais les spectacles n\u00e9cessitent des billets. Faites d\u00e9filer vers le bas ou cliquez sur l&#039;un des boutons pour plus d&#039;informations.\n\n<i>Que la F\u00eate des Lumi\u00e8res apporte l&#039;Esprit de No\u00ebl dans votre c\u0153ur !<\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b8b5343 elementor-section-content-space-evenly elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b8b5343\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-fcf525f\" data-id=\"fcf525f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3aaad7a elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"3aaad7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#performances\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Les performances<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7aec92f\" data-id=\"7aec92f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8e2d22 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"a8e2d22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#nativities\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Pr\u00e9sentoirs de cr\u00e8che<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3f6c35e\" data-id=\"3f6c35e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a62e971 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"a62e971\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#christmasparking\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Informations sur le stationnement<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3994678\" data-id=\"3994678\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f68d75 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"5f68d75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#folfaq\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">FAQ<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e5eb52 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e5eb52\" data-element_type=\"section\" data-e-type=\"section\" id=\"performances\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56c7d2e\" data-id=\"56c7d2e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4eb0cc4 elementor-widget elementor-widget-heading\" data-id=\"4eb0cc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les performances<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba3af86 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ba3af86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90d6a2c elementor-widget elementor-widget-text-editor\" data-id=\"90d6a2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Malheureusement, nous sommes arriv\u00e9s \u00e0 la fin de nos repr\u00e9sentations. La F\u00eate des Lumi\u00e8res se poursuit jusqu&#039;au 2 janvier. Venez voir les vitrines de la cr\u00e8che, les sapins de No\u00ebl, les Light the World Giving Machines et, bien s\u00fbr, les lumi\u00e8res \u00e9blouissantes. Le stationnement est gratuit.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dd18078 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dd18078\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b0eb717\" data-id=\"b0eb717\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-029a2b1\" data-id=\"029a2b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30f6776 elementor-widget elementor-widget-text-editor\" data-id=\"30f6776\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>1 d\u00e9cembre \u2013 2 janvier<\/b><\/p>\n<p style=\"text-align: center;\">Cr\u00e9puscule \u2013 21 h 00 \u2013 Lumi\u00e8res de No\u00ebl ouvertes au public<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2c31a18\" data-id=\"2c31a18\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e37ffc elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0e37ffc\" data-element_type=\"section\" data-e-type=\"section\" id=\"nativities\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c016633\" data-id=\"c016633\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a19864d elementor-widget elementor-widget-heading\" data-id=\"a19864d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pr\u00e9sentoirs de cr\u00e8che<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b8b3e4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3b8b3e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-154b803 elementor-widget elementor-widget-text-editor\" data-id=\"154b803\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLe mot fran\u00e7ais cr\u00e8che est utilis\u00e9 pour d\u00e9crire une sc\u00e8ne de la nativit\u00e9 particuli\u00e8re affich\u00e9e pendant la saison de No\u00ebl. Ces sc\u00e8nes, repr\u00e9sentant la naissance de J\u00e9sus-Christ, sont devenues populaires dans les communaut\u00e9s du monde chr\u00e9tien \u00e0 partir du XIIIe si\u00e8cle. Cette exposition pr\u00e9sente 87 cr\u00e8ches repr\u00e9sentant 64 pays.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-400c801 elementor-widget elementor-widget-image\" data-id=\"400c801\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-scaled.webp\" class=\"attachment-full size-full wp-image-7022\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-scaled.webp 1920w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-300x225.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-1024x768.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-768x576.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-1536x1152.webp 1536w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-16x12.webp 16w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bbbb7ca elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bbbb7ca\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6681e0d\" data-id=\"6681e0d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10c9958 elementor-widget elementor-widget-spacer\" data-id=\"10c9958\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d29cad elementor-widget elementor-widget-heading\" data-id=\"4d29cad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Recevez des mises \u00e0 jour sur la F\u00eate des Lumi\u00e8res<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76e0bcb elementor-widget elementor-widget-html\" data-id=\"76e0bcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<script type=\"text\/javascript\" src=\"https:\/\/mautic.goforthfoundation.org\/form\/generate.js?id=3\"><\/script>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94b199c elementor-widget elementor-widget-spacer\" data-id=\"94b199c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e15408 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e15408\" data-element_type=\"section\" data-e-type=\"section\" id=\"christmasparking\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8e1fe31\" data-id=\"8e1fe31\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-92a8797 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92a8797\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5b96bed\" data-id=\"5b96bed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-126b531 elementor-widget elementor-widget-heading\" data-id=\"126b531\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Informations sur le stationnement<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9774e9f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9774e9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c1a0e7 elementor-widget elementor-widget-text-editor\" data-id=\"1c1a0e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Le parking pour voir la F\u00eate des Lumi\u00e8res et le Centre des Visiteurs est <strong>libre<\/strong> et <strong>aucune carte de stationnement n&#039;est n\u00e9cessaire.<\/strong><\/p>\n\n<p>Trois stationnements sont disponibles, tous \u00e0 distance de marche des expositions. Apr\u00e8s la tomb\u00e9e de la nuit, il y aura des pr\u00e9pos\u00e9s au stationnement \u00e0 chaque entr\u00e9e pour vous diriger vers le stationnement disponible.<\/p>\n\n<p>Centre des visiteurs - 9900 Stoneybrook Dr.<\/p>\n\n<p>Temple \u2013 9900 promenade Stoneybrook<\/p>\n\n<p>Centre de pieu (d\u00e9bordement) - 10000 Stoneybrook Dr.<\/p>\n\n<p>Si vous conduisez vers le nord sur Stoneybrook, la premi\u00e8re entr\u00e9e sur la gauche est le centre des visiteurs, la seconde est le temple et la troisi\u00e8me est le centre de pieu.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d5dd461\" data-id=\"d5dd461\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf9b6c6 elementor-widget elementor-widget-google_maps\" data-id=\"bf9b6c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Washington%20DC%20Temple%20Visitors%27%20Center%2C%20Kensington%2C%20MD&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Centre d&#039;accueil des visiteurs du temple de Washington DC, Kensington, MD\"\n\t\t\t\t\taria-label=\"Centre d&#039;accueil des visiteurs du temple de Washington DC, Kensington, MD\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd31676 elementor-widget elementor-widget-spacer\" data-id=\"dd31676\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ea1022 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ea1022\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-16f8415\" data-id=\"16f8415\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35b6027 elementor-widget elementor-widget-heading\" data-id=\"35b6027\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Avez-vous appr\u00e9ci\u00e9 votre visite?<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ce639bc elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ce639bc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d63f61c\" data-id=\"d63f61c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fb0e01 elementor-widget elementor-widget-html\" data-id=\"4fb0e01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<div style=\"text-align:center\">\r\n<a href=\"\/fr\/feedback\/review\/\"><div style=\"width: 32%; float: left;\"><i class=\"fas fa-smile-beam\" style=\"font-size: 70px; color: #FFD084;\"><\/i><p style=\"font-size: 15px;\">J&#039;ai ador\u00e9 !<\/p><\/div><\/a>\r\n<a href=\"\/fr\/feedback\/good-feedback\/\"><div style=\"width: 32%; float: left;\"><i class=\"fas fa-smile\" style=\"font-size: 70px; color: #8A926F;\"><\/i><p style=\"font-size: 15px;\">C&#039;\u00e9tait bon.<\/p><\/div><\/a>\r\n<a href=\"\/fr\/feedback\/negative-feedback\/\"><div style=\"width: 32%; float: left;\"><i class=\"fas fa-frown\" style=\"font-size: 70px; color: #244480b0;\"><\/i><p style=\"font-size: 15px;\">Je n&#039;ai pas appr\u00e9ci\u00e9.<\/p><\/div><\/a>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7518f69 elementor-widget elementor-widget-spacer\" data-id=\"7518f69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4013575 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4013575\" data-element_type=\"section\" data-e-type=\"section\" id=\"folfaq\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d6d42ae\" data-id=\"d6d42ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77251fc elementor-widget elementor-widget-spacer\" data-id=\"77251fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99e93a1 elementor-widget elementor-widget-heading\" data-id=\"99e93a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ sur la F\u00eate des Lumi\u00e8res<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d952d72 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d952d72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f30f6d6 elementor-widget elementor-widget-toggle\" data-id=\"f30f6d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2541\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2541\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Les \u00e9v\u00e9nements de la F\u00eate des Lumi\u00e8res sont-ils gratuits ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2541\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2541\">Tous les \u00e9v\u00e9nements et expositions de la F\u00eate des Lumi\u00e8res au temple de Washington DC sont gratuits. Les repr\u00e9sentations exigent que vous r\u00e9serviez des billets gratuits \u00e0 l&#039;avance. Les d\u00e9tenteurs de billets sont pri\u00e9s d&#039;\u00eatre \u00e0 leur place au plus tard 15 minutes avant la repr\u00e9sentation. Pass\u00e9 ce d\u00e9lai, la file d&#039;attente sera admise \u00e0 pourvoir les places restantes.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2542\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2542\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ai-je besoin d&#039;un billet et y a-t-il des si\u00e8ges d&#039;attente ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2542\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2542\">Tous les spectacles n\u00e9cessitent un billet pour entrer. Nous vous recommandons de r\u00e9server vos billets \u00e0 l&#039;avance pour vous assurer d&#039;avoir des places. Cependant, si vous n&#039;avez pas de billet, arrivez t\u00f4t et placez-vous dans la file d&#039;attente \u00e0 gauche de l&#039;entr\u00e9e principale. Les d\u00e9tenteurs de billets seront admis en premier. Ils sont pri\u00e9s d&#039;\u00eatre \u00e0 leur place 15 minutes avant la repr\u00e9sentation. Environ 10 \u00e0 15 minutes avant l&#039;heure du spectacle, les billets expirent, permettant aux personnes en file d&#039;attente d&#039;\u00eatre assises dans les si\u00e8ges restants.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2543\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2543\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Je ne suis pas membre de votre \u00e9glise, puis-je quand m\u00eame venir ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2543\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2543\"><p>Absolument! Tout le monde est le bienvenu pour assister \u00e0 nos \u00e9v\u00e9nements et \u00e0 nos cultes (<a href=\"https:\/\/dctemple.org\/fr\/sunday-service\/\">en savoir plus sur nos cultes<\/a>). Nous demandons seulement \u00e0 tous les participants de s&#039;habiller modestement, d&#039;utiliser un langage propre et de traiter tout le monde avec respect. Nous sommes des chr\u00e9tiens qui faisons de notre mieux pour suivre les commandements et les enseignements du Christ. Quel que soit votre parcours, vous \u00eates invit\u00e9 \u00e0 nous rejoindre !<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2544\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2544\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Que dois-je porter?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2544\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2544\"><p>La robe d\u00e9pend du type d&#039;\u00e9v\u00e9nement. Les affaires d\u00e9contract\u00e9es sont une bonne r\u00e8gle de base pour les \u00e9v\u00e9nements de l&#039;Auditorium. Vous pouvez porter des v\u00eatements modestes dans lesquels vous vous sentez \u00e0 l&#039;aise. Pour les d\u00e9votions et les cultes du dimanche, la plupart des hommes portent des costumes, des vestes de sport ou des chemises et des cravates, et les femmes portent des robes ou des jupes. Les enfants se d\u00e9guisent aussi g\u00e9n\u00e9ralement.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2545\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2545\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Puis-je amener mes enfants ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2545\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2545\"><p>Tous les \u00e9v\u00e9nements de la F\u00eate des Lumi\u00e8res sont familiaux et les enfants sont les bienvenus ! Cependant, par respect pour les artistes et les autres membres du public, nous sugg\u00e9rons que les enfants pr\u00e9sents soient assez \u00e2g\u00e9s pour rester assis et attentifs tout au long du spectacle et que tout enfant perturbateur soit calm\u00e9 dans le hall.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2546\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2546\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Comment puis-je obtenir des mises \u00e0 jour sur les \u00e9v\u00e9nements de la F\u00eate des Lumi\u00e8res\u00a0?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2546\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2546\"><p>Les d\u00e9tenteurs de billets pour un \u00e9v\u00e9nement particulier recevront automatiquement des mises \u00e0 jour importantes par e-mail concernant cet \u00e9v\u00e9nement et vous pouvez trouver d&#039;autres informations utiles sur les listes d&#039;\u00e9v\u00e9nements individuels sur dctemple.org. Nous vous recommandons \u00e9galement de suivre le centre des visiteurs du temple de Washington DC sur <a href=\"https:\/\/www.facebook.com\/dctemplevc\">Facebook<\/a> pour des mises \u00e0 jour g\u00e9n\u00e9rales de No\u00ebl et des conseils et rappels utiles sur les \u00e9v\u00e9nements \u00e0 venir, le stationnement, la tenue vestimentaire, etc. Nous vous invitons \u00e9galement \u00e0 vous abonner \u00e0 notre site Web pour rester \u00e0 jour sur tout ce qui se passe au temple de Washington DC.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2547\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2547\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">O\u00f9 puis-je stationner?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2547\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2547\"><p>Stationnement pour voir la F\u00eate des Lumi\u00e8res Le stationnement est gratuit et aucun laissez-passer n&#039;est n\u00e9cessaire. Trois stationnements sont disponibles, tous \u00e0 distance de marche des expositions.\u00a0<span style=\"background-color: var(--nv-site-bg); color: var( --e-global-color-text ); letter-spacing: var(--bodyletterspacing); text-transform: var(--bodytexttransform);\">Il y aura des pr\u00e9pos\u00e9s au stationnement \u00e0 chaque entr\u00e9e pour vous diriger vers le stationnement disponible.<\/span><\/p><p>Centre des visiteurs - 9900 Stoneybrook Dr.<br \/>Temple \u2013 9900 promenade Stoneybrook<br \/>Centre de pieu\u00a0<span style=\"background-color: var(--nv-site-bg); color: var( --e-global-color-text ); letter-spacing: var(--bodyletterspacing); text-transform: var(--bodytexttransform);\">(d\u00e9bordement)<\/span><span style=\"background-color: var(--nv-site-bg); color: var( --e-global-color-text ); letter-spacing: var(--bodyletterspacing); text-transform: var(--bodytexttransform);\">\u00a0\u2013 10000 promenade Stoneybrook\u00a0<\/span><\/p><p>(Si vous conduisez vers le nord sur Stoneybrook, la premi\u00e8re entr\u00e9e sur la gauche est le centre des visiteurs, la seconde est le temple et la troisi\u00e8me est le centre de pieu.)<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2548\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-2548\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">A quelle heure dois-je arriver ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2548\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-2548\"><p>Les portes du th\u00e9\u00e2tre ouvrent g\u00e9n\u00e9ralement environ 30 minutes avant les repr\u00e9sentations (parfois plus t\u00f4t), mais la file d&#039;attente pour les grands \u00e9v\u00e9nements commencera plus t\u00f4t que cela. Nous vous recommandons d&#039;arriver suffisamment t\u00f4t pour profiter des expositions de la Nativit\u00e9 et d&#039;autres favoris saisonniers, ainsi que des expositions r\u00e9guli\u00e8res du centre des visiteurs.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2549\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-2549\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Et si je ne peux pas y assister ? Puis-je annuler mes billets ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2549\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-2549\"><p>Vous pouvez mettre \u00e0 jour ou annuler tout billet gratuit via Eventbrite. Nous vous remercions de le faire si vous ne pouvez pas y assister afin que nous ayons un d\u00e9compte plus pr\u00e9cis des participants.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-25410\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-25410\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Puis-je prendre des photos ou des vid\u00e9os\u00a0?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-25410\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-25410\"><p>Cela d\u00e9pend de l&#039;\u00e9v\u00e9nement, alors v\u00e9rifiez les listes d&#039;\u00e9v\u00e9nements individuels et \u00e9coutez les annonces faites avant la repr\u00e9sentation. Les visiteurs sont toujours encourag\u00e9s \u00e0 prendre des photos et des vid\u00e9os avant et apr\u00e8s la repr\u00e9sentation, ou \u00e0 l&#039;ext\u00e9rieur sur le terrain du temple. Nous serions ravis de voir vos photos ! Assurez-vous de nous TAGUER, @DCTempleVC.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-25411\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-25411\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">J&#039;ai des questions suppl\u00e9mentaires, comment y r\u00e9pondre\u00a0? <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-25411\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-25411\"><div>Si vous avez des questions suppl\u00e9mentaires, veuillez nous \u00e9crire \u00e0 <a href=\"mailto:wdcvisitorscenter@gmail.com\" target=\"_blank\" rel=\"noopener\">wdcvisitorscenter@gmail.com<\/a>. Nous vous r\u00e9pondrons dans les plus brefs d\u00e9lais, et dans les 24 heures.\u00a0\u00a0<\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ccb94c elementor-widget elementor-widget-spacer\" data-id=\"4ccb94c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3cf05aa elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3cf05aa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61d1196\" data-id=\"61d1196\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23f37a9 elementor-widget elementor-widget-spacer\" data-id=\"23f37a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-509a2a1 elementor-blockquote--skin-quotation elementor-blockquote--align-center elementor-widget elementor-widget-blockquote\" data-id=\"509a2a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\tEt voici, je suis la lumi\u00e8re et la vie du monde ; et j&#039;ai bu \u00e0 cette coupe am\u00e8re que le P\u00e8re m&#039;a donn\u00e9e, et j&#039;ai glorifi\u00e9 le P\u00e8re en prenant sur moi les p\u00e9ch\u00e9s du monde, dans lesquels j&#039;ai souffert la volont\u00e9 du P\u00e8re en toutes choses depuis le commencement.\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">3 N\u00e9phi 11:11<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e51b847 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e51b847\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/uqr.to\/1a4j9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus sur la visite du Christ aux Am\u00e9riques<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42770a5 elementor-widget elementor-widget-spacer\" data-id=\"42770a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27f3ba2 elementor-widget elementor-widget-spacer\" data-id=\"27f3ba2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Washington DC Temple Festival of Lights 2025 The Festival of Lights at the Washington DC Temple features over 500,000 lights and beautifully decorated Christmas Trees. The Visitors&#8217; Center exhibits beautiful Cr\u00e9che displays featuring nativities from around the world and hosts daily holiday performances that are free and open to the public. Parking passes are now [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"footnotes":""},"class_list":["post-6661","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festival of Lights - DCTemple.org<\/title>\n<meta name=\"description\" content=\"The Festival of Lights, a yearly tradition at the DC Temple, features musical performances and over 500,000 Christmas lights. All are welcome.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/fr\/festival-of-lights\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festival of Lights - DCTemple.org\" \/>\n<meta property=\"og:description\" content=\"The Festival of Lights, a yearly tradition at the DC Temple, features musical performances and over 500,000 Christmas lights. All are welcome.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/fr\/festival-of-lights\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T16:16:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/festival-of-lights\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/festival-of-lights\\\/\",\"name\":\"Festival of Lights - DCTemple.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/festival-of-lights\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/festival-of-lights\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Creche-wall-2-scaled.webp\",\"datePublished\":\"2022-11-03T20:55:24+00:00\",\"dateModified\":\"2025-11-06T16:16:43+00:00\",\"description\":\"The Festival of Lights, a yearly tradition at the DC Temple, features musical performances and over 500,000 Christmas lights. All are welcome.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/festival-of-lights\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/festival-of-lights\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/festival-of-lights\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Creche-wall-2-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Creche-wall-2-scaled.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/festival-of-lights\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festival of Lights\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festival of Lights - DCTemple.org","description":"The Festival of Lights, a yearly tradition at the DC Temple, features musical performances and over 500,000 Christmas lights. All are welcome.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/fr\/festival-of-lights\/","og_locale":"fr_FR","og_type":"article","og_title":"Festival of Lights - DCTemple.org","og_description":"The Festival of Lights, a yearly tradition at the DC Temple, features musical performances and over 500,000 Christmas lights. All are welcome.","og_url":"https:\/\/dctemple.org\/fr\/festival-of-lights\/","og_site_name":"DCTemple.org","article_modified_time":"2025-11-06T16:16:43+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-scaled.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/festival-of-lights\/","url":"https:\/\/dctemple.org\/festival-of-lights\/","name":"Festival of Lights - DCTemple.org","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dctemple.org\/festival-of-lights\/#primaryimage"},"image":{"@id":"https:\/\/dctemple.org\/festival-of-lights\/#primaryimage"},"thumbnailUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-scaled.webp","datePublished":"2022-11-03T20:55:24+00:00","dateModified":"2025-11-06T16:16:43+00:00","description":"The Festival of Lights, a yearly tradition at the DC Temple, features musical performances and over 500,000 Christmas lights. All are welcome.","breadcrumb":{"@id":"https:\/\/dctemple.org\/festival-of-lights\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/festival-of-lights\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dctemple.org\/festival-of-lights\/#primaryimage","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-scaled.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-scaled.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/festival-of-lights\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"Festival of Lights"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/6661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/comments?post=6661"}],"version-history":[{"count":0,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/6661\/revisions"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/media?parent=6661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":6337,"date":"2022-08-29T17:13:41","date_gmt":"2022-08-29T21:13:41","guid":{"rendered":"http:\/\/dctemple.org\/?page_id=6337"},"modified":"2026-07-02T10:41:56","modified_gmt":"2026-07-02T14:41:56","slug":"home","status":"publish","type":"page","link":"https:\/\/dctemple.org\/fr\/","title":{"rendered":"Accueil"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6337\" class=\"elementor elementor-6337\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-128a24e e-con-full e-flex e-con e-parent\" data-id=\"128a24e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5ce8628 e-con-full e-flex e-con e-child\" data-id=\"5ce8628\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0537249 elementor-widget elementor-widget-slider_revolution\" data-id=\"0537249\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"slider_revolution.default\">\n\t\t\t\t\t\n\t\t<div class=\"wp-block-themepunch-revslider\">\n\t\t\t<!-- START Default Home Page Slider REVOLUTION SLIDER 6.5.11 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_11_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_11_1\" style=\"\" data-version=\"6.5.11\">\n\t\t\t\t\t<rs-slides>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-16\" data-title=\"Slide\" data-anim=\"ms:330;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-11-slide-16-layer-4\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:50px;y:50px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:300px;h:180px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" data-lazyload=\"\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-11-slide-16-layer-16\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:2070px;h:900px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"1920\" height=\"835\" data-lazyload=\"\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Temple_oct_2009_fullimage_2.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-17\" data-title=\"Slide\" data-anim=\"ms:310;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-11-slide-17-layer-15\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:2070px;h:900px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"1920\" height=\"835\" data-lazyload=\"\/\/dctemple.org\/wp-content\/uploads\/2022\/09\/1-13.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-31\" data-title=\"Slide\" data-anim=\"ms:320;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-11-slide-31-layer-14\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:2070px;h:898px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"1920\" height=\"833\" data-lazyload=\"\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Christus-2.jpeg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-18\" data-title=\"Slide\" data-anim=\"ms:320;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-11-slide-18-layer-14\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:2070px;h:900px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"1920\" height=\"835\" data-lazyload=\"\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/VC-reflection-4.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-33\" data-title=\"Slide\" data-anim=\"ms:320;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-11-slide-33-layer-14\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:2070px;h:900px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"1920\" height=\"835\" data-lazyload=\"\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Sunset-2-1.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-20\" data-title=\"Slide\" data-anim=\"ms:310;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-11-slide-20-layer-12\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:2070px;h:900px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"1920\" height=\"835\" data-lazyload=\"\/\/dctemple.org\/wp-content\/uploads\/2022\/09\/1-7.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-34\" data-title=\"Slide\" data-anim=\"ms:330;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-11-slide-34-layer-4\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:50px;y:50px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:300px;h:180px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" data-lazyload=\"\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-11-slide-34-layer-16\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:2070px;h:900px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"1920\" height=\"835\" data-lazyload=\"\/\/dctemple.org\/wp-content\/uploads\/2022\/09\/1-10.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t\t<rs-static-layers><!--\n\t\t\t\t\t--><\/rs-static-layers>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script type=\"text\/javascript\">\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_11_1',rl:[1240,1024,778,480],el:[750],gw:[1240],gh:[750],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider111\"]!==undefined) {window.RS_MODULES.modules[\"revslider111\"].once = false;window.revapi11 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ccb5ca4 homepage-callout-box e-flex e-con-boxed e-con e-parent\" data-id=\"ccb5ca4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-730b35c e-con-full e-flex e-con e-child\" data-id=\"730b35c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7931f1e elementor-cta--skin-cover elementor-widget-tablet__width-auto elementor-widget__width-initial elementor-widget-mobile__width-auto elementor-widget elementor-widget-call-to-action\" data-id=\"7931f1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h1 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tCome See the Washington DC Temple\t\t\t\t\t<\/h1>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tVisible from the beltway, the Washington DC Temple offers beautiful grounds and stunning architecture. There are activities year round at the Visitors' Center. Come &amp; visit with your friends and family. Visit the DC Temple Visitors' Center website to book tours and learn more about the exhibits and events there.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-md\" href=\"https:\/\/dctemplevisitorscenter.org\/\">\n\t\t\t\t\t\tVisitors' Center\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dd63e26 e-flex e-con-boxed e-con e-parent\" data-id=\"dd63e26\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-03314c5 e-con-full e-flex e-con e-child\" data-id=\"03314c5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c1328f pp-info-box-left elementor-widget-tablet__width-initial elementor-widget elementor-widget-pp-info-box\" data-id=\"2c1328f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-info-box.default\">\n\t\t\t\t\t\t\t<div class=\"pp-info-box-container\">\n\t\t\t<div class=\"pp-info-box\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dctemplevisitorscenter.org\/events\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-info-box-icon pp-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-calendar-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M148 288h-40c-6.6 0-12-5.4-12-12v-40c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12zm108-12v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 96v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm192 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96-260v352c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V112c0-26.5 21.5-48 48-48h48V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h128V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h48c26.5 0 48 21.5 48 48zm-48 346V160H48v298c0 3.3 2.7 6 6 6h340c3.3 0 6-2.7 6-6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-info-box-content\">\n\t\t\t\t\t<div class=\"pp-info-box-title-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-title-container\">\n\t\t\t\t\t\t\t\t<h2 class=\"pp-info-box-title\">\n\t\t\t\t\t\t\t\t\tSee Upcoming\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"pp-info-box-subtitle\">\n\t\t\t\t\t\t\t\tEvents\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-description\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dctemplevisitorscenter.org\/events\/\">Check out What Events are Going on.<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-501b0a4 e-con-full e-flex e-con e-child\" data-id=\"501b0a4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9b93978 pp-info-box-left elementor-widget-tablet__width-initial elementor-widget elementor-widget-pp-info-box\" data-id=\"9b93978\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-info-box.default\">\n\t\t\t\t\t\t\t<div class=\"pp-info-box-container\">\n\t\t\t<div class=\"pp-info-box\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dctemplevisitorscenter.org\/visitors-center\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-info-box-icon pp-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-location-arrow\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M444.52 3.52L28.74 195.42c-47.97 22.39-31.98 92.75 19.19 92.75h175.91v175.91c0 51.17 70.36 67.17 92.75 19.19l191.9-415.78c15.99-38.39-25.59-79.97-63.97-63.97z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-info-box-content\">\n\t\t\t\t\t<div class=\"pp-info-box-title-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-title-container\">\n\t\t\t\t\t\t\t\t<h2 class=\"pp-info-box-title\">\n\t\t\t\t\t\t\t\t\tVisit the\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"pp-info-box-subtitle\">\n\t\t\t\t\t\t\t\tVisitors' Center\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-description\">\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/dctemplevisitorscenter.org\/visitors-center\/\" target=\"_blank\" rel=\"noopener\">Learn More About What There is to do!<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1113ec1 e-con-full e-flex e-con e-child\" data-id=\"1113ec1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be930d6 pp-info-box-left elementor-widget-tablet__width-initial elementor-widget elementor-widget-pp-info-box\" data-id=\"be930d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-info-box.default\">\n\t\t\t\t\t\t\t<div class=\"pp-info-box-container\">\n\t\t\t<div class=\"pp-info-box\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dctemple.org\/sunday-service\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-info-box-icon pp-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hands-helping\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M488 192H336v56c0 39.7-32.3 72-72 72s-72-32.3-72-72V126.4l-64.9 39C107.8 176.9 96 197.8 96 220.2v47.3l-80 46.2C.7 322.5-4.6 342.1 4.3 357.4l80 138.6c8.8 15.3 28.4 20.5 43.7 11.7L231.4 448H368c35.3 0 64-28.7 64-64h16c17.7 0 32-14.3 32-32v-64h8c13.3 0 24-10.7 24-24v-48c0-13.3-10.7-24-24-24zm147.7-37.4L555.7 16C546.9.7 527.3-4.5 512 4.3L408.6 64H306.4c-12 0-23.7 3.4-33.9 9.7L239 94.6c-9.4 5.8-15 16.1-15 27.1V248c0 22.1 17.9 40 40 40s40-17.9 40-40v-88h184c30.9 0 56 25.1 56 56v28.5l80-46.2c15.3-8.9 20.5-28.4 11.7-43.7z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-info-box-content\">\n\t\t\t\t\t<div class=\"pp-info-box-title-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-title-container\">\n\t\t\t\t\t\t\t\t<h2 class=\"pp-info-box-title\">\n\t\t\t\t\t\t\t\t\tWorship\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"pp-info-box-subtitle\">\n\t\t\t\t\t\t\t\tWith Us\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-description\">\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/dctemple.org\/sunday-service\/\">Find Meeting Locations in the DC Area.<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-139f3ab e-flex e-con-boxed e-con e-parent\" data-id=\"139f3ab\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9a1e342 e-con-full e-flex e-con e-child\" data-id=\"9a1e342\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35cb9e6 elementor-widget elementor-widget-pp-counter\" data-id=\"35cb9e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-counter.default\">\n\t\t\t\t\t\t\t<div class=\"pp-counter-container\">\n\t\t\t<div class=\"pp-counter pp-counter-layout-1\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-counter-number-title-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"pp-counter-number-wrap\">\n\t\t\t\t\t\t<div class=\"pp-counter-number pp-counter-number-35cb9e6\" data-duration=\"750\" data-to-value=\"17887212\" data-from-value=\"0\" data-delimiter=\",\">\n\t\t\t\t0\t\t\t<\/div>\n\t\t\t\t\t\t\t<span class=\"pp-counter-number-suffix\">\n\t\t\t\t\t+\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"pp-counter-title-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-counter-title\">\n\t\t\t\t\t\tMembers Worldwide\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-48bfa67 e-con-full e-flex e-con e-child\" data-id=\"48bfa67\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0a4861b elementor-widget elementor-widget-pp-counter\" data-id=\"0a4861b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-counter.default\">\n\t\t\t\t\t\t\t<div class=\"pp-counter-container\">\n\t\t\t<div class=\"pp-counter pp-counter-layout-1\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-counter-number-title-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"pp-counter-number-wrap\">\n\t\t\t\t\t\t<div class=\"pp-counter-number pp-counter-number-0a4861b\" data-duration=\"750\" data-to-value=\"32046\" data-from-value=\"0\" data-delimiter=\",\">\n\t\t\t\t0\t\t\t<\/div>\n\t\t\t\t\t\t\t<span class=\"pp-counter-number-suffix\">\n\t\t\t\t\t+\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"pp-counter-title-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-counter-title\">\n\t\t\t\t\t\tCongregations\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-df970fe e-con-full e-flex e-con e-child\" data-id=\"df970fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-398bce2 elementor-widget elementor-widget-pp-counter\" data-id=\"398bce2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-counter.default\">\n\t\t\t\t\t\t\t<div class=\"pp-counter-container\">\n\t\t\t<div class=\"pp-counter pp-counter-layout-1\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-counter-number-title-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"pp-counter-number-wrap\">\n\t\t\t\t\t\t<div class=\"pp-counter-number pp-counter-number-398bce2\" data-duration=\"750\" data-to-value=\"204\" data-from-value=\"0\" data-delimiter=\",\">\n\t\t\t\t0\t\t\t<\/div>\n\t\t\t\t\t\t\t<span class=\"pp-counter-number-suffix\">\n\t\t\t\t\t+\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"pp-counter-title-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-counter-title\">\n\t\t\t\t\t\tOperating Temples\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f772aa e-con-full e-flex e-con e-child\" data-id=\"6f772aa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf33099 elementor-widget-tablet__width-initial elementor-widget elementor-widget-pp-counter\" data-id=\"cf33099\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-counter.default\">\n\t\t\t\t\t\t\t<div class=\"pp-counter-container\">\n\t\t\t<div class=\"pp-counter pp-counter-layout-1\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-counter-number-title-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"pp-counter-number-wrap\">\n\t\t\t\t\t\t<div class=\"pp-counter-number pp-counter-number-cf33099\" data-duration=\"750\" data-to-value=\"114727\" data-from-value=\"0\" data-delimiter=\",\">\n\t\t\t\t0\t\t\t<\/div>\n\t\t\t\t\t\t\t<span class=\"pp-counter-number-suffix\">\n\t\t\t\t\t+\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"pp-counter-title-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-counter-title\">\n\t\t\t\t\t\tTotal Volunteer Missionaries\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cea31d1 e-flex e-con-boxed e-con e-parent\" data-id=\"cea31d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3a06b94 e-con-full e-flex e-con e-child\" data-id=\"3a06b94\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c175aef elementor-widget elementor-widget-text-editor\" data-id=\"c175aef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>Washington DC Temple<\/h2><p>The Washington DC Temple was the first Latter-day Saint temple to be built on the East Coast of the United States. Completed in 1974, it is the third-largest temple in the world.<\/p><p>Visitors from all over the world come to this sacred site for its beauty and religious significance. Members of the Church gather inside the temple for sacred religious ceremonies that bring them closer to God, while tourists come to view the temple grounds and enjoy the Visitors\u2019 Center. There is something for everyone at the Washington DC Temple.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8041d88 e-con-full e-flex e-con e-child\" data-id=\"8041d88\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4263dd3 elementor-widget elementor-widget-image\" data-id=\"4263dd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"960\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple.webp\" class=\"attachment-full size-full wp-image-6357\" alt=\"The Washington DC Temple, visible from the treeline, sits majestically as it stretches to the blue sky coated with wispy clouds.\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple.webp 1280w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple-300x225.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple-1024x768.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple-768x576.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple-16x12.webp 16w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Come See the Washington DC Temple Visible from the beltway, the Washington DC Temple offers beautiful grounds and stunning architecture. There are activities year round at the Visitors&#8217; Center. Come &amp; visit with your friends and family. Visit the DC Temple Visitors&#8217; Center website to book tours and learn more about the exhibits and events [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-6337","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Washington DC Temple - Home<\/title>\n<meta name=\"description\" content=\"The Washington DC Temple offers beautiful grounds and stunning architecture. There are activities year-round at the Visitors&#039; Center.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Washington DC Temple - Home\" \/>\n<meta property=\"og:description\" content=\"The Washington DC Temple offers beautiful grounds and stunning architecture. There are activities year-round at the Visitors&#039; Center.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/fr\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-02T14:41:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/\",\"name\":\"Washington DC Temple - Home\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Washington-DC-Temple.webp\",\"datePublished\":\"2022-08-29T21:13:41+00:00\",\"dateModified\":\"2026-07-02T14:41:56+00:00\",\"description\":\"The Washington DC Temple offers beautiful grounds and stunning architecture. There are activities year-round at the Visitors' Center.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Washington-DC-Temple.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Washington-DC-Temple.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Temple de Washington DC - Accueil","description":"Le temple de Washington DC offre un magnifique parc et une architecture \u00e9poustouflante. Des activit\u00e9s sont propos\u00e9es toute l&#039;ann\u00e9e au centre d&#039;accueil des visiteurs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Washington DC Temple - Home","og_description":"The Washington DC Temple offers beautiful grounds and stunning architecture. There are activities year-round at the Visitors' Center.","og_url":"https:\/\/dctemple.org\/fr\/","og_site_name":"DCTemple.org","article_modified_time":"2026-07-02T14:41:56+00:00","og_image":[{"url":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/","url":"https:\/\/dctemple.org\/","name":"Washington DC Temple - Home","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dctemple.org\/#primaryimage"},"image":{"@id":"https:\/\/dctemple.org\/#primaryimage"},"thumbnailUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple.webp","datePublished":"2022-08-29T21:13:41+00:00","dateModified":"2026-07-02T14:41:56+00:00","description":"The Washington DC Temple offers beautiful grounds and stunning architecture. There are activities year-round at the Visitors' Center.","breadcrumb":{"@id":"https:\/\/dctemple.org\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dctemple.org\/#primaryimage","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/6337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/comments?post=6337"}],"version-history":[{"count":6,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/6337\/revisions"}],"predecessor-version":[{"id":9618,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/6337\/revisions\/9618"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/media?parent=6337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":6245,"date":"2022-07-28T16:57:34","date_gmt":"2022-07-28T20:57:34","guid":{"rendered":"http:\/\/dctemple.org\/?page_id=6245"},"modified":"2026-02-11T17:58:12","modified_gmt":"2026-02-11T22:58:12","slug":"sunday-service","status":"publish","type":"page","link":"https:\/\/dctemple.org\/fr\/sunday-service\/","title":{"rendered":"Service du dimanche"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6245\" class=\"elementor elementor-6245\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12ccc71 e-flex e-con-boxed e-con e-parent\" data-id=\"12ccc71\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6fadbad e-con-full e-flex e-con e-child\" data-id=\"6fadbad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ac653c elementor-widget elementor-widget-video\" data-id=\"4ac653c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/nUfhknjT7do&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca775ba e-flex e-con-boxed e-con e-parent\" data-id=\"ca775ba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9df7193 e-con-full e-flex e-con e-child\" data-id=\"9df7193\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c0b2356 elementor-widget elementor-widget-heading\" data-id=\"c0b2356\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Venez nous rejoindre<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-351e7be e-flex e-con-boxed e-con e-parent\" data-id=\"351e7be\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4632285 e-con-full e-flex e-con e-child\" data-id=\"4632285\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fe2a5a4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fe2a5a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-94c362d e-flex e-con-boxed e-con e-parent\" data-id=\"94c362d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d46946b e-con-full e-flex e-con e-child\" data-id=\"d46946b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-981d260 elementor-widget elementor-widget-text-editor\" data-id=\"981d260\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Bien que les membres de l&#039;\u00c9glise de J\u00e9sus-Christ des Saints des Derniers Jours n&#039;assistent pas aux cultes du dimanche dans le temple, vous \u00eates invit\u00e9s \u00e0 vous rassembler avec nous pour chanter des hymnes, entendre des sermons et en apprendre davantage sur notre Sauveur J\u00e9sus-Christ dans les \u00e9glises locales.<\/p><p>L&#039;\u00e9glise est un refuge contre le chaos de la vie quotidienne. Assister aux services religieux nous donne le temps de nous concentrer sur l&#039;adoration de Dieu et l&#039;amour de nos voisins. C&#039;est une recharge spirituelle et un moyen parfait pour nous aider \u00e0 garder J\u00e9sus au centre de nos vies.<\/p><p>Les heures et les horaires des services religieux varient d&#039;une congr\u00e9gation \u00e0 l&#039;autre. Cependant, vous pouvez toujours compter sur un format similaire - une r\u00e9union principale pour tout le monde et une autre classe s\u00e9par\u00e9e par groupes d&#039;\u00e2ge ou int\u00e9r\u00eats g\u00e9n\u00e9raux.<\/p><p>Pour trouver une maison de r\u00e9union pr\u00e8s de chez vous, veuillez s\u00e9lectionner le bouton ci-dessous.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-749ed21 e-flex e-con-boxed e-con e-parent\" data-id=\"749ed21\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-344f38d e-con-full e-flex e-con e-child\" data-id=\"344f38d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff4a0f0 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ff4a0f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.churchofjesuschrist.org\/welcome\/find-a-church?lang=eng&#038;location=Washington+DC\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Trouver une \u00e9glise<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-625e707 e-flex e-con-boxed e-con e-parent\" data-id=\"625e707\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-601d353 e-con-full e-flex e-con e-child\" data-id=\"601d353\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27f847c elementor-widget elementor-widget-heading\" data-id=\"27f847c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><h2 data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\" style=\"letter-spacing: normal\"><div style=\"text-align: center\"><span style=\"background-color: var(--nv-site-bg)\">\u00c0 quoi s&#039;attendre<\/span><span style=\"letter-spacing: var(--h2letterspacing);background-color: var(--nv-site-bg);color: var( --e-global-color-text )\"><\/span><\/div><\/h2><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb4d1c7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bb4d1c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d083fc9 elementor-widget elementor-widget-image\" data-id=\"d083fc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/elementor\/thumbs\/Sunday-Worship-Service-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk-rcn8hjmg7si4q97pz69et3nm04yhyx5bstf4e87wis.webp\" title=\"Service-de-culte-du-dimanche-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk\" alt=\"Service-de-culte-du-dimanche-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-611dd3a elementor-widget elementor-widget-heading\" data-id=\"611dd3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R\u00e9union de Sainte-C\u00e8ne<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f57c4ab elementor-widget elementor-widget-text-editor\" data-id=\"f57c4ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>La r\u00e9union principale pour tout le monde s&#039;appelle la r\u00e9union de Sainte-C\u00e8ne. Cette r\u00e9union consiste en des chants, des pri\u00e8res et des sermons (ou \u00abdiscours\u00bb) donn\u00e9s par diff\u00e9rents membres de la congr\u00e9gation chaque semaine. Mais la partie la plus importante de la r\u00e9union est lorsque nous prenons le sacrement (ou la communion).\u00a0<a style=\"background-color: var(--nv-site-bg); letter-spacing: var(--bodyletterspacing); text-transform: var(--bodytexttransform);\" href=\"https:\/\/www.churchofjesuschrist.org\/comeuntochrist\/belong\/sunday-services\/sacrament\" target=\"_blank\" rel=\"noopener\">En savoir plus sur la Sainte-C\u00e8ne.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b11b453 elementor-widget elementor-widget-heading\" data-id=\"b11b453\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Musique et hymnes<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e087fc3 elementor-widget elementor-widget-text-editor\" data-id=\"e087fc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Chanter le Sauveur et nos nombreuses b\u00e9n\u00e9dictions nous aide \u00e0 nous sentir plus proches de Dieu. Une r\u00e9union de Sainte-C\u00e8ne typique aura trois ou quatre cantiques chant\u00e9s par toute la congr\u00e9gation. Il peut \u00e9galement y avoir des num\u00e9ros musicaux suppl\u00e9mentaires par un ch\u0153ur, un petit groupe ou un soliste. Vous reconna\u00eetrez peut-\u00eatre certains hymnes comme \u00ab\u00a0Plus pr\u00e8s de toi, mon Dieu\u00a0\u00bb et \u00ab\u00a0Comme tu es grand\u00a0\u00bb, mais vous en apprendrez aussi de nouveaux. Et ce n&#039;est pas grave si vous chantez faux\u00a0! \u00c9levez quand m\u00eame votre voix pendant que vous adorez avec nous.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-754fcb7 elementor-widget elementor-widget-heading\" data-id=\"754fcb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">T\u00e9moigner les uns des autres<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f9de7f elementor-widget elementor-widget-text-editor\" data-id=\"8f9de7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Le premier dimanche de chaque mois, il n&#039;y a pas de sermons typiques. Au lieu de cela, n&#039;importe quel membre de la congr\u00e9gation peut monter \u00e0 la chaire et exprimer ses sentiments au sujet de l&#039;\u00c9vangile. En \u00e9coutant les exp\u00e9riences des autres et en sentant l&#039;Esprit de Dieu remplir nos c\u0153urs, nos propres convictions et croyances peuvent \u00eatre renforc\u00e9es.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b9578b elementor-widget elementor-widget-heading\" data-id=\"7b9578b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Exemple de programme<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f8af1a elementor-widget elementor-widget-image\" data-id=\"1f8af1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"768\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/ward_program_sacrament_meeting.webp\" class=\"attachment-large size-large wp-image-6248\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/ward_program_sacrament_meeting.webp 640w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/ward_program_sacrament_meeting-250x300.webp 250w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/ward_program_sacrament_meeting-10x12.webp 10w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27da50f elementor-widget elementor-widget-heading\" data-id=\"27da50f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Cours du dimanche<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2a0bd4 elementor-widget elementor-widget-text-editor\" data-id=\"d2a0bd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Avant ou apr\u00e8s la r\u00e9union de Sainte-C\u00e8ne, il existe une vari\u00e9t\u00e9 d&#039;autres cours sp\u00e9cifiques \u00e0 l&#039;\u00e2ge pour les enfants et les adultes. Si vous souhaitez assister \u00e0 ces r\u00e9unions suppl\u00e9mentaires, demandez \u00e0 quelqu&#039;un \u00e0 l&#039;\u00e9glise, et il se fera un plaisir de vous aider \u00e0 trouver la bonne salle de classe.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4fafd2b e-flex e-con-boxed e-con e-parent\" data-id=\"4fafd2b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b255952 e-con-full e-flex e-con e-child\" data-id=\"b255952\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1449eee elementor-widget elementor-widget-spacer\" data-id=\"1449eee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9eb2545 e-flex e-con-boxed e-con e-parent\" data-id=\"9eb2545\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-47ef4ba e-con-full e-flex e-con e-child\" data-id=\"47ef4ba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc4cc00 elementor-widget elementor-widget-heading\" data-id=\"dc4cc00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Questions fr\u00e9quemment pos\u00e9es<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0b250a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a0b250a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b0af49 elementor-widget elementor-widget-video\" data-id=\"7b0af49\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/BnJ6QkCACkk&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d29bb00 elementor-widget elementor-widget-heading\" data-id=\"d29bb00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Que dois-je porter?<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-150f3e7 elementor-widget elementor-widget-text-editor\" data-id=\"150f3e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Vous pouvez porter des v\u00eatements modestes dans lesquels vous vous sentez \u00e0 l&#039;aise. Mais pour votre information, la plupart des hommes portent des costumes, des vestes de sport, des chemises et des cravates, et les femmes portent des robes ou des jupes. Les enfants se d\u00e9guisent aussi g\u00e9n\u00e9ralement.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d536ff elementor-widget elementor-widget-heading\" data-id=\"3d536ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Est-ce que je me sentirai mal \u00e0 l&#039;aise d&#039;y assister seul\u00a0?<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d7fdb4 elementor-widget elementor-widget-text-editor\" data-id=\"7d7fdb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous esp\u00e9rons que non. Beaucoup de nos membres viennent seuls \u00e0 l\u2019\u00e9glise chaque semaine. Cependant, si vous souhaitez que quelqu&#039;un vous accompagne pour la premi\u00e8re fois, n&#039;h\u00e9sitez pas \u00e0 contacter les missionnaires ou l&#039;\u00e9v\u00eaque de la paroisse \u00e0 votre arriv\u00e9e et ils vous trouveront un ami avec qui s&#039;asseoir. Il est toujours difficile d&#039;\u00eatre nouveau, quelle que soit la situation, mais avec le temps, vous apprendrez \u00e0 conna\u00eetre les autres membres et vous vous sentirez plus \u00e0 l&#039;aise.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68a521b elementor-widget elementor-widget-image\" data-id=\"68a521b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/elementor\/thumbs\/Women-Talking-Gneral-Conference-e1589998858605-qbatyw956daj7yxnnqys1pjhh3tg2kq4dl6fscyp9g-rcn8g05z0ke7p9g9z0af7zneyejucs15x6xh2wi4pw.webp\" title=\"Conf\u00e9rence-g\u00e9n\u00e9rale-de-femmes-parlant-e1589998858605-qbatyw956daj7yxnnqys1pjhh3tg2kq4dl6fscyp9g\" alt=\"Conf\u00e9rence-g\u00e9n\u00e9rale-de-femmes-parlant-e1589998858605-qbatyw956daj7yxnnqys1pjhh3tg2kq4dl6fscyp9g\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3355ca elementor-widget elementor-widget-heading\" data-id=\"c3355ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Est-ce que tout le monde saura que je suis un visiteur\u00a0?<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbb11d0 elementor-widget elementor-widget-text-editor\" data-id=\"dbb11d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Cela d\u00e9pend probablement de la taille de la branche ou de la congr\u00e9gation que vous visitez. Certaines congr\u00e9gations sont si grandes (jusqu&#039;\u00e0 600 membres) que ses membres r\u00e9guliers peuvent ou non se rendre compte que vous \u00eates un visiteur. D&#039;autres sont si petits que les membres se connaissent tous et reconna\u00eetront et accueilleront certainement un nouveau venu.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c0d2fe elementor-widget elementor-widget-heading\" data-id=\"0c0d2fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Dois-je donner de l&#039;argent?<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f0c7c0 elementor-widget elementor-widget-text-editor\" data-id=\"2f0c7c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Non. Nous ne sollicitons pas de dons et ne passons pas d&#039;assiette.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86059eb elementor-widget elementor-widget-heading\" data-id=\"86059eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Dois-je participer ?<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-583cb3f elementor-widget elementor-widget-text-editor\" data-id=\"583cb3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Non. Les visiteurs ne sont en aucun cas tenus de participer. Vous pouvez simplement vous asseoir et profiter du service.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45f608f elementor-widget elementor-widget-heading\" data-id=\"45f608f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Combien de temps dure l&#039;\u00e9glise ?<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e53c28 elementor-widget elementor-widget-text-editor\" data-id=\"2e53c28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Notre principal service de culte familial s&#039;appelle la r\u00e9union de Sainte-C\u00e8ne. Elle a lieu dans nos chapelles le dimanche et dure environ une heure. Vous pouvez venir seul ou amener votre famille; les enfants sont pr\u00e9sents dans pratiquement toutes nos congr\u00e9gations.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21d4769 elementor-widget elementor-widget-image\" data-id=\"21d4769\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/elementor\/thumbs\/Last-Supper-Banner-qbapyouiodvw1megpwya0lkom0l8698lju3q94s1us-rcnayzxim6yhmba1mu993j0t6820hy9q3kgmk7l4dg.webp\" title=\"Banni\u00e8re-de-la-C\u00e8ne-qbapyouiodvw1megpwya0lkom0l8698lju3q94s1us\" alt=\"Banni\u00e8re-de-la-C\u00e8ne-qbapyouiodvw1megpwya0lkom0l8698lju3q94s1us\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-558e8ec elementor-widget elementor-widget-heading\" data-id=\"558e8ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Que se passe-t-il pendant la r\u00e9union de Sainte-C\u00e8ne ?<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8e2bcf elementor-widget elementor-widget-text-editor\" data-id=\"b8e2bcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous chantons des hymnes (des recueils de cantiques sont fournis). Les membres de l&#039;\u00e9glise r\u00e9citent des pri\u00e8res d&#039;ouverture et de cl\u00f4ture. Nous prenons la Sainte-C\u00e8ne (communion), qui consiste en du pain et de l&#039;eau pr\u00e9par\u00e9s, b\u00e9nis et transmis aux membres de la congr\u00e9gation par les d\u00e9tenteurs de la pr\u00eatrise. Et nous \u00e9coutons deux orateurs ou plus qui sont g\u00e9n\u00e9ralement des membres de la congr\u00e9gation.<\/p><p>Vous pourriez \u00eatre surpris que nous n&#039;ayons pas qu&#039;un seul pasteur ou pr\u00e9dicateur. Nous avons un \u00e9v\u00eaque non r\u00e9mun\u00e9r\u00e9 qui pr\u00e9side chaque congr\u00e9gation (appel\u00e9e une paroisse).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-deb48ce elementor-widget elementor-widget-heading\" data-id=\"deb48ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Y a-t-il d&#039;autres r\u00e9unions dimanche ?<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e6e164 elementor-widget elementor-widget-text-editor\" data-id=\"7e6e164\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Avant ou apr\u00e8s la r\u00e9union de Sainte-C\u00e8ne, il y a une vari\u00e9t\u00e9 d&#039;autres r\u00e9unions adapt\u00e9es \u00e0 l&#039;\u00e2ge auxquelles vous et vos enfants pouvez assister. Si vous souhaitez assister \u00e0 ces r\u00e9unions suppl\u00e9mentaires, demandez \u00e0 quelqu&#039;un de vous guider. S&#039;ils ne le savent pas, ils trouveront quelqu&#039;un qui le sait.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-870be27 e-flex e-con-boxed e-con e-parent\" data-id=\"870be27\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3e1b502 e-con-full e-flex e-con e-child\" data-id=\"3e1b502\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-368acfe elementor-widget elementor-widget-spacer\" data-id=\"368acfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c8a7cf4 e-flex e-con-boxed e-con e-parent\" data-id=\"c8a7cf4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e478252 e-con-full e-flex e-con e-child\" data-id=\"e478252\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e12ccd2 elementor-widget elementor-widget-html\" data-id=\"e12ccd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<div style=\"overflow-x:hidden;text-align: center; background: #ffffff; box-shadow: 0 4px 8px 0 rgba(0, 0, 0, 0.2), 0 6px 20px 0 rgba(0, 0, 0, 0.19); padding: 10px;  min-width: 330px; width:60%; margin: auto;\">\r\n<div style=\"overflow-x:hidden;text-align: center; font-size: 20px; line-height: 36px; width: 80%; margin: auto; padding-bottom: 19px; min-width: 315px; margin-bottom: 20px;\">\r\n\r\n<h3 style=\"overflow-x:hidden;font-weight:300px;font-size:24px;line-height:36px;letter-spacing:.16px;color:#3B3A3A;margin-top:20px;margin-bottom:10px;\">Venez adorer avec nous !<\/h3>\r\n<p style=\"font-size:22px;color:#3B3A3A;padding-top:0px;margin-top:0px;\">Pour plus d&#039;informations, veuillez appeler le centre des visiteurs du temple\u00a0:<\/p>\r\n<p style=\"font-size:22px;\"><i class=\"fa fa-phone\" style=\"color:#3B3A3A\"><\/i> <a href=\"tel:1-301-587-0144\">+1 (301) 587-0144<\/a><\/p>\r\n\r\n<em style=\"font-size:22px;color:#3B3A3A;\">Visiteurs invit\u00e9s. Parking gratuit.<\/em>\r\n\r\n<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1518da7 e-flex e-con-boxed e-con e-parent\" data-id=\"1518da7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7bdf3ea e-con-full e-flex e-con e-child\" data-id=\"7bdf3ea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e973be elementor-widget elementor-widget-spacer\" data-id=\"2e973be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>https:\/\/youtu.be\/nUfhknjT7do Come Join Us While members of The Church of Jesus Christ of Latter-day Saints do not attend Sunday worship services in the temple, you are invited to gather with us to sing hymns, hear sermons, and learn more about our Savior Jesus Christ at local meetinghouses. Church is a refuge from the chaos of [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6245","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sunday Service - DCTemple.org<\/title>\n<meta name=\"description\" content=\"Learn more about what Sunday Services of The Church of Jesus Christ of Latter-day Saints are like and find a meetinghouse near you today.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/fr\/sunday-service\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sunday Service - DCTemple.org\" \/>\n<meta property=\"og:description\" content=\"Learn more about what Sunday Services of The Church of Jesus Christ of Latter-day Saints are like and find a meetinghouse near you today.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/fr\/sunday-service\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T22:58:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dctemple.org\/wp-content\/uploads\/elementor\/thumbs\/Sunday-Worship-Service-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk-rcn8hjmg7si4q97pz69et3nm04yhyx5bstf3udrmkg.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/sunday-service\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/sunday-service\\\/\",\"name\":\"Sunday Service - DCTemple.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/sunday-service\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/sunday-service\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/Sunday-Worship-Service-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk-rcn8hjmg7si4q97pz69et3nm04yhyx5bstf3udrmkg.webp\",\"datePublished\":\"2022-07-28T20:57:34+00:00\",\"dateModified\":\"2026-02-11T22:58:12+00:00\",\"description\":\"Learn more about what Sunday Services of The Church of Jesus Christ of Latter-day Saints are like and find a meetinghouse near you today.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/sunday-service\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/sunday-service\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/sunday-service\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/Sunday-Worship-Service-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk-rcn8hjmg7si4q97pz69et3nm04yhyx5bstf3udrmkg.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/Sunday-Worship-Service-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk-rcn8hjmg7si4q97pz69et3nm04yhyx5bstf3udrmkg.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/sunday-service\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sunday Service\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Service dominical - DCTemple.org","description":"Apprenez-en davantage sur les services du dimanche de l\u2019\u00c9glise de J\u00e9sus-Christ des Saints des Derniers Jours et trouvez un lieu de r\u00e9union pr\u00e8s de chez vous d\u00e8s aujourd\u2019hui.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/fr\/sunday-service\/","og_locale":"fr_FR","og_type":"article","og_title":"Sunday Service - DCTemple.org","og_description":"Learn more about what Sunday Services of The Church of Jesus Christ of Latter-day Saints are like and find a meetinghouse near you today.","og_url":"https:\/\/dctemple.org\/fr\/sunday-service\/","og_site_name":"DCTemple.org","article_modified_time":"2026-02-11T22:58:12+00:00","og_image":[{"url":"https:\/\/dctemple.org\/wp-content\/uploads\/elementor\/thumbs\/Sunday-Worship-Service-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk-rcn8hjmg7si4q97pz69et3nm04yhyx5bstf3udrmkg.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/sunday-service\/","url":"https:\/\/dctemple.org\/sunday-service\/","name":"Sunday Service - DCTemple.org","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dctemple.org\/sunday-service\/#primaryimage"},"image":{"@id":"https:\/\/dctemple.org\/sunday-service\/#primaryimage"},"thumbnailUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/elementor\/thumbs\/Sunday-Worship-Service-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk-rcn8hjmg7si4q97pz69et3nm04yhyx5bstf3udrmkg.webp","datePublished":"2022-07-28T20:57:34+00:00","dateModified":"2026-02-11T22:58:12+00:00","description":"Learn more about what Sunday Services of The Church of Jesus Christ of Latter-day Saints are like and find a meetinghouse near you today.","breadcrumb":{"@id":"https:\/\/dctemple.org\/sunday-service\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/sunday-service\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dctemple.org\/sunday-service\/#primaryimage","url":"https:\/\/dctemple.org\/wp-content\/uploads\/elementor\/thumbs\/Sunday-Worship-Service-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk-rcn8hjmg7si4q97pz69et3nm04yhyx5bstf3udrmkg.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/elementor\/thumbs\/Sunday-Worship-Service-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk-rcn8hjmg7si4q97pz69et3nm04yhyx5bstf3udrmkg.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/sunday-service\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"Sunday Service"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/6245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/comments?post=6245"}],"version-history":[{"count":0,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/6245\/revisions"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/media?parent=6245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":6145,"date":"2022-07-21T12:22:52","date_gmt":"2022-07-21T16:22:52","guid":{"rendered":"http:\/\/dctemple.org\/?page_id=6145"},"modified":"2026-02-11T17:59:56","modified_gmt":"2026-02-11T22:59:56","slug":"gallery-open-house","status":"publish","type":"page","link":"https:\/\/dctemple.org\/fr\/galleries\/gallery-open-house\/","title":{"rendered":"Galerie \u2013 Portes Ouvertes"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6145\" class=\"elementor elementor-6145\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c64031d e-con-full e-flex e-con e-parent\" data-id=\"c64031d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0ee0266 e-con-full e-flex e-con e-child\" data-id=\"0ee0266\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-92d2df3 elementor-widget elementor-widget-heading\" data-id=\"92d2df3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/fr\/galleries\/\">&lt; Retour \u00e0 toutes les galeries<\/a><\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b316d0 e-con-full e-flex e-con e-child\" data-id=\"6b316d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-371dc71 elementor-widget elementor-widget-heading\" data-id=\"371dc71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/dctemple.org\/fr\/galleries\/temple-exterior-gallery\/\">Next Gallery &gt;<\/a><\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d4de52 e-con-full e-flex e-con e-parent\" data-id=\"3d4de52\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3d092f2 e-con-full e-flex e-con e-child\" data-id=\"3d092f2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5aba074 elementor-widget elementor-widget-heading\" data-id=\"5aba074\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Galerie portes ouvertes du temple<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2536da elementor-widget elementor-widget-heading\" data-id=\"b2536da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Profitez de la photographie de la journ\u00e9e portes ouvertes du temple de Washington DC. Cliquez sur une image pour l&#039;agrandir.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecbfb32 elementor-widget elementor-widget-gallery\" data-id=\"ecbfb32\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;masonry&quot;,&quot;columns&quot;:3,&quot;lazyload&quot;:&quot;yes&quot;,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/005-OH119-IMG_1554-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE0OCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzAwNS1PSDExOS1JTUdfMTU1NC1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/005-OH119-IMG_1554-1024x804.webp\" data-width=\"800\" data-height=\"628\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/010-IMG_0343-Temple-sign-by-PageJohnson-Copy-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE0OSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzAxMC1JTUdfMDM0My1UZW1wbGUtc2lnbi1ieS1QYWdlSm9obnNvbi1Db3B5LXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/010-IMG_0343-Temple-sign-by-PageJohnson-Copy-1024x768.webp\" data-width=\"800\" data-height=\"600\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/020-IG76-20220427-BJohnson-IMG_2321-Temple-Tulips-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1MCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzAyMC1JRzc2LTIwMjIwNDI3LUJKb2huc29uLUlNR18yMzIxLVRlbXBsZS1UdWxpcHMtc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/020-IG76-20220427-BJohnson-IMG_2321-Temple-Tulips-1024x767.webp\" data-width=\"800\" data-height=\"599\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/030-IG43-20220422-RBrown-00045-Temple-Reflecting-Pool-no-people-Richard-Brown-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1MSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzAzMC1JRzQzLTIwMjIwNDIyLVJCcm93bi0wMDA0NS1UZW1wbGUtUmVmbGVjdGluZy1Qb29sLW5vLXBlb3BsZS1SaWNoYXJkLUJyb3duLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/030-IG43-20220422-RBrown-00045-Temple-Reflecting-Pool-no-people-Richard-Brown-683x1024.webp\" data-width=\"683\" data-height=\"1024\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/031-OH136-20220611-BJohnson-IMG_1156-Roof-View-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1MiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzAzMS1PSDEzNi0yMDIyMDYxMS1CSm9obnNvbi1JTUdfMTE1Ni1Sb29mLVZpZXctc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/031-OH136-20220611-BJohnson-IMG_1156-Roof-View-1024x602.webp\" data-width=\"800\" data-height=\"470\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/040-551EEDB5-6CA9-461E-B355-2DEFD849AE89-Dayana-Perez-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1MywidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzA0MC01NTFFRURCNS02Q0E5LTQ2MUUtQjM1NS0yREVGRDg0OUFFODktRGF5YW5hLVBlcmV6LXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/040-551EEDB5-6CA9-461E-B355-2DEFD849AE89-Dayana-Perez-1024x681.webp\" data-width=\"800\" data-height=\"532\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/060-20220422-BJohnson-IMG_2116-Annex-Stained-Glass-Close-up-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1NCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzA2MC0yMDIyMDQyMi1CSm9obnNvbi1JTUdfMjExNi1Bbm5leC1TdGFpbmVkLUdsYXNzLUNsb3NlLXVwLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/060-20220422-BJohnson-IMG_2116-Annex-Stained-Glass-Close-up-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/070-IG07-20220418-BJohnson-IMG_1616-Sharon-Eubank-and-Audience-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1NSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzA3MC1JRzA3LTIwMjIwNDE4LUJKb2huc29uLUlNR18xNjE2LVNoYXJvbi1FdWJhbmstYW5kLUF1ZGllbmNlLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/070-IG07-20220418-BJohnson-IMG_1616-Sharon-Eubank-and-Audience-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/080-IG09-HSzamosfalvi-IMG-12-hollie-szamosfalvi-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1NiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzA4MC1JRzA5LUhTemFtb3NmYWx2aS1JTUctMTItaG9sbGllLXN6YW1vc2ZhbHZpLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/080-IG09-HSzamosfalvi-IMG-12-hollie-szamosfalvi-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/090-IG12-HSzamosfalvi-IMG-81-hollie-szamosfalvi-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1NywidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzA5MC1JRzEyLUhTemFtb3NmYWx2aS1JTUctODEtaG9sbGllLXN6YW1vc2ZhbHZpLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/090-IG12-HSzamosfalvi-IMG-81-hollie-szamosfalvi-683x1024.webp\" data-width=\"683\" data-height=\"1024\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/100-IG11-HSzamosfalvi-IMG-73-hollie-szamosfalvi-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1OCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzEwMC1JRzExLUhTemFtb3NmYWx2aS1JTUctNzMtaG9sbGllLXN6YW1vc2ZhbHZpLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/100-IG11-HSzamosfalvi-IMG-73-hollie-szamosfalvi-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/110-IG72-_RBrown_00028_Alan-Ronkin-American-Jewish-Council-Breakfast-2-Richard-Brown-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1OSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzExMC1JRzcyLV9SQnJvd25fMDAwMjhfQWxhbi1Sb25raW4tQW1lcmljYW4tSmV3aXNoLUNvdW5jaWwtQnJlYWtmYXN0LTItUmljaGFyZC1Ccm93bi1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/110-IG72-_RBrown_00028_Alan-Ronkin-American-Jewish-Council-Breakfast-2-Richard-Brown-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/120-IG48-CJohnson-CJ8B0752-Cheryl-Johnson-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2MCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzEyMC1JRzQ4LUNKb2huc29uLUNKOEIwNzUyLUNoZXJ5bC1Kb2huc29uLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/120-IG48-CJohnson-CJ8B0752-Cheryl-Johnson-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/130-HSzamosfalvi-IMG-117-hollie-szamosfalvi-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2MSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzEzMC1IU3phbW9zZmFsdmktSU1HLTExNy1ob2xsaWUtc3phbW9zZmFsdmktc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/130-HSzamosfalvi-IMG-117-hollie-szamosfalvi-683x1024.webp\" data-width=\"683\" data-height=\"1024\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/140-IG37-20220425-CJohnson-CJ8B0146-Cheryl-Johnson-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2MiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzE0MC1JRzM3LTIwMjIwNDI1LUNKb2huc29uLUNKOEIwMTQ2LUNoZXJ5bC1Kb2huc29uLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/140-IG37-20220425-CJohnson-CJ8B0146-Cheryl-Johnson-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/145-IG70-20220426_RBrown_00012_MD-Congressman-John-Sarbanes-1-Richard-Brown-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2MywidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzE0NS1JRzcwLTIwMjIwNDI2X1JCcm93bl8wMDAxMl9NRC1Db25ncmVzc21hbi1Kb2huLVNhcmJhbmVzLTEtUmljaGFyZC1Ccm93bi1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/145-IG70-20220426_RBrown_00012_MD-Congressman-John-Sarbanes-1-Richard-Brown-819x1024.webp\" data-width=\"800\" data-height=\"1000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/150-20220422-volunteer-by-PageJohnson-IMG_0550-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2NCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzE1MC0yMDIyMDQyMi12b2x1bnRlZXItYnktUGFnZUpvaG5zb24tSU1HXzA1NTAtc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/150-20220422-volunteer-by-PageJohnson-IMG_0550-1024x768.webp\" data-width=\"800\" data-height=\"600\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/160-IG16-IMG_0545-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2NSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzE2MC1JRzE2LUlNR18wNTQ1LXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/160-IG16-IMG_0545-1024x799.webp\" data-width=\"800\" data-height=\"624\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/170-IG56-20220425-BJohnson-IMG_2145-Mauri-Introduction-in-Tent-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2NiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzE3MC1JRzU2LTIwMjIwNDI1LUJKb2huc29uLUlNR18yMTQ1LU1hdXJpLUludHJvZHVjdGlvbi1pbi1UZW50LXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/170-IG56-20220425-BJohnson-IMG_2145-Mauri-Introduction-in-Tent-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/180-OH077-IMG_1346-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2NywidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzE4MC1PSDA3Ny1JTUdfMTM0Ni1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/180-OH077-IMG_1346-1024x745.webp\" data-width=\"800\" data-height=\"582\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/190-OH071-_MReeder_IMG-7_100s-line-up-to-see-temple-Mark-Reeder-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2OCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzE5MC1PSDA3MS1fTVJlZWRlcl9JTUctN18xMDBzLWxpbmUtdXAtdG8tc2VlLXRlbXBsZS1NYXJrLVJlZWRlci1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/190-OH071-_MReeder_IMG-7_100s-line-up-to-see-temple-Mark-Reeder-1024x768.webp\" data-width=\"800\" data-height=\"600\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/195-OH096-20220528-BJohnson-IMG_0787-This-Way-to-the-Temple-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2OSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzE5NS1PSDA5Ni0yMDIyMDUyOC1CSm9obnNvbi1JTUdfMDc4Ny1UaGlzLVdheS10by10aGUtVGVtcGxlLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/195-OH096-20220528-BJohnson-IMG_0787-This-Way-to-the-Temple-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/200-CJohnson-CJ8B0588-Cheryl-Johnson-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3MCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzIwMC1DSm9obnNvbi1DSjhCMDU4OC1DaGVyeWwtSm9obnNvbi1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/200-CJohnson-CJ8B0588-Cheryl-Johnson-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/205-OH010-20220429-BJohnson-IMG_0404-Entering-and-Leaving-Temple-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3MSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzIwNS1PSDAxMC0yMDIyMDQyOS1CSm9obnNvbi1JTUdfMDQwNC1FbnRlcmluZy1hbmQtTGVhdmluZy1UZW1wbGUtc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/205-OH010-20220429-BJohnson-IMG_0404-Entering-and-Leaving-Temple-1024x543.webp\" data-width=\"800\" data-height=\"424\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/210-JValentine-ADS_6300a-Neighbors-Jessica-Valentine-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3MiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzIxMC1KVmFsZW50aW5lLUFEU182MzAwYS1OZWlnaGJvcnMtSmVzc2ljYS1WYWxlbnRpbmUtc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/210-JValentine-ADS_6300a-Neighbors-Jessica-Valentine-1024x684.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/215-20220624-HSzamosfalvi-7-hollie-szamosfalvi-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3MywidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzIxNS0yMDIyMDYyNC1IU3phbW9zZmFsdmktNy1ob2xsaWUtc3phbW9zZmFsdmktc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/215-20220624-HSzamosfalvi-7-hollie-szamosfalvi-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/220-20220419-CJohnson-CJ8B9538-Cheryl-Johnson-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3NCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzIyMC0yMDIyMDQxOS1DSm9obnNvbi1DSjhCOTUzOC1DaGVyeWwtSm9obnNvbi1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/220-20220419-CJohnson-CJ8B9538-Cheryl-Johnson-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/230-OH046-20220507-Temple-foyer-by-PageJohnson-IMG_1292-2-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3NSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzIzMC1PSDA0Ni0yMDIyMDUwNy1UZW1wbGUtZm95ZXItYnktUGFnZUpvaG5zb24tSU1HXzEyOTItMi1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/230-OH046-20220507-Temple-foyer-by-PageJohnson-IMG_1292-2-1024x768.webp\" data-width=\"800\" data-height=\"600\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/240-CJohnson-CJ8B0779-Cheryl-Johnson-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3NiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzI0MC1DSm9obnNvbi1DSjhCMDc3OS1DaGVyeWwtSm9obnNvbi1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/240-CJohnson-CJ8B0779-Cheryl-Johnson-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/250-IG17-20220419-BJohnson-IMG_1750-Aburto-Group-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3NywidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzI1MC1JRzE3LTIwMjIwNDE5LUJKb2huc29uLUlNR18xNzUwLUFidXJ0by1Hcm91cC1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/250-IG17-20220419-BJohnson-IMG_1750-Aburto-Group-1024x685.webp\" data-width=\"800\" data-height=\"535\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/260-20220422-RBrown-00249-Elder-Sister-Bennett-UNICEF-group-Richard-Brown-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3OCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzI2MC0yMDIyMDQyMi1SQnJvd24tMDAyNDktRWxkZXItU2lzdGVyLUJlbm5ldHQtVU5JQ0VGLWdyb3VwLVJpY2hhcmQtQnJvd24tc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/260-20220422-RBrown-00249-Elder-Sister-Bennett-UNICEF-group-Richard-Brown-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/270-IG38-20220425-CJohnson-CJ8B0318-Cheryl-Johnson-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3OSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzI3MC1JRzM4LTIwMjIwNDI1LUNKb2huc29uLUNKOEIwMzE4LUNoZXJ5bC1Kb2huc29uLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/270-IG38-20220425-CJohnson-CJ8B0318-Cheryl-Johnson-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/280-IG61-_RBrown_0010_US-Senators-Church-Leaders-Richard-Brown-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4MCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzI4MC1JRzYxLV9SQnJvd25fMDAxMF9VUy1TZW5hdG9ycy1DaHVyY2gtTGVhZGVycy1SaWNoYXJkLUJyb3duLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/280-IG61-_RBrown_0010_US-Senators-Church-Leaders-Richard-Brown-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/290-IG25-20220419-HSzamosfalvi-IMG_-55-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4MSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzI5MC1JRzI1LTIwMjIwNDE5LUhTemFtb3NmYWx2aS1JTUdfLTU1LXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/290-IG25-20220419-HSzamosfalvi-IMG_-55-683x1024.webp\" data-width=\"683\" data-height=\"1024\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/300-IG59-20220425-BJohnson-IMG_2225-Ambassador-Group-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4MiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzMwMC1JRzU5LTIwMjIwNDI1LUJKb2huc29uLUlNR18yMjI1LUFtYmFzc2Fkb3ItR3JvdXAtc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/300-IG59-20220425-BJohnson-IMG_2225-Ambassador-Group-1024x749.webp\" data-width=\"800\" data-height=\"585\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/305-20220624-HSzamosfalvi-13-hollie-szamosfalvi-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4MywidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzMwNS0yMDIyMDYyNC1IU3phbW9zZmFsdmktMTMtaG9sbGllLXN6YW1vc2ZhbHZpLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/305-20220624-HSzamosfalvi-13-hollie-szamosfalvi-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/310-OH030-20220505-volunteer-directing-cars-by-PageJohnson-MG_1176-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4NCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzMxMC1PSDAzMC0yMDIyMDUwNS12b2x1bnRlZXItZGlyZWN0aW5nLWNhcnMtYnktUGFnZUpvaG5zb24tTUdfMTE3Ni1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/310-OH030-20220505-volunteer-directing-cars-by-PageJohnson-MG_1176-1024x768.webp\" data-width=\"800\" data-height=\"600\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/315-IMG_4797-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4NSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzMxNS1JTUdfNDc5Ny1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/315-IMG_4797-1024x750.webp\" data-width=\"800\" data-height=\"586\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/320-OH005-20220428-BJohnson-IMG_2390-Senior-Living-Bus-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4NiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzMyMC1PSDAwNS0yMDIyMDQyOC1CSm9obnNvbi1JTUdfMjM5MC1TZW5pb3ItTGl2aW5nLUJ1cy1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/320-OH005-20220428-BJohnson-IMG_2390-Senior-Living-Bus-1024x625.webp\" data-width=\"800\" data-height=\"488\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/330-OH063-20220518-BJohnson-IMG_0861-St-Albans-Bus-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4NywidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzMzMC1PSDA2My0yMDIyMDUxOC1CSm9obnNvbi1JTUdfMDg2MS1TdC1BbGJhbnMtQnVzLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/330-OH063-20220518-BJohnson-IMG_0861-St-Albans-Bus-1024x495.webp\" data-width=\"800\" data-height=\"387\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/345-IMG_1332-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4OCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzM0NS1JTUdfMTMzMi1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/345-IMG_1332-1024x681.webp\" data-width=\"800\" data-height=\"532\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/350-OH025-5P2A7038-hollie-szamosfalvi-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4OSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzM1MC1PSDAyNS01UDJBNzAzOC1ob2xsaWUtc3phbW9zZmFsdmktc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/350-OH025-5P2A7038-hollie-szamosfalvi-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/360-OH056-2022_05_11_RBrown_DC-Temple-Open-House_00020-Richard-Brown-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE5MCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzM2MC1PSDA1Ni0yMDIyXzA1XzExX1JCcm93bl9EQy1UZW1wbGUtT3Blbi1Ib3VzZV8wMDAyMC1SaWNoYXJkLUJyb3duLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/360-OH056-2022_05_11_RBrown_DC-Temple-Open-House_00020-Richard-Brown-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/370-OH066-2022_05_18_RBrown_Temple-Open-House_00006-Richard-Brown-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE5MSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzM3MC1PSDA2Ni0yMDIyXzA1XzE4X1JCcm93bl9UZW1wbGUtT3Blbi1Ib3VzZV8wMDAwNi1SaWNoYXJkLUJyb3duLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/370-OH066-2022_05_18_RBrown_Temple-Open-House_00006-Richard-Brown-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/380-OH051-2022_05_11_RBrown_DC-Temple-Open-House_00005-Richard-Brown-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE5MiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzM4MC1PSDA1MS0yMDIyXzA1XzExX1JCcm93bl9EQy1UZW1wbGUtT3Blbi1Ib3VzZV8wMDAwNS1SaWNoYXJkLUJyb3duLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/380-OH051-2022_05_11_RBrown_DC-Temple-Open-House_00005-Richard-Brown-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/390-OH064-2022_05_18_RBrown_Temple-Open-House_00002-Richard-Brown-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE5MywidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzM5MC1PSDA2NC0yMDIyXzA1XzE4X1JCcm93bl9UZW1wbGUtT3Blbi1Ib3VzZV8wMDAwMi1SaWNoYXJkLUJyb3duLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/390-OH064-2022_05_18_RBrown_Temple-Open-House_00002-Richard-Brown-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/400-OH086-20220626-HSzamosfalvi-22-hollie-szamosfalvi-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE5NCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzQwMC1PSDA4Ni0yMDIyMDYyNi1IU3phbW9zZmFsdmktMjItaG9sbGllLXN6YW1vc2ZhbHZpLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/400-OH086-20220626-HSzamosfalvi-22-hollie-szamosfalvi-683x1024.webp\" data-width=\"683\" data-height=\"1024\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/410-20220626-HSzamosfalvi-hollie-szamosfalvi-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE5NSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzQxMC0yMDIyMDYyNi1IU3phbW9zZmFsdmktaG9sbGllLXN6YW1vc2ZhbHZpLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/410-20220626-HSzamosfalvi-hollie-szamosfalvi-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/510-OH137-20220611-BJohnson-IMG_1185-Roof-Sunset-Copy-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE5NiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzUxMC1PSDEzNy0yMDIyMDYxMS1CSm9obnNvbi1JTUdfMTE4NS1Sb29mLVN1bnNldC1Db3B5LXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/510-OH137-20220611-BJohnson-IMG_1185-Roof-Sunset-Copy-1024x676.webp\" data-width=\"800\" data-height=\"528\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>&lt; Back to All Galleries Next Gallery &gt; Temple Open House Gallery Enjoy photography of the Washington D.C. Temple Open House. Click on an image to expand.<\/p>","protected":false},"author":2,"featured_media":0,"parent":1209,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6145","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gallery \u2013 Open House - DCTemple.org<\/title>\n<meta name=\"description\" content=\"See a photography gallery from the 2022 Washington DC Temple Open House today and gain perspective from the House of the Lord.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/fr\/galleries\/gallery-open-house\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gallery \u2013 Open House - DCTemple.org\" \/>\n<meta property=\"og:description\" content=\"See a photography gallery from the 2022 Washington DC Temple Open House today and gain perspective from the House of the Lord.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/fr\/galleries\/gallery-open-house\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T22:59:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/galleries\\\/gallery-open-house\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/galleries\\\/gallery-open-house\\\/\",\"name\":\"Gallery \u2013 Open House - DCTemple.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"datePublished\":\"2022-07-21T16:22:52+00:00\",\"dateModified\":\"2026-02-11T22:59:56+00:00\",\"description\":\"See a photography gallery from the 2022 Washington DC Temple Open House today and gain perspective from the House of the Lord.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/galleries\\\/gallery-open-house\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/galleries\\\/gallery-open-house\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/galleries\\\/gallery-open-house\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galleries\",\"item\":\"https:\\\/\\\/dctemple.org\\\/galleries\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gallery \u2013 Open House\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gallery \u2013 Open House - DCTemple.org","description":"See a photography gallery from the 2022 Washington DC Temple Open House today and gain perspective from the House of the Lord.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/fr\/galleries\/gallery-open-house\/","og_locale":"fr_FR","og_type":"article","og_title":"Gallery \u2013 Open House - DCTemple.org","og_description":"See a photography gallery from the 2022 Washington DC Temple Open House today and gain perspective from the House of the Lord.","og_url":"https:\/\/dctemple.org\/fr\/galleries\/gallery-open-house\/","og_site_name":"DCTemple.org","article_modified_time":"2026-02-11T22:59:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/galleries\/gallery-open-house\/","url":"https:\/\/dctemple.org\/galleries\/gallery-open-house\/","name":"Gallery \u2013 Open House - DCTemple.org","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"datePublished":"2022-07-21T16:22:52+00:00","dateModified":"2026-02-11T22:59:56+00:00","description":"See a photography gallery from the 2022 Washington DC Temple Open House today and gain perspective from the House of the Lord.","breadcrumb":{"@id":"https:\/\/dctemple.org\/galleries\/gallery-open-house\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/galleries\/gallery-open-house\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/galleries\/gallery-open-house\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"Galleries","item":"https:\/\/dctemple.org\/galleries\/"},{"@type":"ListItem","position":3,"name":"Gallery \u2013 Open House"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/6145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/comments?post=6145"}],"version-history":[{"count":0,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/6145\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/1209"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/media?parent=6145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":6067,"date":"2022-06-27T13:33:07","date_gmt":"2022-06-27T17:33:07","guid":{"rendered":"http:\/\/dctemple.org\/?page_id=6067"},"modified":"2025-10-03T04:53:59","modified_gmt":"2025-10-03T08:53:59","slug":"washington-d-c-temple","status":"publish","type":"page","link":"https:\/\/dctemple.org\/fr\/washington-d-c-temple\/","title":{"rendered":"Washington DC Temple"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6067\" class=\"elementor elementor-6067\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18c075f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18c075f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a520bb0\" data-id=\"a520bb0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3897822 elementor-widget elementor-widget-heading\" data-id=\"3897822\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Washington DC Temple<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ade3876 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ade3876\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ce34aa elementor-widget elementor-widget-image\" data-id=\"3ce34aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"522\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2.webp\" class=\"attachment-full size-full wp-image-6069\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2.webp 1200w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2-300x131.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2-1024x445.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2-768x334.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2-18x8.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef670fb elementor-widget elementor-widget-text-editor\" data-id=\"ef670fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Le temple de Washington DC est consid\u00e9r\u00e9 comme une maison litt\u00e9rale du Seigneur par les membres de l&#039;\u00c9glise de J\u00e9sus-Christ des Saints des Derniers Jours. Le but principal du temple est de fournir des ordonnances et des b\u00e9n\u00e9dictions aux membres de la r\u00e9gion de Washington DC. Les ordonnances comprennent la dotation, le mariage et le bapt\u00eame.<\/p><p>Les visiteurs sont invit\u00e9s \u00e0 profiter des jardins, des fontaines apaisantes et de la vue sur l&#039;architecture \u00e9poustouflante. Pendant votre visite, arr\u00eatez-vous au Centre des visiteurs pour une visite personnalis\u00e9e.<\/p><p>De nombreux habitants l&#039;appellent le temple mormon, mais le vrai nom est le temple de Washington DC. Il appartient et est exploit\u00e9 par l&#039;\u00c9glise de J\u00e9sus-Christ des Saints des Derniers Jours.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f98d1f7 elementor-widget elementor-widget-image\" data-id=\"f98d1f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"522\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-3.webp\" class=\"attachment-full size-full wp-image-6070\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-3.webp 1200w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-3-300x131.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-3-1024x445.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-3-768x334.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-3-18x8.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bf90db elementor-widget elementor-widget-text-editor\" data-id=\"1bf90db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Le temple se trouve sur un site bien en vue \u00e0 Kensington et est devenu un point de rep\u00e8re local pour les automobilistes, qui en sont venus \u00e0 l&#039;appeler le temple du p\u00e9riph\u00e9rique.<\/p><p>Le temple n\u2019est pas le lieu o\u00f9 les membres se r\u00e9unissent pour les services de culte du dimanche. Les temples sont diff\u00e9rents des chapelles ordinaires que l&#039;\u00c9glise poss\u00e8de dans le monde. Les membres de l\u2019\u00c9glise prient dans les \u00e9glises du monde entier et les visiteurs sont toujours invit\u00e9s \u00e0 y participer. Plusieurs chapelles sont situ\u00e9es sur le terrain du Temple. <a href=\"https:\/\/clickly.org\/47wjv\" target=\"_blank\" rel=\"noopener\">Cliquez ici pour plus d&#039;informations sur les heures et les lieux des cultes.<\/a><\/p><p>Les temples sont un \u00ab lieu o\u00f9 les sacrements les plus \u00e9lev\u00e9s de la foi \u00bb peuvent avoir lieu. Au temple, vous en apprendrez plus sur le plan du salut et sur la fa\u00e7on de suivre l&#039;exemple parfait du Christ. Les plus grandes b\u00e9n\u00e9dictions de Dieu sont disponibles dans Ses temples. \u00c0 l&#039;int\u00e9rieur, les membres portent <a href=\"https:\/\/www.youtube.com\/watch?v=bMutZrefILc\" target=\"_blank\" rel=\"noopener\">v\u00eatements blancs qui symbolisent \u00e0 la fois la puret\u00e9 et l&#039;\u00e9galit\u00e9.<\/a><\/p><p>La pratique de la construction de temples remonte \u00e0 l&#039;Ancien et au Nouveau Testament dans la Bible. Le temple de Washington DC est l&#039;un des plus de 166 temples modernes construits par l&#039;\u00c9glise de J\u00e9sus-Christ des Saints des Derniers Jours.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48db0f6 elementor-widget elementor-widget-video\" data-id=\"48db0f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/HX9K42SnQQQ?feature=shared&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ddb6cd elementor-widget elementor-widget-text-editor\" data-id=\"2ddb6cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Seuls les membres de l&#039;\u00c9glise de J\u00e9sus-Christ des Saints des Derniers Jours poss\u00e9dant une recommandation \u00e0 l&#039;usage du temple active sont autoris\u00e9s \u00e0 entrer \u00e0 l&#039;int\u00e9rieur du temple de Washington DC.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b6cabf elementor-widget elementor-widget-image\" data-id=\"8b6cabf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"522\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1.webp\" class=\"attachment-full size-full wp-image-6058\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1.webp 1200w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1-300x131.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1-1024x445.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1-768x334.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1-18x8.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57a350d elementor-widget elementor-widget-text-editor\" data-id=\"57a350d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Toute personne, quelle que soit sa religion, est invit\u00e9e \u00e0 visiter les jardins du temple, \u00e0 assister aux services de culte dans la chapelle, \u00e0 visiter le centre des visiteurs et \u00e0 utiliser les autres installations.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-055e3af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"055e3af\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ba650a\" data-id=\"7ba650a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea3f80b elementor-widget elementor-widget-heading\" data-id=\"ea3f80b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Lieu de paix et d&#039;apprentissage<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d02098 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4d02098\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a89506 elementor-widget elementor-widget-text-editor\" data-id=\"6a89506\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Pour les membres de l&#039;\u00c9glise, le temple de Washington DC est cens\u00e9 \u00eatre un lieu d&#039;apprentissage et un lieu de paix. Il est cens\u00e9 \u00eatre un endroit o\u00f9 les membres peuvent recevoir des conseils spirituels pour les d\u00e9cisions dans leur vie. Les membres qui vont au temple ont la chance de s&#039;asseoir dans la salle c\u00e9leste - une belle salle destin\u00e9e aux membres pour m\u00e9diter et prier.<\/p><p>\u00a0<\/p><p>Les membres de l&#039;\u00c9glise de J\u00e9sus-Christ des Saints des Derniers Jours accomplissent plusieurs ordonnances dans le temple DC. Les ordonnances sont des actes sacr\u00e9s qui cr\u00e9ent une promesse contraignante entre Dieu et une personne qui souhaite retourner en la pr\u00e9sence de Dieu.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-758bca0 elementor-widget elementor-widget-heading\" data-id=\"758bca0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Donation<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e85fccf elementor-widget elementor-widget-image\" data-id=\"e85fccf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1775\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122348_LNilsson_Celestial_0729_Pano-scaled.webp\" class=\"attachment-full size-full wp-image-6072\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122348_LNilsson_Celestial_0729_Pano-scaled.webp 1920w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122348_LNilsson_Celestial_0729_Pano-300x277.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122348_LNilsson_Celestial_0729_Pano-1024x947.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122348_LNilsson_Celestial_0729_Pano-768x710.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122348_LNilsson_Celestial_0729_Pano-1536x1420.webp 1536w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122348_LNilsson_Celestial_0729_Pano-13x12.webp 13w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">La salle c\u00e9leste du temple de Washington DC<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efea154 elementor-widget elementor-widget-text-editor\" data-id=\"efea154\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>L&#039;ordonnance de dotation &quot;se compose d&#039;une s\u00e9rie d&#039;instructions et comprend des alliances pour vivre dans la justice et suivre les exigences de l&#039;\u00c9vangile&quot;. Le membre promet de suivre les normes de l&#039;\u00c9glise de J\u00e9sus-Christ des Saints des Derniers Jours.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cf16b0 elementor-widget elementor-widget-heading\" data-id=\"1cf16b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Mariage<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-913dad0 elementor-widget elementor-widget-image\" data-id=\"913dad0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122351_LNilsson_Brides_0678-scaled.webp\" class=\"attachment-full size-full wp-image-6073\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122351_LNilsson_Brides_0678-scaled.webp 1920w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122351_LNilsson_Brides_0678-300x200.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122351_LNilsson_Brides_0678-1024x683.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122351_LNilsson_Brides_0678-768x512.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122351_LNilsson_Brides_0678-1536x1024.webp 1536w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122351_LNilsson_Brides_0678-18x12.webp 18w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122351_LNilsson_Brides_0678-930x620.webp 930w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">La chambre de la mari\u00e9e dans le temple de Washington DC<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e506f1f elementor-widget elementor-widget-text-editor\" data-id=\"e506f1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Les mariages c\u00e9l\u00e9br\u00e9s dans le temple de Washington DC sont consid\u00e9r\u00e9s comme \u00e9ternels et se poursuivent au-del\u00e0 de la mort. Cependant, ce mariage pour toujours est conditionnel \u00e0 ce que le mari et la femme restent fid\u00e8les aux promesses qu&#039;ils font dans le temple et respectent les normes des enseignements du Christ.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e237e78 elementor-widget elementor-widget-heading\" data-id=\"e237e78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Bapt\u00eame<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6c0331 elementor-widget elementor-widget-image\" data-id=\"f6c0331\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122347_LNilsson_Baptistery_0657-scaled.webp\" class=\"attachment-full size-full wp-image-6071\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122347_LNilsson_Baptistery_0657-scaled.webp 1920w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122347_LNilsson_Baptistery_0657-300x200.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122347_LNilsson_Baptistery_0657-1024x683.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122347_LNilsson_Baptistery_0657-768x512.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122347_LNilsson_Baptistery_0657-1536x1024.webp 1536w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122347_LNilsson_Baptistery_0657-18x12.webp 18w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122347_LNilsson_Baptistery_0657-930x620.webp 930w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Le baptist\u00e8re du temple de Washington DC<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e10ab6 elementor-widget elementor-widget-text-editor\" data-id=\"0e10ab6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Les bapt\u00eames dans le temple de Washington DC sont effectu\u00e9s au nom des anc\u00eatres des membres d\u00e9c\u00e9d\u00e9s et qui n&#039;ont pas eu la chance d&#039;\u00eatre baptis\u00e9s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-95a1a9a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"95a1a9a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-00184f6\" data-id=\"00184f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8cbedba elementor-widget elementor-widget-heading\" data-id=\"8cbedba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Questions fr\u00e9quemment pos\u00e9es<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9346929 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9346929\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9228667 elementor-widget elementor-widget-accordion\" data-id=\"9228667\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1531\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1531\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Puis-je entrer dans le temple de Washington DC\u00a0?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1531\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1531\"><p><iframe title=\"lecteur vid\u00e9o YouTube\" src=\"https:\/\/www.youtube.com\/embed\/xSiwmYzSYTM\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/>Seuls les membres de l&#039;\u00c9glise de J\u00e9sus-Christ des Saints des Derniers Jours poss\u00e9dant une recommandation \u00e0 l&#039;usage du temple active sont actuellement autoris\u00e9s \u00e0 entrer \u00e0 l&#039;int\u00e9rieur du temple de Washington DC.<\/p><p>Tout le monde, quelle que soit sa religion, ses origines ou ses croyances, est plus que bienvenu pour profiter des fontaines et des jardins paisibles, faire une visite au centre des visiteurs, en apprendre davantage sur la vie du Christ \u00e0 travers l&#039;art et les peintures murales, assister aux d\u00e9votions et aux spectacles organis\u00e9s dans le centre des visiteurs et rejoignez-nous dimanche pour des services de culte \u00e9difiants.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1532\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1532\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Que sont les temples ? En quoi sont-ils diff\u00e9rents d&#039;une \u00e9glise?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1532\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1532\"><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/xkjUpbMebRU\" title=\"lecteur vid\u00e9o YouTube\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\nLes temples sont litt\u00e9ralement les maisons du Seigneur. Ce sont des endroits o\u00f9 les individus peuvent se rendre pour faire des promesses sacr\u00e9es avec Dieu, ressentir son esprit et \u00e9chapper aux exigences tr\u00e9pidantes de la vie quotidienne. Les temples existent depuis longtemps. Mo\u00efse avait un tabernacle, Salomon a construit un beau temple et J\u00e9sus a enseign\u00e9 au temple de J\u00e9rusalem. Aujourd&#039;hui, des temples sont construits partout dans le monde. \u00c0 l&#039;int\u00e9rieur des temples, les couples peuvent \u00eatre mari\u00e9s pour l&#039;\u00e9ternit\u00e9, pas seulement \u00ab\u00a0jusqu&#039;\u00e0 ce que la mort vous s\u00e9pare\u00a0\u00bb. Les membres de l&#039;\u00c9glise peuvent aussi accomplir des bapt\u00eames et d&#039;autres ordonnances pour leurs proches qui sont morts sans avoir re\u00e7u ces b\u00e9n\u00e9dictions. Les membres de l&#039;\u00c9glise adorent dans les \u00e9glises du monde entier et les visiteurs sont toujours les bienvenus. Ces b\u00e2timents peuvent inclure une chapelle de quartier ou m\u00eame un espace lou\u00e9 dans un b\u00e2timent de la ville. Dans tous les cas, ces lieux de r\u00e9union sont les lieux o\u00f9 les membres de l&#039;\u00c9glise se r\u00e9unissent r\u00e9guli\u00e8rement pour les cultes du dimanche et les activit\u00e9s hebdomadaires.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1533\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1533\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Puis-je visiter le temple si je ne suis pas membre ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1533\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1533\"><p>Oui. Bien que vous ne puissiez pas entrer dans le temple lui-m\u00eame, vous \u00eates plus que bienvenu pour profiter des fontaines et des jardins, faire une visite au centre des visiteurs, en apprendre davantage sur la vie du Christ \u00e0 travers l&#039;art et les peintures murales, assister aux d\u00e9votions et aux spectacles organis\u00e9s au le centre des visiteurs et rejoignez-nous dimanche pour des services de culte \u00e9difiants.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1534\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1534\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Comment est-ce \u00e0 l&#039;int\u00e9rieur du temple ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1534\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1534\"><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/mUYF1TX5RxM\" title=\"lecteur vid\u00e9o YouTube\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1535\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1535\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Que sont les bapt\u00eames pour les morts ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1535\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1535\"><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/RzCSrMJhWeQ\" title=\"lecteur vid\u00e9o YouTube\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1536\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1536\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Qu&#039;est-ce qu&#039;une dotation du temple ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1536\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1536\"><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/Fd8tVXN9y6Q\" title=\"lecteur vid\u00e9o YouTube\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1537\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1537\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00c0 quoi ressemble un mariage au temple\u00a0?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1537\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1537\"><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/gA6aTiMDYho\" title=\"lecteur vid\u00e9o YouTube\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1538\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1538\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Que sont les v\u00eatements du temple ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1538\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1538\"><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/5vvN4qJRBM0\" title=\"lecteur vid\u00e9o YouTube\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1539\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-1539\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Pourquoi certaines personnes l&#039;appellent-elles le temple mormon ou le temple LDS\u00a0?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1539\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-1539\"><p>Un surnom courant pour les membres de l\u2019\u00c9glise de J\u00e9sus-Christ des Saints des Derniers Jours est \u00ab mormon \u00bb. Un autre surnom courant est \u00ab\u00a0l&#039;\u00c9glise LDS\u00a0\u00bb. Ainsi, les gens appellent parfois le temple de Washington DC le \u00ab temple mormon \u00bb ou le \u00ab temple LDS \u00bb.<\/p><p>Le surnom de \u00ab mormon \u00bb vient d\u2019un livre d\u2019\u00c9critures que nous avons appel\u00e9 Le Livre de Mormon : Un autre t\u00e9moignage de J\u00e9sus-Christ. En savoir plus sur <a href=\"https:\/\/www.churchofjesuschrist.org\/comeuntochrist\/believe\/book-of-mormon\/what-is-the-book-of-mormon#:~:text=The%20Book%20of%20Mormon%20is,and%20teachings%20of%20Jesus%20Christ.\">Le Livre de Mormon.<\/a><\/p><p>M\u00eame si le terme \u00ab \u00c9glise mormone \u00bb a longtemps \u00e9t\u00e9 appliqu\u00e9 publiquement \u00e0 l\u2019\u00c9glise comme surnom, il ne s\u2019agit pas d\u2019un titre autoris\u00e9 et l\u2019\u00c9glise d\u00e9courage son utilisation. Ainsi, nous demandons \u00e0 tous d\u2019\u00e9viter d\u2019utiliser l\u2019abr\u00e9viation \u00ab LDS \u00bb ou le surnom \u00ab Mormon \u00bb comme substituts au nom de l\u2019\u00c9glise.<\/p><p>Lorsque l&#039;on se r\u00e9f\u00e8re aux membres de l&#039;\u00c9glise, les termes \u00ab membres de l&#039;\u00c9glise de J\u00e9sus-Christ des Saints des Derniers Jours \u00bb ou \u00ab Saints des Derniers Jours \u00bb sont pr\u00e9f\u00e9r\u00e9s.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23e438a elementor-widget elementor-widget-text-editor\" data-id=\"23e438a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/dctemple.org\/fr\/about\/\">En savoir plus sur l&#039;histoire du temple de Washington DC ici&gt;&gt;<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Washington D.C. Temple The Washington D.C. Temple is considered a literal house of the Lord by members of The Church of Jesus Christ of Latter-Day Saints. The principal purpose of the temple is to provide ordinances and blessings to members in the Washington D.C. area. Ordinances include endowment, marriage, and baptism. Visitors are invited to [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"footnotes":""},"class_list":["post-6067","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Washington D.C. Temple - DCTemple.org<\/title>\n<meta name=\"description\" content=\"Discover the Washington D.C. Temple with its elaborate spires and gardens and about frequently asked questions, such as what happens inside.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/fr\/washington-d-c-temple\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Washington D.C. Temple - DCTemple.org\" \/>\n<meta property=\"og:description\" content=\"Discover the Washington D.C. Temple with its elaborate spires and gardens and about frequently asked questions, such as what happens inside.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/fr\/washington-d-c-temple\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-03T08:53:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/washington-d-c-temple\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/washington-d-c-temple\\\/\",\"name\":\"Washington D.C. Temple - DCTemple.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/washington-d-c-temple\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/washington-d-c-temple\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/DC-Banner-Series-2.webp\",\"datePublished\":\"2022-06-27T17:33:07+00:00\",\"dateModified\":\"2025-10-03T08:53:59+00:00\",\"description\":\"Discover the Washington D.C. Temple with its elaborate spires and gardens and about frequently asked questions, such as what happens inside.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/washington-d-c-temple\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/washington-d-c-temple\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/washington-d-c-temple\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/DC-Banner-Series-2.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/DC-Banner-Series-2.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/washington-d-c-temple\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Washington D.C. Temple\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Temple de Washington DC - DCTemple.org","description":"D\u00e9couvrez le temple de Washington DC avec ses fl\u00e8ches et ses jardins \u00e9labor\u00e9s et r\u00e9pondez aux questions fr\u00e9quemment pos\u00e9es, telles que ce qui se passe \u00e0 l&#039;int\u00e9rieur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/fr\/washington-d-c-temple\/","og_locale":"fr_FR","og_type":"article","og_title":"Washington D.C. Temple - DCTemple.org","og_description":"Discover the Washington D.C. Temple with its elaborate spires and gardens and about frequently asked questions, such as what happens inside.","og_url":"https:\/\/dctemple.org\/fr\/washington-d-c-temple\/","og_site_name":"DCTemple.org","article_modified_time":"2025-10-03T08:53:59+00:00","og_image":[{"url":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/washington-d-c-temple\/","url":"https:\/\/dctemple.org\/washington-d-c-temple\/","name":"Washington D.C. Temple - DCTemple.org","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dctemple.org\/washington-d-c-temple\/#primaryimage"},"image":{"@id":"https:\/\/dctemple.org\/washington-d-c-temple\/#primaryimage"},"thumbnailUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2.webp","datePublished":"2022-06-27T17:33:07+00:00","dateModified":"2025-10-03T08:53:59+00:00","description":"Discover the Washington D.C. Temple with its elaborate spires and gardens and about frequently asked questions, such as what happens inside.","breadcrumb":{"@id":"https:\/\/dctemple.org\/washington-d-c-temple\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/washington-d-c-temple\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dctemple.org\/washington-d-c-temple\/#primaryimage","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/washington-d-c-temple\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"Washington D.C. Temple"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/6067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/comments?post=6067"}],"version-history":[{"count":0,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/6067\/revisions"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/media?parent=6067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":6056,"date":"2022-06-27T12:18:40","date_gmt":"2022-06-27T16:18:40","guid":{"rendered":"http:\/\/dctemple.org\/?page_id=6056"},"modified":"2024-07-22T08:34:48","modified_gmt":"2024-07-22T12:34:48","slug":"expected-behavior-and-policies","status":"publish","type":"page","link":"https:\/\/dctemple.org\/fr\/expected-behavior-and-policies\/","title":{"rendered":"Comportement et politiques attendus"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6056\" class=\"elementor elementor-6056\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d939a77 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d939a77\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dbbac39\" data-id=\"dbbac39\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ecac13 elementor-widget elementor-widget-heading\" data-id=\"0ecac13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Robe attendue<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e749e32 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e749e32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a0aa39 elementor-widget elementor-widget-image\" data-id=\"2a0aa39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"522\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series.webp\" class=\"attachment-full size-full wp-image-6059\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series.webp 1200w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-300x131.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1024x445.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-768x334.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-18x8.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0df960 elementor-widget elementor-widget-text-editor\" data-id=\"d0df960\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Essayez juste d&#039;avoir l&#039;air gentil. Vous pouvez venir dans n&#039;importe quel v\u00eatement dans lequel vous vous sentez \u00e0 l&#039;aise tant qu&#039;il est modeste et non r\u00e9v\u00e9lateur.<\/p>\n<p>Chemises et chaussures sont obligatoires.<\/p>\n<p>Vous verrez des hommes porter des costumes ou des chemises boutonn\u00e9es et des cravates, les femmes portent g\u00e9n\u00e9ralement des robes ou des jupes. Ces personnes sont g\u00e9n\u00e9ralement des membres de l\u2019\u00c9glise qui se rendent \u00e0 l\u2019int\u00e9rieur du Temple ou assistent \u00e0 une activit\u00e9 de l\u2019\u00c9glise.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1684ecc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1684ecc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cb9fb0c\" data-id=\"cb9fb0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94d7789 elementor-widget elementor-widget-heading\" data-id=\"94d7789\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Comportement attendu<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1da52e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b1da52e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce629f2 elementor-widget elementor-widget-image\" data-id=\"ce629f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"522\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1.webp\" class=\"attachment-full size-full wp-image-6058\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1.webp 1200w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1-300x131.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1-1024x445.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1-768x334.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1-18x8.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c047ccc elementor-widget elementor-widget-text-editor\" data-id=\"c047ccc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Les terrains du temple de Washington DC sont consid\u00e9r\u00e9s comme sacr\u00e9s et doivent \u00eatre trait\u00e9s comme tels. Merci de respecter les jardins, les b\u00e2timents et les personnes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ed49f6 elementor-widget elementor-widget-text-editor\" data-id=\"2ed49f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Conditions g\u00e9n\u00e9rales d&#039;Utilisation:<\/p>\n<p>\u00c9vitez les propos offensants ou inappropri\u00e9s. Soyez gentil et courtois avec les autres.<\/p>\n<p>\u00c9vitez les commentaires ou les phrases grossi\u00e8res. Une bonne r\u00e8gle de base est de garder votre langue PG not\u00e9e.<\/p>\n<p>Les jardiniers ont d\u00e9ploy\u00e9 beaucoup d&#039;efforts pour garder le terrain propre et beau. Veuillez ne pas laisser de d\u00e9chets ni marcher sur les fleurs.<\/p>\n<p>Pas de planche \u00e0 roulettes, de longboard ou de patin \u00e0 roues align\u00e9es sur le terrain du temple.<\/p>\n<p>Vous \u00eates invit\u00e9s \u00e0 prendre des photos et des vid\u00e9os. Soyez respectueux des autres lorsque vous prenez des photos et respectez leur vie priv\u00e9e. Demandez la permission avant de prendre des photos d&#039;autres personnes.<\/p>\n<p>\u00c9vitez de crier ou de hurler. L&#039;enceinte du temple est un lieu de paix et de m\u00e9ditation. Vous pouvez parler librement, mais faites attention \u00e0 ceux qui vous entourent et qui viennent profiter de l&#039;esprit des lieux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Expected Dress Just try to look nice. You\u2019re welcome to come in any clothes you feel comfortable in as long as they are modest and not revealing. Shirts and shoes are required. You\u2019ll see men wear suits or button-up shirts and ties, women typically wear dresses or skirts. These people are generally members of the [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"footnotes":""},"class_list":["post-6056","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Expected Behavior and policies - DCTemple.org<\/title>\n<meta name=\"description\" content=\"See expected behavior and policies for visiting the Washington DC Temple grounds. All are welcome, so please be respectful during your visit.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/fr\/expected-behavior-and-policies\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expected Behavior and policies - DCTemple.org\" \/>\n<meta property=\"og:description\" content=\"See expected behavior and policies for visiting the Washington DC Temple grounds. All are welcome, so please be respectful during your visit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/fr\/expected-behavior-and-policies\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-22T12:34:48+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/expected-behavior-and-policies\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/expected-behavior-and-policies\\\/\",\"name\":\"Expected Behavior and policies - DCTemple.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/expected-behavior-and-policies\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/expected-behavior-and-policies\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/DC-Banner-Series.jpg\",\"datePublished\":\"2022-06-27T16:18:40+00:00\",\"dateModified\":\"2024-07-22T12:34:48+00:00\",\"description\":\"See expected behavior and policies for visiting the Washington DC Temple grounds. All are welcome, so please be respectful during your visit.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/expected-behavior-and-policies\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/expected-behavior-and-policies\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/expected-behavior-and-policies\\\/#primaryimage\",\"url\":\"http:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/DC-Banner-Series.jpg\",\"contentUrl\":\"http:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/DC-Banner-Series.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/expected-behavior-and-policies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Expected Behavior and policies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comportement attendu et politiques - DCTemple.org","description":"Consultez les r\u00e8gles de comportement et de s\u00e9curit\u00e9 pour visiter le temple de Washington DC. Tout le monde est le bienvenu\u00a0; soyez donc respectueux lors de votre visite.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/fr\/expected-behavior-and-policies\/","og_locale":"fr_FR","og_type":"article","og_title":"Expected Behavior and policies - DCTemple.org","og_description":"See expected behavior and policies for visiting the Washington DC Temple grounds. All are welcome, so please be respectful during your visit.","og_url":"https:\/\/dctemple.org\/fr\/expected-behavior-and-policies\/","og_site_name":"DCTemple.org","article_modified_time":"2024-07-22T12:34:48+00:00","og_image":[{"url":"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/expected-behavior-and-policies\/","url":"https:\/\/dctemple.org\/expected-behavior-and-policies\/","name":"Expected Behavior and policies - DCTemple.org","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dctemple.org\/expected-behavior-and-policies\/#primaryimage"},"image":{"@id":"https:\/\/dctemple.org\/expected-behavior-and-policies\/#primaryimage"},"thumbnailUrl":"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series.jpg","datePublished":"2022-06-27T16:18:40+00:00","dateModified":"2024-07-22T12:34:48+00:00","description":"See expected behavior and policies for visiting the Washington DC Temple grounds. All are welcome, so please be respectful during your visit.","breadcrumb":{"@id":"https:\/\/dctemple.org\/expected-behavior-and-policies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/expected-behavior-and-policies\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dctemple.org\/expected-behavior-and-policies\/#primaryimage","url":"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series.jpg","contentUrl":"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/expected-behavior-and-policies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"Expected Behavior and policies"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/6056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/comments?post=6056"}],"version-history":[{"count":0,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/6056\/revisions"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/media?parent=6056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":5961,"date":"2022-06-27T11:33:45","date_gmt":"2022-06-27T15:33:45","guid":{"rendered":"http:\/\/dctemple.org\/?page_id=5961"},"modified":"2024-07-23T09:28:31","modified_gmt":"2024-07-23T13:28:31","slug":"visit","status":"publish","type":"page","link":"https:\/\/dctemple.org\/fr\/visit\/","title":{"rendered":"Visite"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"5961\" class=\"elementor elementor-5961\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ff92c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ff92c4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf8521a\" data-id=\"bf8521a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6dd83fb elementor-widget elementor-widget-heading\" data-id=\"6dd83fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Choses \u00e0 faire<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0cb1aa elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c0cb1aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50a2120 elementor-widget elementor-widget-text-editor\" data-id=\"50a2120\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Toutes les activit\u00e9s sont familiales et ouvertes \u00e0 tous. Le terrain du temple est un lieu sacr\u00e9. Nous aimons rire, sourire et nous amuser. Nous demandons que l&#039;enceinte du temple soit trait\u00e9e avec gentillesse et respect. Pour plus d\u2019informations sur les comportements et politiques attendus, <a href=\"https:\/\/dctemple.org\/fr\/expected-behavior-and-policies\/\" rel=\"noopener\">Cliquez ici.<\/a><\/p><p>L&#039;entr\u00e9e dans le temple lui-m\u00eame est r\u00e9serv\u00e9e uniquement aux membres ayant une recommandation active \u00e0 l&#039;usage du temple (<a href=\"https:\/\/dctemple.org\/fr\/washington-d-c-temple\/\" rel=\"noopener\">plus de d\u00e9tails ici<\/a>).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e76f345 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e76f345\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-08bb4ea\" data-id=\"08bb4ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fede4fd elementor-widget elementor-widget-pp-flipbox\" data-id=\"fede4fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-flipbox.default\">\n\t\t\t\t\t\t\t<div class=\"pp-flipbox-container pp-animate-flip pp-direction-right\">\n\t\t\t<div class=\"pp-flipbox-flip-card\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-front\">\n\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t<div class=\"pp-flipbox-icon-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-10.webp\" alt=\"Images de cartes \u00e0 rabat DC (10)\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<h1 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\tVisites gratuites\t\t\t\t\t<\/h1>\n\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"pp-flipbox-back\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\t\tVisitez le centre des visiteurs et l&#039;enceinte du temple\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\tProfitez d&#039;une visite guid\u00e9e avec l&#039;un de nos sympathiques b\u00e9n\u00e9voles. Au cours de la visite, vous d\u00e9couvrirez les meilleures vues de l&#039;int\u00e9rieur, explorerez les lieux, serez guid\u00e9 \u00e0 travers des expositions interactives et vivrez une exp\u00e9rience incroyable avec le Christus de Thorvaldsen.\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-172c63a\" data-id=\"172c63a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0ed50c elementor-widget elementor-widget-pp-flipbox\" data-id=\"c0ed50c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-flipbox.default\">\n\t\t\t\t\t\t\t<div class=\"pp-flipbox-container pp-animate-flip pp-direction-right\">\n\t\t\t<div class=\"pp-flipbox-flip-card\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-front\">\n\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t<div class=\"pp-flipbox-icon-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-11.webp\" alt=\"Images de cartes \u00e0 rabat DC (11)\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<h1 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\tInteractif<br> Affiche\t\t\t\t\t<\/h1>\n\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"pp-flipbox-back\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\t\tExpositions et affichages interactifs\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\tProfitez d&#039;expositions interactives amusantes et familiales. Chaque exposition aide les familles \u00e0 d\u00e9couvrir le plan de Dieu, la pri\u00e8re et d&#039;autres exp\u00e9riences \u00e9difiantes.<br> En plus des expositions, il y a des vid\u00e9os pour les familles. Des vid\u00e9os et des expositions interactives sont disponibles en plusieurs langues.\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5aadf1a\" data-id=\"5aadf1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9636aee elementor-widget elementor-widget-pp-flipbox\" data-id=\"9636aee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-flipbox.default\">\n\t\t\t\t\t\t\t<div class=\"pp-flipbox-container pp-animate-flip pp-direction-right\">\n\t\t\t<div class=\"pp-flipbox-flip-card\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-front\">\n\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t<div class=\"pp-flipbox-icon-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-9.webp\" alt=\"Images de cartes \u00e0 rabat DC (9)\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<h1 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\tArt et peintures murales\t\t\t\t\t<\/h1>\n\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"pp-flipbox-back\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\t\tEn savoir plus sur le Christ \u00e0 travers l&#039;art\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\tSuivez la vie du Christ \u00e0 travers les peintures du b\u00e2timent et interagissez avec des expositions passionnantes. R\u00e9fl\u00e9chissez \u00e0 la majest\u00e9 et \u00e0 l&#039;\u00e9merveillement des cr\u00e9ations de Dieu et r\u00e9fl\u00e9chissez \u00e0 l&#039;invitation des bras tendus du Christus de Thorvaldsen, une magnifique statue de 11 pieds du Sauveur.\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7be44eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7be44eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dcb3d97\" data-id=\"dcb3d97\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4115c2 elementor-widget elementor-widget-pp-flipbox\" data-id=\"b4115c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-flipbox.default\">\n\t\t\t\t\t\t\t<div class=\"pp-flipbox-container pp-animate-flip pp-direction-right\">\n\t\t\t<div class=\"pp-flipbox-flip-card\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-front\">\n\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t<div class=\"pp-flipbox-icon-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-8.webp\" alt=\"Images de cartes \u00e0 rabat DC (8)\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<h1 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\tJardins organis\u00e9s\t\t\t\t\t<\/h1>\n\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"pp-flipbox-back\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\t\tExplorez les jardins\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\tLe temple de Washington DC se trouve au sommet d&#039;une colline de 52 acres avec des bois, des sp\u00e9cimens d&#039;arbres et de magnifiques jardins de fleurs.<br>Les jardins sont destin\u00e9s \u00e0 \u00eatre un lieu paisible pour se reposer, m\u00e9diter et se promener tranquillement.\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e9adf30\" data-id=\"e9adf30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c754afd elementor-widget elementor-widget-pp-flipbox\" data-id=\"c754afd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-flipbox.default\">\n\t\t\t\t\t\t\t<div class=\"pp-flipbox-container pp-animate-flip pp-direction-right\">\n\t\t\t<div class=\"pp-flipbox-flip-card\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-front\">\n\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t<div class=\"pp-flipbox-icon-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-7.webp\" alt=\"Images de cartes \u00e0 rabat DC (7)\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<h1 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\tVues inspirantes\t\t\t\t\t<\/h1>\n\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"pp-flipbox-back\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\t\tGagner en perspective\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\tLe temple de Washington DC se dresse magnifiquement contre le ciel, que ce soit sous le soleil du jour ou lorsqu&#039;il est illumin\u00e9 la nuit. Profitez de la paix des jardins, de la fontaine qui coule et des vues inspirantes.\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5155541\" data-id=\"5155541\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b71115d elementor-widget elementor-widget-pp-flipbox\" data-id=\"b71115d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-flipbox.default\">\n\t\t\t\t\t\t\t<div class=\"pp-flipbox-container pp-animate-flip pp-direction-right\">\n\t\t\t<div class=\"pp-flipbox-flip-card\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-front\">\n\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t<div class=\"pp-flipbox-icon-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-6.webp\" alt=\"Images de cartes \u00e0 rabat DC (6)\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<h1 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\tLa photographie\t\t\t\t\t<\/h1>\n\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"pp-flipbox-back\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\t\tCapturez l&#039;instant\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\tUne architecture \u00e9poustouflante, de beaux jardins et des fontaines jaillissantes font du temple de Washington DC l&#039;endroit id\u00e9al pour la photographie. Les photographes sont invit\u00e9s \u00e0 utiliser le terrain pour les s\u00e9ances photo. Il n&#039;y a pas de frais d&#039;entr\u00e9e ni de frais de photographie. \n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8991bbd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8991bbd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c752d05\" data-id=\"c752d05\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31d5f17 elementor-widget elementor-widget-heading\" data-id=\"31d5f17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Faire un tour<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97fe432 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"97fe432\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5c111b elementor-widget elementor-widget-text-editor\" data-id=\"e5c111b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Faites une visite guid\u00e9e avec l\u2019une de nos s\u0153urs missionnaires. Au cours de la visite, vous d\u00e9couvrirez les meilleures vues de l&#039;int\u00e9rieur, profiterez du paisible bassin de r\u00e9flexion et des fontaines, serez guid\u00e9 \u00e0 travers des expositions interactives et vivrez une exp\u00e9rience inoubliable avec le mus\u00e9e de Thorvaldsen. <i>Christus.<\/i><\/p><p>D\u00e9couvrez les meilleurs endroits pour prendre des selfies et des photos, les trois meilleures vues du temple et les joyaux cach\u00e9s du temple de Washington DC. Ces visites sont gratuites et sans rendez-vous. Si vous souhaitez planifier une visite virtuelle, veuillez cliquer sur le bouton ci-dessous.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-121873d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"121873d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/clickly.org\/6go85\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Planifier une visite virtuelle<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4169678 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4169678\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-96433c5\" data-id=\"96433c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f2aa70 elementor-widget elementor-widget-spacer\" data-id=\"1f2aa70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0b3c86 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0b3c86\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-313e9e7\" data-id=\"313e9e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3eeca49 elementor-widget elementor-widget-html\" data-id=\"3eeca49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<h2 id=\"visitvc\" style=\"text-align:center;\">Centre des visiteurs du temple de Washington DC<\/h2>\n<center><hr style=\"width:6%;color:#FFD084;padding-bottom:15px;padding-top:15px;border-width:3.3px;\"><\/center>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a13abc elementor-widget elementor-widget-spacer\" data-id=\"7a13abc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7831ef0b elementor-section-content-middle elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7831ef0b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-18b2346d\" data-id=\"18b2346d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-110b3fdc elementor-widget elementor-widget-google_maps\" data-id=\"110b3fdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Washington%20D.C.%20Temple%20Visitors%27%20Center&#038;t=m&#038;z=17&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Centre des visiteurs du temple de Washington DC\"\n\t\t\t\t\taria-label=\"Centre des visiteurs du temple de Washington DC\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-50080dfd\" data-id=\"50080dfd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-145826f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"145826f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-33d58541\" data-id=\"33d58541\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-764a14b2 elementor-widget elementor-widget-heading\" data-id=\"764a14b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Emplacement<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3175dc77 elementor-widget elementor-widget-text-editor\" data-id=\"3175dc77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>9900 promenade Stoneybrook\u00a0<br \/>Kensington, MD 20895<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2b2cdd65\" data-id=\"2b2cdd65\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ea4f26 elementor-widget elementor-widget-heading\" data-id=\"9ea4f26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Nous contacter<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e0fd02c elementor-widget elementor-widget-text-editor\" data-id=\"2e0fd02c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tT\u00e9l\u00e9phone : <a href=\"tel:+1-301-587-0144\">+ 1 301 587 0144<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ed28bde elementor-widget elementor-widget-text-editor\" data-id=\"2ed28bde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>E-mail : <a href=\"mailto:wdcvisitorscenter@gmail.com\">wdcvisitorscenter@gmail.com<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-377f1a21 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"377f1a21\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6b6a9ff5\" data-id=\"6b6a9ff5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54c0836f elementor-widget elementor-widget-heading\" data-id=\"54c0836f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Nos heures<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31e4d55b elementor-widget elementor-widget-text-editor\" data-id=\"31e4d55b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tSept jours sur sept\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68648e0d elementor-widget elementor-widget-text-editor\" data-id=\"68648e0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>10h00 \u2013 21h00<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-57a8034d\" data-id=\"57a8034d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5693c4a0 elementor-widget elementor-widget-heading\" data-id=\"5693c4a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Suivez-nous<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13d1b088 elementor-shape-square e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"13d1b088\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-animation-grow elementor-repeater-item-2d0da0c\" href=\"https:\/\/www.facebook.com\/dctemplevisitorscenter\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook-f\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M279.14 288l14.22-92.66h-88.91v-60.13c0-25.35 12.42-50.06 52.24-50.06h40.42V6.26S260.43 0 225.36 0c-73.22 0-121.08 44.38-121.08 124.72v70.62H22.89V288h81.39v224h100.17V288z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-grow elementor-repeater-item-af38224\" href=\"https:\/\/www.instagram.com\/dctemplevisitorscenter\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-envelope elementor-animation-grow elementor-repeater-item-914746e\" href=\"mailto:wdcvisitorscenter@gmail.com\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Enveloppe<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.3 190.8c3.9-3.1 9.7-.2 9.7 4.7V400c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V195.6c0-5 5.7-7.8 9.7-4.7 22.4 17.4 52.1 39.5 154.1 113.6 21.1 15.4 56.7 47.8 92.2 47.6 35.7.3 72-32.8 92.3-47.6 102-74.1 131.6-96.3 154-113.7zM256 320c23.2.4 56.6-29.2 73.4-41.4 132.7-96.3 142.8-104.7 173.4-128.7 5.8-4.5 9.2-11.5 9.2-18.9v-19c0-26.5-21.5-48-48-48H48C21.5 64 0 85.5 0 112v19c0 7.4 3.4 14.3 9.2 18.9 30.6 23.9 40.7 32.4 173.4 128.7 16.8 12.2 50.2 41.8 73.4 41.4z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-animation-grow elementor-repeater-item-d138417\" href=\"https:\/\/www.youtube.com\/channel\/UCbTvEqM1-VcgfruzKbG9S9Q\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ad08e17 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad08e17\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-76cf388\" data-id=\"76cf388\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58c5919 elementor-widget elementor-widget-text-editor\" data-id=\"58c5919\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><em>Des toilettes propres sont disponibles au centre des visiteurs. <\/em><em>Parking gratuit.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f654e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f654e2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b3a0686\" data-id=\"b3a0686\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd0d7ea elementor-widget elementor-widget-heading\" data-id=\"dd0d7ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Galeries d&#039;images<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-280c2a8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"280c2a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb24bba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb24bba\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3bd78f8\" data-id=\"3bd78f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e62bd3 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"1e62bd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-756de23 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"washington-dc-temple-spring-1160328-wallpaper cropped-27\"><\/div><div class=\"elementor-background-overlay\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/dctemple.org\/fr\/temple-exterior-gallery\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">EXT\u00c9RIEUR DU TEMPLE<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3150782\" data-id=\"3150782\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47d4acd elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"47d4acd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-756de23 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"20.01.29 DC Temple - celestial\"><\/div><div class=\"elementor-background-overlay\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/dctemple.org\/fr\/interior-renderings\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">RENDUITS INT\u00c9RIEURS<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1032f6c\" data-id=\"1032f6c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-271232e elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"271232e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-756de23 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Capture d&#039;\u00e9cran 2021-12-29 \u00e0 22h58h52\"><\/div><div class=\"elementor-background-overlay\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/dctemple.org\/fr\/history-gallery\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">L&#039;HISTOIRE<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-501faec\" data-id=\"501faec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1345b3d elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"1345b3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-756de23 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"The Morning Breaks Cropped 3-28\"><\/div><div class=\"elementor-background-overlay\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/dctemple.org\/fr\/original-artwork\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">ART ORIGINAL<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fecb8cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fecb8cf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4cea9b4\" data-id=\"4cea9b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe4c509 elementor-widget elementor-widget-spacer\" data-id=\"fe4c509\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a54875 elementor-widget elementor-widget-heading\" data-id=\"1a54875\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Questions fr\u00e9quemment pos\u00e9es<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75fccc3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"75fccc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8860e1 elementor-widget elementor-widget-global elementor-global-1724 elementor-widget-toggle\" data-id=\"e8860e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2431\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2431\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Est-ce le temple \u00ab mormon \u00bb sur le p\u00e9riph\u00e9rique ?\u200b<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2431\"><p>Ce b\u00e2timent sacr\u00e9 \u00e9tait souvent appel\u00e9 le \u00ab Temple mormon \u00bb. Cependant, en 2018, le proph\u00e8te et pr\u00e9sident de l&#039;\u00c9glise, Russell M. Nelson, a propos\u00e9 de corriger tout nom inexact de l&#039;\u00c9glise de J\u00e9sus-Christ des Saints des Derniers Jours, y compris une r\u00e9f\u00e9rence inappropri\u00e9e \u00e0 \u00ab l&#039;\u00c9glise mormone \u00bb. Mormon \u00e9tait un grand proph\u00e8te que nous honorons, mais l&#039;\u00c9glise a \u00e9t\u00e9 nomm\u00e9e d&#039;apr\u00e8s notre Sauveur J\u00e9sus-Christ. Le nom correct de l&#039;\u00c9glise est : L&#039;\u00c9glise de J\u00e9sus-Christ des Saints des Derniers Jours. Ainsi, le nom propre du Temple est le \u00ab\u00a0Temple de Washington DC de l&#039;\u00c9glise de J\u00e9sus-Christ des Saints des Derniers Jours\u00a0\u00bb.\u00a0<\/p><p>La r\u00e9f\u00e9rence aux \u00ab saints \u00bb au nom de l&#039;\u00c9glise fait r\u00e9f\u00e9rence \u00e0 l&#039;utilisation par l&#039;ap\u00f4tre Paul pour les personnes qui essaient de suivre les enseignements de J\u00e9sus-Christ.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2432\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2432\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Le temple de Washington DC est-il toujours ouvert aux visites\u00a0? <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2432\"><p>Les visites en personne de l&#039;int\u00e9rieur du temple de Washington DC ont officiellement pris fin le 11 juin 2022, mais il existe encore de nombreuses fa\u00e7ons de voir le temple. Vous pouvez prendre un <a href=\"https:\/\/www.youtube.com\/watch?v=BSV4BrjDJU4\">Visite virtuelle \u00e0 360 degr\u00e9s<\/a> de l&#039;int\u00e9rieur ici, prenez le <a href=\"https:\/\/www.youtube.com\/watch?v=mUYF1TX5RxM\">tour virtuel<\/a> ici, ou voir des photos de l&#039;int\u00e9rieur du temple <a href=\"https:\/\/dctemple.org\/fr\/galleries\/temple-interior\/\">ici<\/a>. Vous pouvez \u00e9galement voir venir voir l&#039;ext\u00e9rieur et les terrains du temple et profiter d&#039;une reproduction inspirante du <em>J\u00e9sus<\/em> statue, expositions interactives, activit\u00e9s et \u00e9v\u00e9nements adapt\u00e9s aux familles et gratuits au centre des visiteurs du temple. Le centre des visiteurs est ouvert au public toute l&#039;ann\u00e9e de 10 h \u00e0 21 h, sept jours sur sept.<\/p><p>\u00c0 No\u00ebl, les jardins s&#039;illuminent pendant la F\u00eate des Lumi\u00e8res, qui propose des concerts nocturnes, une cr\u00e8che grandeur nature et des cr\u00e8ches internationales.<\/p><p><a href=\"https:\/\/dctemple.org\/fr\/\">Abonnez-vous \u00e0 notre newsletter<\/a> soyez les premiers inform\u00e9s de nos derniers \u00e9v\u00e9nements.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2433\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2433\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Je n&#039;ai pas pu assister \u00e0 la journ\u00e9e portes ouvertes. Existe-t-il une option de visite virtuelle ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2433\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2433\"><p>Oui! <a href=\"https:\/\/www.youtube.com\/watch?v=mUYF1TX5RxM&amp;feature=emb_imp_woyt\">Cliquez ici<\/a> pour une visite virtuelle du temple de Washington DC dirig\u00e9e par fr\u00e8re et s\u0153ur Stevenson et fr\u00e8re et s\u0153ur Renlund.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2434\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2434\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Le centre d&#039;accueil est-il d\u00e9j\u00e0 ouvert\u00a0?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2434\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2434\"><p>Le centre des visiteurs est maintenant ouvert au public, sept jours sur sept toute l&#039;ann\u00e9e de 10 h 00 \u00e0 21 h 00. Venez profiter de l&#039;ext\u00e9rieur et du terrain du temple, voir une reproduction inspirante du <em>J\u00e9sus<\/em> statue et profitez d&#039;expositions interactives, d&#039;activit\u00e9s et d&#039;\u00e9v\u00e9nements gratuits et adapt\u00e9s aux familles.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2435\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2435\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quand est la F\u00eate des Lumi\u00e8res ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2435\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2435\"><p>Chaque ann\u00e9e, aux alentours de No\u00ebl, le parc s&#039;illumine lors de la F\u00eate des Lumi\u00e8res, qui propose des concerts nocturnes, une cr\u00e8che grandeur nature et des cr\u00e8ches internationales.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2436\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2436\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Pourquoi construit-on des temples et que se passe-t-il \u00e0 l&#039;int\u00e9rieur ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2436\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2436\"><p>Visitez notre <a href=\"https:\/\/dctemple.org\/fr\/about\/\">\u00c0 propos de la page<\/a> pour tout savoir sur les raisons de la construction des temples et sur ce qui se passe \u00e0 l&#039;int\u00e9rieur.\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2437\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2437\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Pourquoi les saints des derniers jours construisent-ils des temples ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2437\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2437\"><p>L&#039;\u00c9glise de J\u00e9sus-Christ des Saints des Derniers Jours construit des temples depuis les ann\u00e9es 1830. Les temples des saints des derniers jours sont consid\u00e9r\u00e9s comme des maisons de Dieu, un lieu de saintet\u00e9 et de paix s\u00e9par\u00e9 des pr\u00e9occupations du monde. Ils offrent un lieu o\u00f9 les membres de l&#039;\u00c9glise font des promesses et des engagements formels envers Dieu. Ils sont aussi le lieu o\u00f9 se d\u00e9roulent les plus hauts sacrements de la foi \u2014 le mariage des couples et le \u00ab scellement \u00bb des familles pour l&#039;\u00e9ternit\u00e9.<\/p><p>En savoir plus sur le <a href=\"https:\/\/dctemple.org\/fr\/about\/\">\u00c0 propos de la page.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2438\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-2438\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">J&#039;ai des questions suppl\u00e9mentaires, comment y r\u00e9pondre\u00a0? <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2438\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-2438\"><div>Si vous avez des questions suppl\u00e9mentaires, veuillez nous \u00e9crire \u00e0\u00a0<a href=\"mailto:wdcvisitorscenter@gmail.com\" target=\"_blank\" rel=\"noopener\">wdcvisitorscenter@gmail.com<\/a>. Nous r\u00e9pondrons aussi rapidement que possible, probablement dans les 24 heures.<\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e2e22d elementor-widget elementor-widget-spacer\" data-id=\"2e2e22d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Things To Do All activities are family-friendly and open to all. The temple grounds are a sacred place. We love to laugh, smile, and have fun. We ask that the temple grounds be treated with kindness and respect. For more information about expected behavior and policies, click here. Entering the temple itself is reserved only [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"footnotes":""},"class_list":["post-5961","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visit - DCTemple.org<\/title>\n<meta name=\"description\" content=\"Plan your visit to the Washington DC Temple and feel the peace of Jesus Christ as you stroll around the gardens and see the Visitors&#039; Center.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/fr\/visit\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visit - DCTemple.org\" \/>\n<meta property=\"og:description\" content=\"Plan your visit to the Washington DC Temple and feel the peace of Jesus Christ as you stroll around the gardens and see the Visitors&#039; Center.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/fr\/visit\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-23T13:28:31+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-10.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/visit\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/visit\\\/\",\"name\":\"Visit - DCTemple.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/visit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/visit\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/DC-Flip-Card-Images-10.jpg\",\"datePublished\":\"2022-06-27T15:33:45+00:00\",\"dateModified\":\"2024-07-23T13:28:31+00:00\",\"description\":\"Plan your visit to the Washington DC Temple and feel the peace of Jesus Christ as you stroll around the gardens and see the Visitors' Center.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/visit\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/visit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/visit\\\/#primaryimage\",\"url\":\"http:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/DC-Flip-Card-Images-10.jpg\",\"contentUrl\":\"http:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/DC-Flip-Card-Images-10.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/visit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visit - DCTemple.org","description":"Plan your visit to the Washington DC Temple and feel the peace of Jesus Christ as you stroll around the gardens and see the Visitors' Center.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/fr\/visit\/","og_locale":"fr_FR","og_type":"article","og_title":"Visit - DCTemple.org","og_description":"Plan your visit to the Washington DC Temple and feel the peace of Jesus Christ as you stroll around the gardens and see the Visitors' Center.","og_url":"https:\/\/dctemple.org\/fr\/visit\/","og_site_name":"DCTemple.org","article_modified_time":"2024-07-23T13:28:31+00:00","og_image":[{"url":"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-10.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/visit\/","url":"https:\/\/dctemple.org\/visit\/","name":"Visit - DCTemple.org","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dctemple.org\/visit\/#primaryimage"},"image":{"@id":"https:\/\/dctemple.org\/visit\/#primaryimage"},"thumbnailUrl":"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-10.jpg","datePublished":"2022-06-27T15:33:45+00:00","dateModified":"2024-07-23T13:28:31+00:00","description":"Plan your visit to the Washington DC Temple and feel the peace of Jesus Christ as you stroll around the gardens and see the Visitors' Center.","breadcrumb":{"@id":"https:\/\/dctemple.org\/visit\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/visit\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dctemple.org\/visit\/#primaryimage","url":"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-10.jpg","contentUrl":"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-10.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/visit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"Visit"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/5961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/comments?post=5961"}],"version-history":[{"count":0,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/5961\/revisions"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/media?parent=5961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":4260,"date":"2022-04-14T18:56:55","date_gmt":"2022-04-14T22:56:55","guid":{"rendered":"http:\/\/dctemple.org\/?page_id=4260"},"modified":"2024-07-19T13:16:18","modified_gmt":"2024-07-19T17:16:18","slug":"asl-tour","status":"publish","type":"page","link":"https:\/\/dctemple.org\/fr\/asl-tour\/","title":{"rendered":"Visite ASL"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4260\" class=\"elementor elementor-4260\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2120af7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2120af7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c7940fd\" data-id=\"c7940fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2298533 elementor-widget elementor-widget-text-editor\" data-id=\"2298533\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #000000;\">Langue:<\/span> \u00a0<a href=\"https:\/\/dctemple.org\/asl-tour\/\">ASL\u00a0 <\/a><span style=\"color: #999999;\">|\u00a0<\/span> <a href=\"https:\/\/dctemple.org\/zh\/open-house-tour\/\">Chinois<\/a>\u00a0 <span style=\"color: #999999;\">|\u00a0<\/span> <a href=\"https:\/\/dctemple.org\/en\/open-house-tour\/\">Anglais\u00a0 <span style=\"color: #999999;\">|\u00a0<\/span><\/a>\u00a0\u00a0<a href=\"https:\/\/dctemple.org\/fr\/open-house-tour\/\">fran\u00e7ais<\/a><a href=\"https:\/\/www.youtube.com\/watch?v=pmarf921mkA\">\u00a0\u00a0<span style=\"color: #999999;\">|\u00a0<\/span><\/a>\u00a0\u00a0<a href=\"https:\/\/dctemple.org\/de\/open-house-tour\/\">allemand<\/a><a href=\"https:\/\/www.youtube.com\/watch?v=pmarf921mkA\">\u00a0\u00a0<span style=\"color: #999999;\">|\u00a0<\/span><\/a><a href=\"https:\/\/dctemple.org\/de\/open-house-tour\/\">\u00a0\u00a0<\/a><a href=\"https:\/\/dctemple.org\/ja\/open-house-tour\/\">Japonais<\/a><a href=\"https:\/\/www.youtube.com\/watch?v=pmarf921mkA\">\u00a0\u00a0<span style=\"color: #999999;\">|\u00a0<\/span><\/a><a href=\"https:\/\/dctemple.org\/de\/open-house-tour\/\">\u00a0\u00a0<\/a><a href=\"https:\/\/dctemple.org\/ko\/open-house-tour\/\">cor\u00e9en<\/a><a href=\"https:\/\/www.youtube.com\/watch?v=pmarf921mkA\">\u00a0\u00a0<span style=\"color: #999999;\">|\u00a0<\/span><\/a><a href=\"https:\/\/dctemple.org\/de\/open-house-tour\/\">\u00a0\u00a0<\/a><a href=\"https:\/\/dctemple.org\/fa\/open-house-tour\/\">persan<\/a><a href=\"https:\/\/youtu.be\/xHtTp0UbBvE\"> <span style=\"color: #999999;\">|\u00a0<\/span><\/a> \u00a0<a href=\"https:\/\/dctemple.org\/pt\/open-house-tour\/\">Portugais Br\u00e9silien <span style=\"color: #999999;\">|\u00a0<\/span><\/a>\u00a0\u00a0<a href=\"https:\/\/dctemple.org\/es\/open-house-tour\/\">Espagnol<\/a><a href=\"https:\/\/www.youtube.com\/watch?v=pmarf921mkA\">\u00a0\u00a0<span style=\"color: #999999;\">|\u00a0<\/span><\/a><a href=\"https:\/\/dctemple.org\/es\/open-house-tour\/\">\u00a0\u00a0<\/a><a href=\"https:\/\/dctemple.org\/tl\/open-house-tour\/\">tagalog<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8d5b6eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8d5b6eb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41b0524\" data-id=\"41b0524\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e064bb elementor-widget elementor-widget-spacer\" data-id=\"0e064bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4a683e elementor-widget elementor-widget-text-editor\" data-id=\"a4a683e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #223661;\">LA MAISON DU SEIGNEUR<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97cbacd elementor-widget elementor-widget-text-editor\" data-id=\"97cbacd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" contenteditable=\"true\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\">Washington D.C. Temple\u200b<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d199f8 elementor-widget elementor-widget-text-editor\" data-id=\"2d199f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #223661;\">L\u2019\u00c9GLISE DE J\u00c9SUS-CHRIST DES SAINTS DES DERNIERS JOURS<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5e8009 elementor-widget elementor-widget-text-editor\" data-id=\"e5e8009\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #223661;\">American Sign Language <br \/>Self-Guided Tour<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1732572 elementor-widget elementor-widget-spacer\" data-id=\"1732572\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74007ed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74007ed\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-15d1bed\" data-id=\"15d1bed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42da297 elementor-widget elementor-widget-spacer\" data-id=\"42da297\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50e509e elementor-widget elementor-widget-heading\" data-id=\"50e509e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><h3 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\" style=\"letter-spacing: normal;text-align: center\">Introduction<\/h3><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9a7949 elementor-widget elementor-widget-video\" data-id=\"b9a7949\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/sbdQ4hoZlQA&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6969147 elementor-widget elementor-widget-text-editor\" data-id=\"6969147\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>As members of The Church of Jesus Christ of Latter-day Saints, we worship God and His Son, Jesus Christ. We come to the house of the Lord to learn about them and promise to follow their commandments. Like biblical temples, modern temples are places of peace, love and connection. Temples also are places where sacred religious ceremonies are performed<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28bec39 elementor-widget elementor-widget-spacer\" data-id=\"28bec39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c39f8a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c39f8a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22a247f\" data-id=\"22a247f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ece17d elementor-widget elementor-widget-spacer\" data-id=\"5ece17d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c2e869 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c2e869\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0651c85\" data-id=\"0651c85\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-affb8bb elementor-widget elementor-widget-heading\" data-id=\"affb8bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><h3 data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\" style=\"letter-spacing: normal\">1. Le bureau d'accueil<\/h3><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9065c9 elementor-widget elementor-widget-video\" data-id=\"a9065c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/2UwYp0_vbg0&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a0c6ff elementor-widget elementor-widget-text-editor\" data-id=\"1a0c6ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u00ef Pendant la journ\u00e9e portes ouvertes, nous invitons tout le monde \u00e0 entrer\ndans le temple et \u00e0 en apprendre davantage sur ses objectifs.<\/p><p>\u00ef Une fois que le temple est consacr\u00e9, les membres de l\u2019\u00c9glise peuvent entrer\nen s\u2019effor\u00e7ant de vivre une vie juste et d\u2019avoir une d\u00e9votion semblable \u00e0 celle\ndu Christ. Ils re\u00e7oivent ensuite une carte, appel\u00e9e recommandation du\ntemple, qui leur permet d\u2019entrer et d\u2019adorer dans le temple.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0620507 elementor-widget elementor-widget-spacer\" data-id=\"0620507\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44adcd9 elementor-widget elementor-widget-heading\" data-id=\"44adcd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2. Baptistry\u200b<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-545734b elementor-widget elementor-widget-video\" data-id=\"545734b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/niHjsPVXbzo&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1543f0f elementor-widget elementor-widget-text-editor\" data-id=\"1543f0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u2022J\u00e9sus-Christ a \u00e9t\u00e9 baptis\u00e9 et nous a enseign\u00e9 que le bapt\u00eame est n\u00e9cessaire\npour entrer dans le royaume de Dieu (voir Jean 3:5).<\/p><p>\u2022 Dans nos \u00e9glises, les bapt\u00eames sont effectu\u00e9s pour les vivants apr\u00e8s l\u2019\u00e2ge de\nhuit ans.<\/p><p>\u2022 Gr\u00e2ce \u00e0 la recherche sur l\u2019histoire familiale, nous identifions nos anc\u00eatres et\naccomplissons des bapt\u00eames en leur nom dans notre temple.<\/p><p>\u2022 Ce bapt\u00eame est une offrande d\u2019amour. Nous croyons que ceux qui sont\nmorts sont libres d\u2019accepter ou de refuser ce don du bapt\u00eame.<\/p><p>\u2022 La pratique d\u2019\u00eatre baptis\u00e9 pour les morts a \u00e9t\u00e9 mentionn\u00e9e par l\u2019ap\u00f4tre Paul\n(1 Cor.15:29).<\/p><p>\u2022 Les fonts baptismaux sont similaires aux fonts baptismaux du temple de\nSalomon, d\u00e9crits dans la Bible (1 Rois 7:25).<\/p><p>\u2022 The 12 oxen symbolize the 12 tribes of Israel spoken about in the Old Testament<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26a5df7 elementor-widget elementor-widget-spacer\" data-id=\"26a5df7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad6de95 elementor-widget elementor-widget-heading\" data-id=\"ad6de95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3. Vestiaires<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4add4dd elementor-widget elementor-widget-video\" data-id=\"4add4dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/eyWra9VXnv8&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d33fd7 elementor-widget elementor-widget-text-editor\" data-id=\"1d33fd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Les membres passent de v\u00eatements de tous les jours \u00e0 des v\u00eatements blancs\ndans le temple, symboles de la puret\u00e9 et de notre \u00e9galit\u00e9 devant Dieu.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-443754b elementor-widget elementor-widget-spacer\" data-id=\"443754b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0418539 elementor-widget elementor-widget-heading\" data-id=\"0418539\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4. Chambre des mari\u00e9es<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f23cbe5 elementor-widget elementor-widget-video\" data-id=\"f23cbe5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/QzcnTAR0hg0&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3d375f elementor-widget elementor-widget-text-editor\" data-id=\"b3d375f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Il n\u2019y a pas de c\u00e9r\u00e9monies effectu\u00e9es dans cette salle. Ici, une mari\u00e9e se\npr\u00e9pare pour sa c\u00e9r\u00e9monie de mariage.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69ca09a elementor-widget elementor-widget-spacer\" data-id=\"69ca09a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54b2548 elementor-widget elementor-widget-heading\" data-id=\"54b2548\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5. Salle d&#039;instructions<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07b21f0 elementor-widget elementor-widget-video\" data-id=\"07b21f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/gBhEPTxKFAs&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1357494 elementor-widget elementor-widget-text-editor\" data-id=\"1357494\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Les membres viennent \u00e0 la salle d\u2019instruction pour en apprendre davantage\nsur la mission de J\u00e9sus-Christ et le plan de Dieu pour nous.<\/p><p>\u2022 Gr\u00e2ce \u00e0 une pr\u00e9sentation audiovisuelle, nous apprenons d&#039;o\u00f9 nous venons, pourquoi nous sommes ici et o\u00f9 nous allons apr\u00e8s notre mort.<\/p><p>\u2022 Dans le cadre de l&#039;instruction, les membres font des promesses, appel\u00e9es alliances, de suivre Dieu et de garder ses commandements.<\/p><p>\u2022 Les autels du temple, comme celui de cette salle, nous rappellent\nJ\u00e9sus-Christ et son sacrifice pour nous.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c48c450 elementor-widget elementor-widget-spacer\" data-id=\"c48c450\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0fae16 elementor-widget elementor-widget-heading\" data-id=\"f0fae16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">6. Celestial Room\u200b<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c4e6bc elementor-widget elementor-widget-video\" data-id=\"6c4e6bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/KwNztlLYBCA&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69c5a9c elementor-widget elementor-widget-text-editor\" data-id=\"69c5a9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 La salle c\u00e9leste est l\u2019un des endroits les plus sacr\u00e9s de la terre et symbolise le\nciel ou le fait d\u2019\u00eatre en pr\u00e9sence de Dieu.<\/p><p>\u2022 La salle c\u00e9leste est un lieu de contemplation tranquille et de pri\u00e8re o\u00f9 nous\npouvons nous sentir proches de Dieu et communier avec lui.<\/p><p>\u2022 Il n\u2019y a pas de c\u00e9r\u00e9monies effectu\u00e9es dans cette salle sacr\u00e9e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-890baa6 elementor-widget elementor-widget-spacer\" data-id=\"890baa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64f7238 elementor-widget elementor-widget-heading\" data-id=\"64f7238\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">7. Sealing Room\u200b<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d95a75 elementor-widget elementor-widget-video\" data-id=\"5d95a75\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/-bhBw5hyjBI&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55e3778 elementor-widget elementor-widget-text-editor\" data-id=\"55e3778\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 La salle de scellement est l\u2019endroit o\u00f9 les mariages ou les scellements sont\neffectu\u00e9s.<\/p><p>\u2022 Un couple s\u2019agenouille sur un autel et est scell\u00e9 par une alliance de mariage\nafin que leur mariage puisse durer au-del\u00e0 de cette vie et dans l\u2019\u00e9ternit\u00e9.\nLes enfants peuvent \u00e9galement \u00eatre scell\u00e9s \u00e0 leurs parents.<\/p><p>\u2022 L\u2019autorit\u00e9 de sceller ou de lier les familles ensemble pour toujours a \u00e9t\u00e9\ndonn\u00e9e \u00e0 l\u2019ap\u00f4tre Pierre, comme mentionn\u00e9 dans le Nouveau Testament\n(Matthieu 16:19).<\/p><p>\u2022 Comme pour les autres c\u00e9r\u00e9monies du temple, ces ordonnances sont\n\u00e9galement accomplies pour nos anc\u00eatres d\u00e9c\u00e9d\u00e9s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-739a740 elementor-widget elementor-widget-heading\" data-id=\"739a740\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Virtual Tour (CC)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-138f3ed elementor-widget elementor-widget-text-editor\" data-id=\"138f3ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Apprenez-en davantage sur ce qui se passe dans le temple lors d&#039;une visite virtuelle du temple de Washington DC avec fr\u00e8re et s\u0153ur Stevenson et fr\u00e8re et s\u0153ur Renlund.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af7eebd elementor-widget elementor-widget-video\" data-id=\"af7eebd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=mUYF1TX5RxM&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d64e960 elementor-widget elementor-widget-spacer\" data-id=\"d64e960\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-161fbbf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"161fbbf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c76692f\" data-id=\"c76692f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89567dd elementor-widget elementor-widget-spacer\" data-id=\"89567dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee2bb05 elementor-widget elementor-widget-heading\" data-id=\"ee2bb05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">To Learn about our Washington D.C. ASL Congregation<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e3fd39 elementor-widget elementor-widget-text-editor\" data-id=\"9e3fd39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\">Visitez notre\u00a0<a href=\"https:\/\/www.facebook.com\/FollowersofJesusChristinDC.ASL\">Facebook page<\/a>\u00a0or email\u00a0<a href=\"mailto:info@dctemple.org\">info@dctemple.org\u00a0<\/a>with the subject &#8220;ASL Congregation&#8221;<\/span><\/p><p>\u00a0<\/p><p><span style=\"color: #ffffff;\">En savoir plus sur le temple de Washington DC\u00a0:<\/span> <a href=\"http:\/\/dctemple.org\/fr\/about\/\">dcttemple.org\/about<\/a><\/p><p><span style=\"color: #ffffff;\">En savoir plus sur ce qui se passe \u00e0 l&#039;int\u00e9rieur des temples<\/span> <a href=\"https:\/\/www.churchofjesuschrist.org\/comeuntochrist\/article\/what-happens-inside-latter-day-saint-temples\">ici<\/a><\/p><p><a href=\"https:\/\/clickly.org\/e0s88\">www.churchofjesuschrist.org\/?lang=fra<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b450c4 elementor-widget elementor-widget-spacer\" data-id=\"0b450c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Language: \u00a0ASL\u00a0 |\u00a0 Chinese\u00a0 |\u00a0 English\u00a0 |\u00a0\u00a0\u00a0French\u00a0\u00a0|\u00a0\u00a0\u00a0German\u00a0\u00a0|\u00a0\u00a0\u00a0Japanese\u00a0\u00a0|\u00a0\u00a0\u00a0Korean\u00a0\u00a0|\u00a0\u00a0\u00a0Persian |\u00a0 \u00a0Portuguese Brazilian |\u00a0\u00a0\u00a0Spanish\u00a0\u00a0|\u00a0\u00a0\u00a0Tagalog THE HOUSE OF THE LORD Washington D.C. Temple\u200b THE CHURCH OF JESUS CHRIST OF LATTER-DAY SAINTS American Sign Language Self-Guided Tour Introduction https:\/\/youtu.be\/sbdQ4hoZlQA As members of The Church of Jesus Christ of Latter-day Saints, we worship God and His Son, Jesus Christ. We come [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-4260","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ASL Tour - DCTemple.org<\/title>\n<meta name=\"description\" content=\"With ASL translations available, tour different rooms in the Washington D.C. Temple of The Church of Jesus Christ of Latter-day Saints today.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/fr\/asl-tour\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASL Tour - DCTemple.org\" \/>\n<meta property=\"og:description\" content=\"With ASL translations available, tour different rooms in the Washington D.C. Temple of The Church of Jesus Christ of Latter-day Saints today.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/fr\/asl-tour\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-19T17:16:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/asl-tour\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/asl-tour\\\/\",\"name\":\"ASL Tour - DCTemple.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"datePublished\":\"2022-04-14T22:56:55+00:00\",\"dateModified\":\"2024-07-19T17:16:18+00:00\",\"description\":\"With ASL translations available, tour different rooms in the Washington D.C. Temple of The Church of Jesus Christ of Latter-day Saints today.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/asl-tour\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/asl-tour\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/asl-tour\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASL Tour\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASL Tour - DCTemple.org","description":"With ASL translations available, tour different rooms in the Washington D.C. Temple of The Church of Jesus Christ of Latter-day Saints today.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/fr\/asl-tour\/","og_locale":"fr_FR","og_type":"article","og_title":"ASL Tour - DCTemple.org","og_description":"With ASL translations available, tour different rooms in the Washington D.C. Temple of The Church of Jesus Christ of Latter-day Saints today.","og_url":"https:\/\/dctemple.org\/fr\/asl-tour\/","og_site_name":"DCTemple.org","article_modified_time":"2024-07-19T17:16:18+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/asl-tour\/","url":"https:\/\/dctemple.org\/asl-tour\/","name":"ASL Tour - DCTemple.org","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"datePublished":"2022-04-14T22:56:55+00:00","dateModified":"2024-07-19T17:16:18+00:00","description":"With ASL translations available, tour different rooms in the Washington D.C. Temple of The Church of Jesus Christ of Latter-day Saints today.","breadcrumb":{"@id":"https:\/\/dctemple.org\/asl-tour\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/asl-tour\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/asl-tour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"ASL Tour"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/4260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/comments?post=4260"}],"version-history":[{"count":0,"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/pages\/4260\/revisions"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/fr\/wp-json\/wp\/v2\/media?parent=4260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}]