[{"id":9563,"date":"2025-09-18T17:50:32","date_gmt":"2025-09-18T21:50:32","guid":{"rendered":"https:\/\/dctemple.org\/?page_id=9563"},"modified":"2025-09-18T17:52:53","modified_gmt":"2025-09-18T21:52:53","slug":"email-subscription-confirmation","status":"publish","type":"page","link":"https:\/\/dctemple.org\/de\/email-subscription-confirmation\/","title":{"rendered":"Email subscription confirmation"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"9563\" class=\"elementor elementor-9563\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1bd0b56 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1bd0b56\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0a0e97f\" data-id=\"0a0e97f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f34700e elementor-widget elementor-widget-heading\" data-id=\"f34700e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Thank you for Subscribing!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d1e7a8 elementor-widget elementor-widget-text-editor\" data-id=\"3d1e7a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>You\u2019re now subscribed to the DC Temple Visitors&#8217; Center Newsletter. We\u2019re excited to have you join our community.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Thank you for Subscribing! You\u2019re now subscribed to the DC Temple Visitors&#8217; Center Newsletter. We\u2019re excited to have you join our community.<\/p>","protected":false},"author":29,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"footnotes":""},"class_list":["post-9563","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Email subscription confirmation - DCTemple.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/de\/email-subscription-confirmation\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Email subscription confirmation - DCTemple.org\" \/>\n<meta property=\"og:description\" content=\"Thank you for Subscribing! You\u2019re now subscribed to the DC Temple Visitors&#8217; Center Newsletter. We\u2019re excited to have you join our community.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/de\/email-subscription-confirmation\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-18T21:52:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/email-subscription-confirmation\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/email-subscription-confirmation\\\/\",\"name\":\"Email subscription confirmation - DCTemple.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"datePublished\":\"2025-09-18T21:50:32+00:00\",\"dateModified\":\"2025-09-18T21:52:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/email-subscription-confirmation\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/email-subscription-confirmation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/email-subscription-confirmation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Email subscription confirmation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Email subscription confirmation - DCTemple.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/de\/email-subscription-confirmation\/","og_locale":"de_DE","og_type":"article","og_title":"Email subscription confirmation - DCTemple.org","og_description":"Thank you for Subscribing! You\u2019re now subscribed to the DC Temple Visitors&#8217; Center Newsletter. We\u2019re excited to have you join our community.","og_url":"https:\/\/dctemple.org\/de\/email-subscription-confirmation\/","og_site_name":"DCTemple.org","article_modified_time":"2025-09-18T21:52:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/email-subscription-confirmation\/","url":"https:\/\/dctemple.org\/email-subscription-confirmation\/","name":"Email subscription confirmation - DCTemple.org","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"datePublished":"2025-09-18T21:50:32+00:00","dateModified":"2025-09-18T21:52:53+00:00","breadcrumb":{"@id":"https:\/\/dctemple.org\/email-subscription-confirmation\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/email-subscription-confirmation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/email-subscription-confirmation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"Email subscription confirmation"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/9563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/comments?post=9563"}],"version-history":[{"count":0,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/9563\/revisions"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/media?parent=9563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":9557,"date":"2025-08-28T17:31:32","date_gmt":"2025-08-28T21:31:32","guid":{"rendered":"https:\/\/dctemple.org\/?page_id=9557"},"modified":"2026-01-07T11:28:32","modified_gmt":"2026-01-07T16:28:32","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/dctemple.org\/de\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"9557\" class=\"elementor elementor-9557\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94d740b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"94d740b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60b1103\" data-id=\"60b1103\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fbf752 elementor-widget elementor-widget-text-editor\" data-id=\"1fbf752\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h1 class=\"wp-block-heading\" data-start=\"152\" data-end=\"168\">Privacy Policy<\/h1><p data-start=\"170\" data-end=\"203\"><strong data-start=\"170\" data-end=\"189\">Effective Date:<\/strong>\u00a08\/28\/2025<\/p><p data-start=\"354\" data-end=\"637\">The Goforth Foundation (\u201cwe,\u201d \u201cour,\u201d or \u201cus\u201d) operates a number of websites designed to provide community resources, news and updates, and information about visiting and participating in events.<br data-start=\"548\" data-end=\"551\" \/>We are committed to protecting your privacy and handling your information responsibly.<\/p><hr data-start=\"639\" data-end=\"642\" \/><h2 data-start=\"644\" data-end=\"672\">1. Information We Collect<\/h2><p data-start=\"674\" data-end=\"720\">We collect the following types of information:<\/p><p data-start=\"722\" data-end=\"781\"><strong data-start=\"722\" data-end=\"767\">Personal Information you provide directly<\/strong>, including:<\/p><ul data-start=\"782\" data-end=\"1006\"><li data-start=\"782\" data-end=\"850\"><p data-start=\"784\" data-end=\"850\">Contact information (such as name, email address, phone number).<\/p><\/li><li data-start=\"851\" data-end=\"925\"><p data-start=\"853\" data-end=\"925\">Reservation or ticketing information (such as tour or event bookings).<\/p><\/li><li data-start=\"926\" data-end=\"960\"><p data-start=\"928\" data-end=\"960\">Survey responses and feedback.<\/p><\/li><li data-start=\"961\" data-end=\"1006\"><p data-start=\"963\" data-end=\"1006\">Email subscriptions and form submissions.<\/p><\/li><\/ul><p data-start=\"1008\" data-end=\"1061\"><strong data-start=\"1008\" data-end=\"1047\">Automatically collected information<\/strong>, including:<\/p><ul data-start=\"1062\" data-end=\"1274\"><li data-start=\"1062\" data-end=\"1115\"><p data-start=\"1064\" data-end=\"1115\">IP address, browser type, and device information.<\/p><\/li><li data-start=\"1116\" data-end=\"1184\"><p data-start=\"1118\" data-end=\"1184\">Website usage data (pages visited, time spent, referral source).<\/p><\/li><li data-start=\"1185\" data-end=\"1274\"><p data-start=\"1187\" data-end=\"1274\">Cookies and similar technologies (to improve site functionality and user experience).<\/p><\/li><\/ul><hr data-start=\"1276\" data-end=\"1279\" \/><h2 data-start=\"1281\" data-end=\"1314\">2. How We Use Your Information<\/h2><p data-start=\"1316\" data-end=\"1355\">We use the information we collect to:<\/p><ul data-start=\"1356\" data-end=\"1653\"><li data-start=\"1356\" data-end=\"1415\"><p data-start=\"1358\" data-end=\"1415\">Provide, manage, and improve our websites and services.<\/p><\/li><li data-start=\"1416\" data-end=\"1500\"><p data-start=\"1418\" data-end=\"1500\">Communicate with you, including sending confirmations, updates, and newsletters.<\/p><\/li><li data-start=\"1501\" data-end=\"1560\"><p data-start=\"1503\" data-end=\"1560\">Understand usage trends and improve visitor experience.<\/p><\/li><li data-start=\"1561\" data-end=\"1618\"><p data-start=\"1563\" data-end=\"1618\">Respond to questions, feedback, and survey responses.<\/p><\/li><li data-start=\"1619\" data-end=\"1653\"><p data-start=\"1621\" data-end=\"1653\">Comply with legal obligations.<\/p><\/li><\/ul><p data-start=\"1655\" data-end=\"1725\">We do\u00a0<strong data-start=\"1661\" data-end=\"1707\">not sell or rent your personal information<\/strong>\u00a0to third parties.<\/p><hr data-start=\"1727\" data-end=\"1730\" \/><h2 data-start=\"1732\" data-end=\"1760\">3. Sharing of Information<\/h2><p data-start=\"1762\" data-end=\"1790\">We only share information:<\/p><ul data-start=\"1791\" data-end=\"2021\"><li data-start=\"1791\" data-end=\"1907\"><p data-start=\"1793\" data-end=\"1907\">With trusted service providers who help us operate our websites (such as ticketing, email, or survey platforms).<\/p><\/li><li data-start=\"1908\" data-end=\"1961\"><p data-start=\"1910\" data-end=\"1961\">If required by law, regulation, or legal process.<\/p><\/li><li data-start=\"1962\" data-end=\"2021\"><p data-start=\"1964\" data-end=\"2021\">To protect our rights, safety, or the safety of others.<\/p><\/li><\/ul><p data-start=\"2023\" data-end=\"2077\">We do not share personal information with advertisers.<\/p><hr data-start=\"2079\" data-end=\"2082\" \/><h2 data-start=\"2084\" data-end=\"2109\">4. Your Privacy Rights<\/h2><p data-start=\"2111\" data-end=\"2170\">Depending on where you live, you may have certain rights:<\/p><ul data-start=\"2172\" data-end=\"2610\"><li data-start=\"2172\" data-end=\"2412\"><p data-start=\"2174\" data-end=\"2412\"><strong data-start=\"2174\" data-end=\"2211\">California Residents (CCPA\/CPRA):<\/strong>\u00a0You have the right to know what personal information we collect, request deletion, opt-out of sale\/sharing of data (we do not sell personal data), and non-discrimination for exercising these rights.<\/p><\/li><li data-start=\"2413\" data-end=\"2610\"><p data-start=\"2415\" data-end=\"2610\"><strong data-start=\"2415\" data-end=\"2441\">European Union (GDPR):<\/strong>\u00a0You have the right to access, correct, delete, restrict processing, and request portability of your personal data. You may also object to processing in certain cases.<\/p><\/li><\/ul><p data-start=\"2612\" data-end=\"2692\">To exercise your rights, please contact us at:\u00a0<strong data-start=\"2659\" data-end=\"2692\"><a class=\"decorated-link cursor-pointer\" rel=\"noopener\" data-start=\"2661\" data-end=\"2690\">privacy@goforthfoundation.org<\/a><\/strong><\/p><hr data-start=\"2694\" data-end=\"2697\" \/><h2 data-start=\"2699\" data-end=\"2718\">5. Data Security<\/h2><p data-start=\"2720\" data-end=\"2941\">We use reasonable technical and organizational safeguards to protect your information against unauthorized access, disclosure, or misuse. However, no system is completely secure, and we cannot guarantee absolute security.<\/p><hr data-start=\"2943\" data-end=\"2946\" \/><h2 data-start=\"2948\" data-end=\"2968\">6. Data Retention<\/h2><p data-start=\"2970\" data-end=\"3116\">We keep your personal information only as long as necessary for the purposes described above, unless a longer retention period is required by law.<\/p><hr data-start=\"3118\" data-end=\"3121\" \/><h2 data-start=\"3123\" data-end=\"3147\">7. Children\u2019s Privacy<\/h2><p data-start=\"3149\" data-end=\"3339\">Our websites are not directed to children under 16. We do not knowingly collect personal information from children. If we learn that we have done so, we will delete the information promptly.<\/p><hr data-start=\"3341\" data-end=\"3344\" \/><h2 data-start=\"3346\" data-end=\"3371\">8. International Users<\/h2><p data-start=\"3373\" data-end=\"3550\">If you are accessing our sites from outside the United States, your information may be transferred and processed in the U.S. By using our websites, you consent to this transfer.<\/p><hr data-start=\"3552\" data-end=\"3555\" \/><h2 data-start=\"3557\" data-end=\"3580\">9. Third-Party Links<\/h2><p data-start=\"3582\" data-end=\"3696\">Our websites may contain links to other websites. We are not responsible for the privacy practices of those sites.<\/p><hr data-start=\"3698\" data-end=\"3701\" \/><h2 data-start=\"3703\" data-end=\"3732\">10. Changes to This Policy<\/h2><p data-start=\"3734\" data-end=\"3901\">We may update this Privacy Policy from time to time. Updates will be posted on this page with a revised effective date. We encourage you to review this page regularly.<\/p><hr data-start=\"3903\" data-end=\"3906\" \/><h2 data-start=\"3908\" data-end=\"3925\">11. Contact Us<\/h2><p data-start=\"3927\" data-end=\"4016\">If you have any questions about this Privacy Policy or your data, please contact us at:<\/p><p data-start=\"4018\" data-end=\"4132\"><strong data-start=\"4018\" data-end=\"4028\">Email:<\/strong>\u00a0<a class=\"decorated-link cursor-pointer\" rel=\"noopener\" data-start=\"4029\" data-end=\"4058\">privacy@goforthfoundation.org<\/a><br data-start=\"4058\" data-end=\"4061\" \/><strong data-start=\"4061\" data-end=\"4073\">Address:<\/strong>\u00a0GoForth Foundation, 6 W Main St, American Fork, UT 84003<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Privacy Policy Effective Date:\u00a08\/28\/2025 The Goforth Foundation (\u201cwe,\u201d \u201cour,\u201d or \u201cus\u201d) operates a number of websites designed to provide community resources, news and updates, and information about visiting and participating in events.We are committed to protecting your privacy and handling your information responsibly. 1. Information We Collect We collect the following types of information: Personal [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"footnotes":""},"class_list":["post-9557","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Policy - DCTemple.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/de\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - DCTemple.org\" \/>\n<meta property=\"og:description\" content=\"Privacy Policy Effective Date:\u00a08\/28\/2025 The Goforth Foundation (\u201cwe,\u201d \u201cour,\u201d or \u201cus\u201d) operates a number of websites designed to provide community resources, news and updates, and information about visiting and participating in events.We are committed to protecting your privacy and handling your information responsibly. 1. Information We Collect We collect the following types of information: Personal [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/de\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-07T16:28:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/privacy-policy\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/privacy-policy\\\/\",\"name\":\"Privacy Policy - DCTemple.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"datePublished\":\"2025-08-28T21:31:32+00:00\",\"dateModified\":\"2026-01-07T16:28:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/privacy-policy\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/privacy-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/privacy-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy Policy - DCTemple.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/de\/privacy-policy\/","og_locale":"de_DE","og_type":"article","og_title":"Privacy Policy - DCTemple.org","og_description":"Privacy Policy Effective Date:\u00a08\/28\/2025 The Goforth Foundation (\u201cwe,\u201d \u201cour,\u201d or \u201cus\u201d) operates a number of websites designed to provide community resources, news and updates, and information about visiting and participating in events.We are committed to protecting your privacy and handling your information responsibly. 1. Information We Collect We collect the following types of information: Personal [&hellip;]","og_url":"https:\/\/dctemple.org\/de\/privacy-policy\/","og_site_name":"DCTemple.org","article_modified_time":"2026-01-07T16:28:32+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/privacy-policy\/","url":"https:\/\/dctemple.org\/privacy-policy\/","name":"Privacy Policy - DCTemple.org","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"datePublished":"2025-08-28T21:31:32+00:00","dateModified":"2026-01-07T16:28:32+00:00","breadcrumb":{"@id":"https:\/\/dctemple.org\/privacy-policy\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/9557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/comments?post=9557"}],"version-history":[{"count":0,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/9557\/revisions"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/media?parent=9557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":6661,"date":"2022-11-03T16:55:24","date_gmt":"2022-11-03T20:55:24","guid":{"rendered":"http:\/\/dctemple.org\/?page_id=6661"},"modified":"2025-11-06T11:16:43","modified_gmt":"2025-11-06T16:16:43","slug":"festival-of-lights","status":"publish","type":"page","link":"https:\/\/dctemple.org\/de\/festival-of-lights\/","title":{"rendered":"Lichterfest"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6661\" class=\"elementor elementor-6661\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83742de elementor-section-full_width elementor-section-stretched elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"83742de\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b4d5de9\" data-id=\"b4d5de9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ef21c52 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ef21c52\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a4bd870\" data-id=\"a4bd870\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13ad12b elementor-widget elementor-widget-heading\" data-id=\"13ad12b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Washington DC Temple Festival of Lights 2025<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df26a41 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"df26a41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ab0959 elementor-widget elementor-widget-text-editor\" data-id=\"7ab0959\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>The Festival of Lights at the Washington DC Temple features over 500,000 lights and beautifully decorated Christmas Trees. The Visitors&#8217; Center exhibits beautiful Cr\u00e9che displays featuring nativities from around the world and hosts daily holiday performances that are free and open to the public.<\/p><h3>Parking passes are now required. For details about the 2025 Festival of Lights, including the performance schedule and how to reserve a mandatory parking pass, please visit <a href=\"https:\/\/dctemplevisitorscenter.org\/festival-of-lights\/\">DCTempleVisitorsCenter.org.<\/a>\u00a0<\/h3><p><i>M\u00f6ge das Festival of Lights den Geist der Weihnacht in Ihr Herz bringen!<\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ebc560 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"4ebc560\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tKommen Sie und sehen Sie sich das Festival of Lights im Washington DC Temple an. Genie\u00dfen Sie \u00fcber 400.000 Lichter und wundersch\u00f6n geschm\u00fcckte Weihnachtsb\u00e4ume. Das Besucherzentrum ist t\u00e4glich von 10:00 bis 21:00 Uhr ge\u00f6ffnet, damit Sie wundersch\u00f6ne Krippenausstellungen mit Krippen aus aller Welt sehen, eine der vielen Auff\u00fchrungen besuchen und der Gemeinschaft bei den Light the World Giving Machines etwas zur\u00fcckgeben k\u00f6nnen. Parken und Auff\u00fchrungen sind kostenlos, f\u00fcr Auff\u00fchrungen sind jedoch Eintrittskarten erforderlich. Scrollen Sie nach unten oder klicken Sie auf eine der Schaltfl\u00e4chen, um weitere Informationen zu erhalten.\n\n<i>M\u00f6ge das Festival of Lights den Geist der Weihnacht in Ihr Herz bringen!<\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b8b5343 elementor-section-content-space-evenly elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b8b5343\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-fcf525f\" data-id=\"fcf525f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3aaad7a elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"3aaad7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#performances\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Auff\u00fchrungen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7aec92f\" data-id=\"7aec92f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8e2d22 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"a8e2d22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#nativities\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Krippendisplays<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3f6c35e\" data-id=\"3f6c35e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a62e971 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"a62e971\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#christmasparking\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Parkinfo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3994678\" data-id=\"3994678\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f68d75 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"5f68d75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#folfaq\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">H\u00e4ufig gestellte Fragen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e5eb52 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e5eb52\" data-element_type=\"section\" data-e-type=\"section\" id=\"performances\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56c7d2e\" data-id=\"56c7d2e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4eb0cc4 elementor-widget elementor-widget-heading\" data-id=\"4eb0cc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Auff\u00fchrungen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba3af86 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ba3af86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90d6a2c elementor-widget elementor-widget-text-editor\" data-id=\"90d6a2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Leider sind wir am Ende unserer Auftritte angelangt. Das Festival of Lights dauert noch bis zum 2. Januar an. Kommen Sie und sehen Sie sich die Krippenausstellungen, die Weihnachtsb\u00e4ume, die Light the World Giving Machines und nat\u00fcrlich die schillernden Lichter an. Das Parken ist kostenlos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dd18078 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dd18078\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b0eb717\" data-id=\"b0eb717\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-029a2b1\" data-id=\"029a2b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30f6776 elementor-widget elementor-widget-text-editor\" data-id=\"30f6776\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>1. Dezember \u2013 2. Januar<\/b><\/p>\n<p style=\"text-align: center;\">Abendd\u00e4mmerung \u2013 21:00 Uhr \u2013 Weihnachtsbeleuchtung f\u00fcr die \u00d6ffentlichkeit zug\u00e4nglich<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2c31a18\" data-id=\"2c31a18\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e37ffc elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0e37ffc\" data-element_type=\"section\" data-e-type=\"section\" id=\"nativities\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c016633\" data-id=\"c016633\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a19864d elementor-widget elementor-widget-heading\" data-id=\"a19864d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Krippendisplays<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b8b3e4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3b8b3e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-154b803 elementor-widget elementor-widget-text-editor\" data-id=\"154b803\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDas franz\u00f6sische Wort Cr\u00e8che wird verwendet, um eine unverwechselbare Krippe zu beschreiben, die w\u00e4hrend der Weihnachtszeit gezeigt wird. Diese Szenen, die die Geburt Jesu Christi darstellen, wurden ab dem 13. Jahrhundert in Gemeinden in der ganzen christlichen Welt popul\u00e4r. Diese Ausstellung zeigt 87 Kinderkrippen aus 64 L\u00e4ndern.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-400c801 elementor-widget elementor-widget-image\" data-id=\"400c801\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-scaled.webp\" class=\"attachment-full size-full wp-image-7022\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-scaled.webp 1920w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-300x225.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-1024x768.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-768x576.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-1536x1152.webp 1536w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-16x12.webp 16w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bbbb7ca elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bbbb7ca\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6681e0d\" data-id=\"6681e0d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10c9958 elementor-widget elementor-widget-spacer\" data-id=\"10c9958\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d29cad elementor-widget elementor-widget-heading\" data-id=\"4d29cad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Erhalten Sie Updates zum Festival of Lights<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76e0bcb elementor-widget elementor-widget-html\" data-id=\"76e0bcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<script type=\"text\/javascript\" src=\"https:\/\/mautic.goforthfoundation.org\/form\/generate.js?id=3\"><\/script>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94b199c elementor-widget elementor-widget-spacer\" data-id=\"94b199c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e15408 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e15408\" data-element_type=\"section\" data-e-type=\"section\" id=\"christmasparking\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8e1fe31\" data-id=\"8e1fe31\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-92a8797 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92a8797\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5b96bed\" data-id=\"5b96bed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-126b531 elementor-widget elementor-widget-heading\" data-id=\"126b531\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Parkinformationen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9774e9f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9774e9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c1a0e7 elementor-widget elementor-widget-text-editor\" data-id=\"1c1a0e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Parkplatz, um das Festival of Lights und das Besucherzentrum zu sehen <strong>frei<\/strong> und <strong>es wird kein Parkausweis ben\u00f6tigt.<\/strong><\/p>\n\n<p>Drei Parkpl\u00e4tze stehen zur Verf\u00fcgung, alle in Gehweite der Displays. Nach Einbruch der Dunkelheit gibt es an jedem Eingang einen Parkw\u00e4chter, der Sie zu den verf\u00fcgbaren Parkpl\u00e4tzen f\u00fchrt.<\/p>\n\n<p>Besucherzentrum \u2013 9900 Stoneybrook Dr.<\/p>\n\n<p>Tempel \u2013 9900 Stoneybrook Dr.<\/p>\n\n<p>Pfahlzentrum (\u00dcberlauf) \u2013 10000 Stoneybrook Dr.<\/p>\n\n<p>Wenn Sie auf Stoneybrook nach Norden fahren, ist der erste Eingang links das Besucherzentrum, der zweite der Tempel und der dritte das Pfahlzentrum.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d5dd461\" data-id=\"d5dd461\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf9b6c6 elementor-widget elementor-widget-google_maps\" data-id=\"bf9b6c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Washington%20DC%20Temple%20Visitors%27%20Center%2C%20Kensington%2C%20MD&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Washington DC Temple Visitors&#039; Center, Kensington, MD\"\n\t\t\t\t\taria-label=\"Washington DC Temple Visitors&#039; Center, Kensington, MD\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd31676 elementor-widget elementor-widget-spacer\" data-id=\"dd31676\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ea1022 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ea1022\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-16f8415\" data-id=\"16f8415\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35b6027 elementor-widget elementor-widget-heading\" data-id=\"35b6027\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Hat Ihnen Ihr Besuch gefallen?<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ce639bc elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ce639bc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d63f61c\" data-id=\"d63f61c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fb0e01 elementor-widget elementor-widget-html\" data-id=\"4fb0e01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<div style=\"text-align:center\">\r\n<a href=\"\/de\/feedback\/review\/\"><div style=\"width: 32%; float: left;\"><i class=\"fas fa-smile-beam\" style=\"font-size: 70px; color: #FFD084;\"><\/i><p style=\"font-size: 15px;\">Liebte es!<\/p><\/div><\/a>\r\n<a href=\"\/de\/feedback\/good-feedback\/\"><div style=\"width: 32%; float: left;\"><i class=\"fas fa-smile\" style=\"font-size: 70px; color: #8A926F;\"><\/i><p style=\"font-size: 15px;\">Es war gut.<\/p><\/div><\/a>\r\n<a href=\"\/de\/feedback\/negative-feedback\/\"><div style=\"width: 32%; float: left;\"><i class=\"fas fa-frown\" style=\"font-size: 70px; color: #244480b0;\"><\/i><p style=\"font-size: 15px;\">Hat mir keinen Spa\u00df gemacht.<\/p><\/div><\/a>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7518f69 elementor-widget elementor-widget-spacer\" data-id=\"7518f69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4013575 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4013575\" data-element_type=\"section\" data-e-type=\"section\" id=\"folfaq\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d6d42ae\" data-id=\"d6d42ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77251fc elementor-widget elementor-widget-spacer\" data-id=\"77251fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99e93a1 elementor-widget elementor-widget-heading\" data-id=\"99e93a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">H\u00e4ufig gestellte Fragen zum Lichterfest<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d952d72 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d952d72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f30f6d6 elementor-widget elementor-widget-toggle\" data-id=\"f30f6d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2541\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2541\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Sind die Festival of Lights-Veranstaltungen kostenlos?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2541\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2541\">Alle Veranstaltungen und Vorf\u00fchrungen des Festival of Lights im Washington DC Temple sind kostenlos. F\u00fcr die Vorstellungen ist eine Vorreservierung von Freikarten erforderlich. Karteninhaber werden gebeten, sp\u00e4testens 15 Minuten vor Vorstellungsbeginn an ihren Pl\u00e4tzen zu sein. Nach dieser Zeit wird die Warteschleife zugelassen, um alle verbleibenden Pl\u00e4tze zu besetzen.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2542\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2542\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ben\u00f6tige ich ein Ticket und gibt es Standby-Sitzpl\u00e4tze?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2542\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2542\">F\u00fcr alle Vorstellungen ist eine Eintrittskarte erforderlich. Wir empfehlen Ihnen, Karten im Voraus zu reservieren, um sicherzustellen, dass Sie Sitzpl\u00e4tze haben. Wenn Sie jedoch kein Ticket haben, kommen Sie fr\u00fch und stellen Sie sich in die Warteschleife links vom Haupteingang. Ticketinhaber werden zuerst eingelassen. Sie werden gebeten, 15 Minuten vor der Vorstellung auf ihren Pl\u00e4tzen zu sein. Etwa 10 bis 15 Minuten vor Vorstellungsbeginn verfallen die Tickets, sodass diejenigen in der Warteschleife auf allen verbleibenden Pl\u00e4tzen Platz nehmen k\u00f6nnen.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2543\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2543\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ich bin kein Mitglied Ihrer Kirche, kann ich trotzdem kommen?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2543\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2543\"><p>Unbedingt! Zu unseren Veranstaltungen und Gottesdiensten sind alle herzlich willkommen (<a href=\"https:\/\/dctemple.org\/de\/sunday-service\/\">erfahren Sie mehr \u00fcber unsere Gottesdienste<\/a>). Wir bitten nur darum, dass sich alle Teilnehmer anst\u00e4ndig kleiden, eine saubere Sprache verwenden und jeden mit Respekt behandeln. Wir sind Christen, die unser Bestes tun, um die Gebote und Lehren Christi zu befolgen. Unabh\u00e4ngig von Ihrem Hintergrund sind Sie eingeladen, sich uns anzuschlie\u00dfen!<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2544\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2544\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Was soll ich anziehen?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2544\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2544\"><p>Das Kleid h\u00e4ngt von der Art der Veranstaltung ab. Business Casual ist eine gute Faustregel f\u00fcr Veranstaltungen im Auditorium. Sie k\u00f6nnen gerne jede bescheidene Kleidung tragen, in der Sie sich wohlf\u00fchlen. Bei Andachten und Sonntagsgottesdiensten tragen die meisten M\u00e4nner Anz\u00fcge, Sakkos oder Hemden und Krawatten, und Frauen tragen Kleider oder R\u00f6cke. Kinder verkleiden sich normalerweise auch.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2545\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2545\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Kann ich meine Kinder mitbringen?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2545\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2545\"><p>Alle Veranstaltungen des Festival of Lights sind familienfreundlich und Kinder sind willkommen! Aus Respekt vor den Darstellern und anderen Zuschauern empfehlen wir jedoch, dass die anwesenden Kinder alt genug sind, um w\u00e4hrend der gesamten Auff\u00fchrung sitzen und aufmerksam zu bleiben, und dass st\u00f6rende Kinder in der Lobby beruhigt werden.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2546\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2546\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wie kann ich Updates zu den Festival of Lights-Events erhalten?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2546\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2546\"><p>Ticketinhaber f\u00fcr eine bestimmte Veranstaltung erhalten automatisch wichtige E-Mail-Updates zu dieser Veranstaltung und weitere hilfreiche Informationen finden Sie in den einzelnen Veranstaltungslisten auf dctemple.org. Wir empfehlen auch, dem Washington DC Temple Visitors&#039; Center zu folgen <a href=\"https:\/\/www.facebook.com\/dctemplevc\">Facebook<\/a> f\u00fcr allgemeine Weihnachtsaktualisierungen und hilfreiche Tipps und Erinnerungen zu bevorstehenden Veranstaltungen, Parken, Kleidung usw. Wir laden Sie auch ein, unsere Website zu abonnieren, um \u00fcber alles, was im Washington DC Temple passiert, auf dem Laufenden zu bleiben.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2547\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2547\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wo kann ich parken?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2547\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2547\"><p>Das Parken, um das Festival of Lights zu sehen, ist kostenlos und es wird kein Pass ben\u00f6tigt. Drei Parkpl\u00e4tze stehen zur Verf\u00fcgung, alle in Gehweite der Displays.\u00a0<span style=\"background-color: var(--nv-site-bg); color: var( --e-global-color-text ); letter-spacing: var(--bodyletterspacing); text-transform: var(--bodytexttransform);\">An jedem Eingang gibt es Parkw\u00e4chter, die Sie zu verf\u00fcgbaren Parkpl\u00e4tzen f\u00fchren.<\/span><\/p><p>Besucherzentrum \u2013 9900 Stoneybrook Dr.<br \/>Tempel \u2013 9900 Stoneybrook Dr.<br \/>Pfahlzentrum\u00a0<span style=\"background-color: var(--nv-site-bg); color: var( --e-global-color-text ); letter-spacing: var(--bodyletterspacing); text-transform: var(--bodytexttransform);\">(\u00dcberlauf)<\/span><span style=\"background-color: var(--nv-site-bg); color: var( --e-global-color-text ); letter-spacing: var(--bodyletterspacing); text-transform: var(--bodytexttransform);\">\u00a0\u2013 10000 Stoneybrook Dr.\u00a0<\/span><\/p><p>(Wenn Sie auf Stoneybrook nach Norden fahren, ist der erste Eingang links das Besucherzentrum, der zweite der Tempel und der dritte das Pfahlzentrum.)<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2548\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-2548\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wie fr\u00fch sollte ich ankommen?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2548\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-2548\"><p>Die Theatert\u00fcren \u00f6ffnen normalerweise etwa 30 Minuten vor Vorstellungsbeginn (manchmal fr\u00fcher), aber die Warteschlange f\u00fcr gro\u00dfe Veranstaltungen beginnt fr\u00fcher. Wir empfehlen, fr\u00fch genug anzureisen, um die Krippenausstellungen und andere saisonale Highlights sowie die regelm\u00e4\u00dfigen Ausstellungen im Besucherzentrum zu genie\u00dfen.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2549\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-2549\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Was ist, wenn ich nicht teilnehmen kann? Kann ich meine Tickets stornieren?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2549\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-2549\"><p>Sie k\u00f6nnen alle kostenlosen Tickets \u00fcber Eventbrite aktualisieren oder stornieren. Wir wissen es zu sch\u00e4tzen, dass Sie dies tun, wenn Sie nicht teilnehmen k\u00f6nnen, damit wir eine genauere Z\u00e4hlung der Teilnehmer haben.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-25410\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-25410\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Darf ich Fotos oder Videos machen?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-25410\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-25410\"><p>Es h\u00e4ngt von der Veranstaltung ab, also \u00fcberpr\u00fcfen Sie die einzelnen Veranstaltungslisten und achten Sie auf Ank\u00fcndigungen, die vor der Auff\u00fchrung gemacht wurden. Besucher werden immer ermutigt, vor und nach der Auff\u00fchrung oder drau\u00dfen auf dem Tempelgel\u00e4nde Fotos und Videos zu machen. Wir w\u00fcrden gerne Ihre Bilder sehen! Stellen Sie sicher, dass Sie uns TAGGEN, @DCTempleVC.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-25411\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-25411\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ich habe weitere Fragen, wie bekomme ich diese beantwortet? <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-25411\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-25411\"><div>Bei weiteren Fragen schreiben Sie uns bitte an <a href=\"mailto:wdcvisitorscenter@gmail.com\" target=\"_blank\" rel=\"noopener\">wdcvisitorscenter@gmail.com<\/a>. Wir werden so schnell wie m\u00f6glich antworten, und zwar innerhalb von 24 Stunden.\u00a0\u00a0<\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ccb94c elementor-widget elementor-widget-spacer\" data-id=\"4ccb94c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3cf05aa elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3cf05aa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61d1196\" data-id=\"61d1196\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23f37a9 elementor-widget elementor-widget-spacer\" data-id=\"23f37a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-509a2a1 elementor-blockquote--skin-quotation elementor-blockquote--align-center elementor-widget elementor-widget-blockquote\" data-id=\"509a2a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\tUnd siehe, ich bin das Licht und das Leben der Welt; und ich habe aus diesem bitteren Kelch getrunken, den der Vater mir gegeben hat, und habe den Vater verherrlicht, indem ich die S\u00fcnden der Welt auf mich genommen habe, in denen ich den Willen des Vaters in allen Dingen von Anfang an gelitten habe.\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">3 Nephi 11:11<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e51b847 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e51b847\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/uqr.to\/1a4j9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Erfahren Sie mehr \u00fcber den Besuch Christi in Amerika<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42770a5 elementor-widget elementor-widget-spacer\" data-id=\"42770a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27f3ba2 elementor-widget elementor-widget-spacer\" data-id=\"27f3ba2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Washington DC Temple Festival of Lights 2025 The Festival of Lights at the Washington DC Temple features over 500,000 lights and beautifully decorated Christmas Trees. The Visitors&#8217; Center exhibits beautiful Cr\u00e9che displays featuring nativities from around the world and hosts daily holiday performances that are free and open to the public. Parking passes are now [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"footnotes":""},"class_list":["post-6661","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festival of Lights - DCTemple.org<\/title>\n<meta name=\"description\" content=\"The Festival of Lights, a yearly tradition at the DC Temple, features musical performances and over 500,000 Christmas lights. All are welcome.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/de\/festival-of-lights\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festival of Lights - DCTemple.org\" \/>\n<meta property=\"og:description\" content=\"The Festival of Lights, a yearly tradition at the DC Temple, features musical performances and over 500,000 Christmas lights. All are welcome.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/de\/festival-of-lights\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T16:16:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/festival-of-lights\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/festival-of-lights\\\/\",\"name\":\"Festival of Lights - DCTemple.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/festival-of-lights\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/festival-of-lights\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Creche-wall-2-scaled.webp\",\"datePublished\":\"2022-11-03T20:55:24+00:00\",\"dateModified\":\"2025-11-06T16:16:43+00:00\",\"description\":\"The Festival of Lights, a yearly tradition at the DC Temple, features musical performances and over 500,000 Christmas lights. All are welcome.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/festival-of-lights\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/festival-of-lights\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/festival-of-lights\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Creche-wall-2-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Creche-wall-2-scaled.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/festival-of-lights\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festival of Lights\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festival of Lights - DCTemple.org","description":"The Festival of Lights, a yearly tradition at the DC Temple, features musical performances and over 500,000 Christmas lights. All are welcome.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/de\/festival-of-lights\/","og_locale":"de_DE","og_type":"article","og_title":"Festival of Lights - DCTemple.org","og_description":"The Festival of Lights, a yearly tradition at the DC Temple, features musical performances and over 500,000 Christmas lights. All are welcome.","og_url":"https:\/\/dctemple.org\/de\/festival-of-lights\/","og_site_name":"DCTemple.org","article_modified_time":"2025-11-06T16:16:43+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-scaled.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"6 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/festival-of-lights\/","url":"https:\/\/dctemple.org\/festival-of-lights\/","name":"Festival of Lights - DCTemple.org","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dctemple.org\/festival-of-lights\/#primaryimage"},"image":{"@id":"https:\/\/dctemple.org\/festival-of-lights\/#primaryimage"},"thumbnailUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-scaled.webp","datePublished":"2022-11-03T20:55:24+00:00","dateModified":"2025-11-06T16:16:43+00:00","description":"The Festival of Lights, a yearly tradition at the DC Temple, features musical performances and over 500,000 Christmas lights. All are welcome.","breadcrumb":{"@id":"https:\/\/dctemple.org\/festival-of-lights\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/festival-of-lights\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dctemple.org\/festival-of-lights\/#primaryimage","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-scaled.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Creche-wall-2-scaled.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/festival-of-lights\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"Festival of Lights"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/6661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/comments?post=6661"}],"version-history":[{"count":0,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/6661\/revisions"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/media?parent=6661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":6337,"date":"2022-08-29T17:13:41","date_gmt":"2022-08-29T21:13:41","guid":{"rendered":"http:\/\/dctemple.org\/?page_id=6337"},"modified":"2026-07-02T10:41:56","modified_gmt":"2026-07-02T14:41:56","slug":"home","status":"publish","type":"page","link":"https:\/\/dctemple.org\/de\/","title":{"rendered":"Heim"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6337\" class=\"elementor elementor-6337\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-128a24e e-con-full e-flex e-con e-parent\" data-id=\"128a24e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5ce8628 e-con-full e-flex e-con e-child\" data-id=\"5ce8628\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0537249 elementor-widget elementor-widget-slider_revolution\" data-id=\"0537249\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"slider_revolution.default\">\n\t\t\t\t\t\n\t\t<div class=\"wp-block-themepunch-revslider\">\n\t\t\t<!-- START Default Home Page Slider REVOLUTION SLIDER 6.5.11 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_11_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_11_1\" style=\"\" data-version=\"6.5.11\">\n\t\t\t\t\t<rs-slides>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-16\" data-title=\"Slide\" data-anim=\"ms:330;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-11-slide-16-layer-4\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:50px;y:50px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:300px;h:180px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" data-lazyload=\"\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-11-slide-16-layer-16\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:2070px;h:900px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"1920\" height=\"835\" data-lazyload=\"\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Temple_oct_2009_fullimage_2.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-17\" data-title=\"Slide\" data-anim=\"ms:310;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-11-slide-17-layer-15\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:2070px;h:900px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"1920\" height=\"835\" data-lazyload=\"\/\/dctemple.org\/wp-content\/uploads\/2022\/09\/1-13.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-31\" data-title=\"Slide\" data-anim=\"ms:320;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-11-slide-31-layer-14\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:2070px;h:898px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"1920\" height=\"833\" data-lazyload=\"\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Christus-2.jpeg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-18\" data-title=\"Slide\" data-anim=\"ms:320;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-11-slide-18-layer-14\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:2070px;h:900px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"1920\" height=\"835\" data-lazyload=\"\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/VC-reflection-4.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-33\" data-title=\"Slide\" data-anim=\"ms:320;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-11-slide-33-layer-14\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:2070px;h:900px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"1920\" height=\"835\" data-lazyload=\"\/\/dctemple.org\/wp-content\/uploads\/2022\/11\/Sunset-2-1.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-20\" data-title=\"Slide\" data-anim=\"ms:310;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-11-slide-20-layer-12\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:2070px;h:900px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"1920\" height=\"835\" data-lazyload=\"\/\/dctemple.org\/wp-content\/uploads\/2022\/09\/1-7.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-34\" data-title=\"Slide\" data-anim=\"ms:330;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"Home\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-11-slide-34-layer-4\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:50px;y:50px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:300px;h:180px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" data-lazyload=\"\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-11-slide-34-layer-16\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:2070px;h:900px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img loading=\"lazy\" decoding=\"async\" src=\"\/\/dctemple.org\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" class=\"tp-rs-img rs-lazyload\" width=\"1920\" height=\"835\" data-lazyload=\"\/\/dctemple.org\/wp-content\/uploads\/2022\/09\/1-10.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t\t<rs-static-layers><!--\n\t\t\t\t\t--><\/rs-static-layers>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script type=\"text\/javascript\">\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_11_1',rl:[1240,1024,778,480],el:[750],gw:[1240],gh:[750],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider111\"]!==undefined) {window.RS_MODULES.modules[\"revslider111\"].once = false;window.revapi11 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ccb5ca4 homepage-callout-box e-flex e-con-boxed e-con e-parent\" data-id=\"ccb5ca4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-730b35c e-con-full e-flex e-con e-child\" data-id=\"730b35c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7931f1e elementor-cta--skin-cover elementor-widget-tablet__width-auto elementor-widget__width-initial elementor-widget-mobile__width-auto elementor-widget elementor-widget-call-to-action\" data-id=\"7931f1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h1 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tCome See the Washington DC Temple\t\t\t\t\t<\/h1>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tVisible from the beltway, the Washington DC Temple offers beautiful grounds and stunning architecture. There are activities year round at the Visitors' Center. Come &amp; visit with your friends and family. Visit the DC Temple Visitors' Center website to book tours and learn more about the exhibits and events there.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-md\" href=\"https:\/\/dctemplevisitorscenter.org\/\">\n\t\t\t\t\t\tVisitors' Center\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dd63e26 e-flex e-con-boxed e-con e-parent\" data-id=\"dd63e26\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-03314c5 e-con-full e-flex e-con e-child\" data-id=\"03314c5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c1328f pp-info-box-left elementor-widget-tablet__width-initial elementor-widget elementor-widget-pp-info-box\" data-id=\"2c1328f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-info-box.default\">\n\t\t\t\t\t\t\t<div class=\"pp-info-box-container\">\n\t\t\t<div class=\"pp-info-box\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dctemplevisitorscenter.org\/events\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-info-box-icon pp-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-calendar-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M148 288h-40c-6.6 0-12-5.4-12-12v-40c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12zm108-12v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 96v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm192 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96-260v352c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V112c0-26.5 21.5-48 48-48h48V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h128V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h48c26.5 0 48 21.5 48 48zm-48 346V160H48v298c0 3.3 2.7 6 6 6h340c3.3 0 6-2.7 6-6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-info-box-content\">\n\t\t\t\t\t<div class=\"pp-info-box-title-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-title-container\">\n\t\t\t\t\t\t\t\t<h2 class=\"pp-info-box-title\">\n\t\t\t\t\t\t\t\t\tSee Upcoming\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"pp-info-box-subtitle\">\n\t\t\t\t\t\t\t\tEvents\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-description\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/dctemplevisitorscenter.org\/events\/\">Check out What Events are Going on.<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-501b0a4 e-con-full e-flex e-con e-child\" data-id=\"501b0a4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9b93978 pp-info-box-left elementor-widget-tablet__width-initial elementor-widget elementor-widget-pp-info-box\" data-id=\"9b93978\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-info-box.default\">\n\t\t\t\t\t\t\t<div class=\"pp-info-box-container\">\n\t\t\t<div class=\"pp-info-box\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dctemplevisitorscenter.org\/visitors-center\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-info-box-icon pp-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-location-arrow\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M444.52 3.52L28.74 195.42c-47.97 22.39-31.98 92.75 19.19 92.75h175.91v175.91c0 51.17 70.36 67.17 92.75 19.19l191.9-415.78c15.99-38.39-25.59-79.97-63.97-63.97z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-info-box-content\">\n\t\t\t\t\t<div class=\"pp-info-box-title-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-title-container\">\n\t\t\t\t\t\t\t\t<h2 class=\"pp-info-box-title\">\n\t\t\t\t\t\t\t\t\tVisit the\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"pp-info-box-subtitle\">\n\t\t\t\t\t\t\t\tVisitors' Center\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-description\">\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/dctemplevisitorscenter.org\/visitors-center\/\" target=\"_blank\" rel=\"noopener\">Learn More About What There is to do!<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1113ec1 e-con-full e-flex e-con e-child\" data-id=\"1113ec1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be930d6 pp-info-box-left elementor-widget-tablet__width-initial elementor-widget elementor-widget-pp-info-box\" data-id=\"be930d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-info-box.default\">\n\t\t\t\t\t\t\t<div class=\"pp-info-box-container\">\n\t\t\t<div class=\"pp-info-box\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dctemple.org\/sunday-service\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-info-box-icon pp-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-hands-helping\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M488 192H336v56c0 39.7-32.3 72-72 72s-72-32.3-72-72V126.4l-64.9 39C107.8 176.9 96 197.8 96 220.2v47.3l-80 46.2C.7 322.5-4.6 342.1 4.3 357.4l80 138.6c8.8 15.3 28.4 20.5 43.7 11.7L231.4 448H368c35.3 0 64-28.7 64-64h16c17.7 0 32-14.3 32-32v-64h8c13.3 0 24-10.7 24-24v-48c0-13.3-10.7-24-24-24zm147.7-37.4L555.7 16C546.9.7 527.3-4.5 512 4.3L408.6 64H306.4c-12 0-23.7 3.4-33.9 9.7L239 94.6c-9.4 5.8-15 16.1-15 27.1V248c0 22.1 17.9 40 40 40s40-17.9 40-40v-88h184c30.9 0 56 25.1 56 56v28.5l80-46.2c15.3-8.9 20.5-28.4 11.7-43.7z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-info-box-content\">\n\t\t\t\t\t<div class=\"pp-info-box-title-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-title-container\">\n\t\t\t\t\t\t\t\t<h2 class=\"pp-info-box-title\">\n\t\t\t\t\t\t\t\t\tWorship\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"pp-info-box-subtitle\">\n\t\t\t\t\t\t\t\tWith Us\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-description\">\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/dctemple.org\/sunday-service\/\">Find Meeting Locations in the DC Area.<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-139f3ab e-flex e-con-boxed e-con e-parent\" data-id=\"139f3ab\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9a1e342 e-con-full e-flex e-con e-child\" data-id=\"9a1e342\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35cb9e6 elementor-widget elementor-widget-pp-counter\" data-id=\"35cb9e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-counter.default\">\n\t\t\t\t\t\t\t<div class=\"pp-counter-container\">\n\t\t\t<div class=\"pp-counter pp-counter-layout-1\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-counter-number-title-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"pp-counter-number-wrap\">\n\t\t\t\t\t\t<div class=\"pp-counter-number pp-counter-number-35cb9e6\" data-duration=\"750\" data-to-value=\"17887212\" data-from-value=\"0\" data-delimiter=\",\">\n\t\t\t\t0\t\t\t<\/div>\n\t\t\t\t\t\t\t<span class=\"pp-counter-number-suffix\">\n\t\t\t\t\t+\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"pp-counter-title-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-counter-title\">\n\t\t\t\t\t\tMembers Worldwide\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-48bfa67 e-con-full e-flex e-con e-child\" data-id=\"48bfa67\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0a4861b elementor-widget elementor-widget-pp-counter\" data-id=\"0a4861b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-counter.default\">\n\t\t\t\t\t\t\t<div class=\"pp-counter-container\">\n\t\t\t<div class=\"pp-counter pp-counter-layout-1\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-counter-number-title-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"pp-counter-number-wrap\">\n\t\t\t\t\t\t<div class=\"pp-counter-number pp-counter-number-0a4861b\" data-duration=\"750\" data-to-value=\"32046\" data-from-value=\"0\" data-delimiter=\",\">\n\t\t\t\t0\t\t\t<\/div>\n\t\t\t\t\t\t\t<span class=\"pp-counter-number-suffix\">\n\t\t\t\t\t+\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"pp-counter-title-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-counter-title\">\n\t\t\t\t\t\tCongregations\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-df970fe e-con-full e-flex e-con e-child\" data-id=\"df970fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-398bce2 elementor-widget elementor-widget-pp-counter\" data-id=\"398bce2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-counter.default\">\n\t\t\t\t\t\t\t<div class=\"pp-counter-container\">\n\t\t\t<div class=\"pp-counter pp-counter-layout-1\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-counter-number-title-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"pp-counter-number-wrap\">\n\t\t\t\t\t\t<div class=\"pp-counter-number pp-counter-number-398bce2\" data-duration=\"750\" data-to-value=\"204\" data-from-value=\"0\" data-delimiter=\",\">\n\t\t\t\t0\t\t\t<\/div>\n\t\t\t\t\t\t\t<span class=\"pp-counter-number-suffix\">\n\t\t\t\t\t+\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"pp-counter-title-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-counter-title\">\n\t\t\t\t\t\tOperating Temples\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f772aa e-con-full e-flex e-con e-child\" data-id=\"6f772aa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf33099 elementor-widget-tablet__width-initial elementor-widget elementor-widget-pp-counter\" data-id=\"cf33099\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-counter.default\">\n\t\t\t\t\t\t\t<div class=\"pp-counter-container\">\n\t\t\t<div class=\"pp-counter pp-counter-layout-1\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-counter-number-title-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"pp-counter-number-wrap\">\n\t\t\t\t\t\t<div class=\"pp-counter-number pp-counter-number-cf33099\" data-duration=\"750\" data-to-value=\"114727\" data-from-value=\"0\" data-delimiter=\",\">\n\t\t\t\t0\t\t\t<\/div>\n\t\t\t\t\t\t\t<span class=\"pp-counter-number-suffix\">\n\t\t\t\t\t+\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"pp-counter-title-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-counter-title\">\n\t\t\t\t\t\tTotal Volunteer Missionaries\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cea31d1 e-flex e-con-boxed e-con e-parent\" data-id=\"cea31d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3a06b94 e-con-full e-flex e-con e-child\" data-id=\"3a06b94\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c175aef elementor-widget elementor-widget-text-editor\" data-id=\"c175aef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>Washington DC Temple<\/h2><p>The Washington DC Temple was the first Latter-day Saint temple to be built on the East Coast of the United States. Completed in 1974, it is the third-largest temple in the world.<\/p><p>Visitors from all over the world come to this sacred site for its beauty and religious significance. Members of the Church gather inside the temple for sacred religious ceremonies that bring them closer to God, while tourists come to view the temple grounds and enjoy the Visitors\u2019 Center. There is something for everyone at the Washington DC Temple.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8041d88 e-con-full e-flex e-con e-child\" data-id=\"8041d88\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4263dd3 elementor-widget elementor-widget-image\" data-id=\"4263dd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"960\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple.webp\" class=\"attachment-full size-full wp-image-6357\" alt=\"The Washington DC Temple, visible from the treeline, sits majestically as it stretches to the blue sky coated with wispy clouds.\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple.webp 1280w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple-300x225.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple-1024x768.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple-768x576.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple-16x12.webp 16w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Come See the Washington DC Temple Visible from the beltway, the Washington DC Temple offers beautiful grounds and stunning architecture. There are activities year round at the Visitors&#8217; Center. Come &amp; visit with your friends and family. Visit the DC Temple Visitors&#8217; Center website to book tours and learn more about the exhibits and events [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-6337","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Washington DC Temple - Home<\/title>\n<meta name=\"description\" content=\"The Washington DC Temple offers beautiful grounds and stunning architecture. There are activities year-round at the Visitors&#039; Center.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/de\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Washington DC Temple - Home\" \/>\n<meta property=\"og:description\" content=\"The Washington DC Temple offers beautiful grounds and stunning architecture. There are activities year-round at the Visitors&#039; Center.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/de\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-02T14:41:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/\",\"name\":\"Washington DC Temple - Home\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Washington-DC-Temple.webp\",\"datePublished\":\"2022-08-29T21:13:41+00:00\",\"dateModified\":\"2026-07-02T14:41:56+00:00\",\"description\":\"The Washington DC Temple offers beautiful grounds and stunning architecture. There are activities year-round at the Visitors' Center.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Washington-DC-Temple.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Washington-DC-Temple.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Washington DC Tempel - Startseite","description":"Der Washington DC-Tempel besticht durch sein wundersch\u00f6nes Gel\u00e4nde und seine beeindruckende Architektur. Im Besucherzentrum finden das ganze Jahr \u00fcber Aktivit\u00e4ten statt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/de\/","og_locale":"de_DE","og_type":"article","og_title":"Washington DC Temple - Home","og_description":"The Washington DC Temple offers beautiful grounds and stunning architecture. There are activities year-round at the Visitors' Center.","og_url":"https:\/\/dctemple.org\/de\/","og_site_name":"DCTemple.org","article_modified_time":"2026-07-02T14:41:56+00:00","og_image":[{"url":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/","url":"https:\/\/dctemple.org\/","name":"Washington DC Temple - Home","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dctemple.org\/#primaryimage"},"image":{"@id":"https:\/\/dctemple.org\/#primaryimage"},"thumbnailUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple.webp","datePublished":"2022-08-29T21:13:41+00:00","dateModified":"2026-07-02T14:41:56+00:00","description":"The Washington DC Temple offers beautiful grounds and stunning architecture. There are activities year-round at the Visitors' Center.","breadcrumb":{"@id":"https:\/\/dctemple.org\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dctemple.org\/#primaryimage","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/08\/Washington-DC-Temple.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/6337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/comments?post=6337"}],"version-history":[{"count":0,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/6337\/revisions"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/media?parent=6337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":6245,"date":"2022-07-28T16:57:34","date_gmt":"2022-07-28T20:57:34","guid":{"rendered":"http:\/\/dctemple.org\/?page_id=6245"},"modified":"2026-02-11T17:58:12","modified_gmt":"2026-02-11T22:58:12","slug":"sunday-service","status":"publish","type":"page","link":"https:\/\/dctemple.org\/de\/sunday-service\/","title":{"rendered":"Sonntagsservice"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6245\" class=\"elementor elementor-6245\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12ccc71 e-flex e-con-boxed e-con e-parent\" data-id=\"12ccc71\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6fadbad e-con-full e-flex e-con e-child\" data-id=\"6fadbad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ac653c elementor-widget elementor-widget-video\" data-id=\"4ac653c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/nUfhknjT7do&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca775ba e-flex e-con-boxed e-con e-parent\" data-id=\"ca775ba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9df7193 e-con-full e-flex e-con e-child\" data-id=\"9df7193\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c0b2356 elementor-widget elementor-widget-heading\" data-id=\"c0b2356\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mach bei uns mit<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-351e7be e-flex e-con-boxed e-con e-parent\" data-id=\"351e7be\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4632285 e-con-full e-flex e-con e-child\" data-id=\"4632285\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fe2a5a4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fe2a5a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-94c362d e-flex e-con-boxed e-con e-parent\" data-id=\"94c362d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d46946b e-con-full e-flex e-con e-child\" data-id=\"d46946b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-981d260 elementor-widget elementor-widget-text-editor\" data-id=\"981d260\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>W\u00e4hrend die Mitglieder der Kirche Jesu Christi der Heiligen der Letzten Tage nicht an den sonnt\u00e4glichen Gottesdiensten im Tempel teilnehmen, sind Sie eingeladen, sich mit uns zu versammeln, um Kirchenlieder zu singen, Predigten zu h\u00f6ren und mehr \u00fcber unseren Erretter Jesus Christus in den \u00f6rtlichen Gemeindeh\u00e4usern zu erfahren.<\/p><p>Die Kirche ist ein Zufluchtsort vor dem Chaos des Alltags. Der Besuch von Gottesdiensten gibt uns Zeit, uns darauf zu konzentrieren, Gott anzubeten und unsere N\u00e4chsten zu lieben. Es ist eine geistliche Aufladung und ein perfekter Weg, um uns zu helfen, Jesus im Mittelpunkt unseres Lebens zu halten.<\/p><p>Die Gottesdienstzeiten und -pl\u00e4ne sind von Gemeinde zu Gemeinde unterschiedlich. Sie k\u00f6nnen sich jedoch immer auf ein \u00e4hnliches Format verlassen \u2013 ein Haupttreffen f\u00fcr alle und eine andere Klasse, die nach Altersgruppen oder allgemeinen Interessen getrennt ist.<\/p><p>Um ein Versammlungshaus in Ihrer N\u00e4he zu finden, w\u00e4hlen Sie bitte die Schaltfl\u00e4che unten aus.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-749ed21 e-flex e-con-boxed e-con e-parent\" data-id=\"749ed21\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-344f38d e-con-full e-flex e-con e-child\" data-id=\"344f38d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff4a0f0 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ff4a0f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.churchofjesuschrist.org\/welcome\/find-a-church?lang=eng&#038;location=Washington+DC\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Finden Sie ein Gemeindehaus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-625e707 e-flex e-con-boxed e-con e-parent\" data-id=\"625e707\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-601d353 e-con-full e-flex e-con e-child\" data-id=\"601d353\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27f847c elementor-widget elementor-widget-heading\" data-id=\"27f847c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><h2 data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\" style=\"letter-spacing: normal\"><div style=\"text-align: center\"><span style=\"background-color: var(--nv-site-bg)\">Was zu erwarten ist<\/span><span style=\"letter-spacing: var(--h2letterspacing);background-color: var(--nv-site-bg);color: var( --e-global-color-text )\"><\/span><\/div><\/h2><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb4d1c7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bb4d1c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d083fc9 elementor-widget elementor-widget-image\" data-id=\"d083fc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/elementor\/thumbs\/Sunday-Worship-Service-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk-rcn8hjmg7si4q97pz69et3nm04yhyx5bstf4e87wis.webp\" title=\"Sonntagsgottesdienst-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk\" alt=\"Sonntagsgottesdienst-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-611dd3a elementor-widget elementor-widget-heading\" data-id=\"611dd3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Abendmahlsversammlung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f57c4ab elementor-widget elementor-widget-text-editor\" data-id=\"f57c4ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die Hauptversammlung f\u00fcr alle wird Abendmahlsversammlung genannt. Dieses Treffen besteht aus Liedern, Gebeten und Predigten (oder \u201eVortr\u00e4gen\u201c), die jede Woche von verschiedenen Mitgliedern der Gemeinde gehalten werden. Aber der wichtigste Teil des Treffens ist, wenn wir das Abendmahl (oder die Kommunion) nehmen.\u00a0<a style=\"background-color: var(--nv-site-bg); letter-spacing: var(--bodyletterspacing); text-transform: var(--bodytexttransform);\" href=\"https:\/\/www.churchofjesuschrist.org\/comeuntochrist\/belong\/sunday-services\/sacrament\" target=\"_blank\" rel=\"noopener\">Mehr zum Sakrament.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b11b453 elementor-widget elementor-widget-heading\" data-id=\"b11b453\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Musik und Hymnen<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e087fc3 elementor-widget elementor-widget-text-editor\" data-id=\"e087fc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wenn wir \u00fcber den Erretter und unsere vielen Segnungen singen, f\u00fchlen wir uns Gott n\u00e4her. Bei einer typischen Abendmahlsversammlung werden drei oder vier Kirchenlieder von der gesamten Versammlung gesungen. Es kann auch zus\u00e4tzliche Musiknummern von einem Chor, einer kleinen Gruppe oder einem Solisten geben. Vielleicht kennen Sie einige der Hymnen wie \u201eNearer, My God, to Thee\u201c und \u201eHow Great Thou Art\u201c, aber Sie werden auch einige neue lernen. Und es ist in Ordnung, wenn Sie falsch singen! Erheben Sie trotzdem Ihre Stimme, w\u00e4hrend Sie mit uns anbeten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-754fcb7 elementor-widget elementor-widget-heading\" data-id=\"754fcb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Einander Zeugnis geben<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f9de7f elementor-widget elementor-widget-text-editor\" data-id=\"8f9de7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>An jedem ersten Sonntag im Monat gibt es keine typischen Predigten. Stattdessen kann jedes Mitglied der Versammlung zur Kanzel gehen und seine Gef\u00fchle zum Evangelium zum Ausdruck bringen. Wenn wir den Erfahrungen anderer zuh\u00f6ren und sp\u00fcren, wie Gottes Geist unser Herz erf\u00fcllt, k\u00f6nnen unsere eigenen \u00dcberzeugungen und \u00dcberzeugungen gest\u00e4rkt werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b9578b elementor-widget elementor-widget-heading\" data-id=\"7b9578b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Beispielprogramm<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f8af1a elementor-widget elementor-widget-image\" data-id=\"1f8af1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"768\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/ward_program_sacrament_meeting.webp\" class=\"attachment-large size-large wp-image-6248\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/ward_program_sacrament_meeting.webp 640w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/ward_program_sacrament_meeting-250x300.webp 250w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/ward_program_sacrament_meeting-10x12.webp 10w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27da50f elementor-widget elementor-widget-heading\" data-id=\"27da50f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Sonntagskurse<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2a0bd4 elementor-widget elementor-widget-text-editor\" data-id=\"d2a0bd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Entweder vor oder nach der Abendmahlsversammlung gibt es eine Vielzahl anderer altersspezifischer Kurse f\u00fcr Kinder und Erwachsene. Wenn Sie an diesen zus\u00e4tzlichen Treffen teilnehmen m\u00f6chten, fragen Sie jemanden in der Kirche, er wird Ihnen gerne dabei helfen, das richtige Klassenzimmer zu finden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4fafd2b e-flex e-con-boxed e-con e-parent\" data-id=\"4fafd2b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b255952 e-con-full e-flex e-con e-child\" data-id=\"b255952\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1449eee elementor-widget elementor-widget-spacer\" data-id=\"1449eee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9eb2545 e-flex e-con-boxed e-con e-parent\" data-id=\"9eb2545\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-47ef4ba e-con-full e-flex e-con e-child\" data-id=\"47ef4ba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc4cc00 elementor-widget elementor-widget-heading\" data-id=\"dc4cc00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">H\u00e4ufig gestellte Fragen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0b250a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a0b250a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b0af49 elementor-widget elementor-widget-video\" data-id=\"7b0af49\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/BnJ6QkCACkk&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d29bb00 elementor-widget elementor-widget-heading\" data-id=\"d29bb00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Was soll ich anziehen?<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-150f3e7 elementor-widget elementor-widget-text-editor\" data-id=\"150f3e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Sie k\u00f6nnen gerne jede bescheidene Kleidung tragen, in der Sie sich wohlf\u00fchlen. Aber nur damit Sie es wissen, die meisten M\u00e4nner tragen Anz\u00fcge, Sakkos, Hemden und Krawatten, und Frauen tragen Kleider oder R\u00f6cke. Auch Kinder verkleiden sich in der Regel.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d536ff elementor-widget elementor-widget-heading\" data-id=\"3d536ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">F\u00fchle ich mich unwohl, wenn ich alleine teilnehme?<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d7fdb4 elementor-widget elementor-widget-text-editor\" data-id=\"7d7fdb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wir hoffen nicht. Viele unserer Mitglieder kommen jede Woche alleine in die Kirche. Wenn Sie jedoch m\u00f6chten, dass jemand Sie zum ersten Mal begleitet, wenden Sie sich bei Ihrer Ankunft gerne an die Missionare oder den Bischof der Gemeinde, der dann einen Freund f\u00fcr Sie finden wird, mit dem Sie zusammensitzen k\u00f6nnen. Es ist immer schwer, neu zu sein, egal in welcher Situation, aber mit der Zeit lernt man die anderen Mitglieder kennen und f\u00fchlt sich heimischer.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68a521b elementor-widget elementor-widget-image\" data-id=\"68a521b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/elementor\/thumbs\/Women-Talking-Gneral-Conference-e1589998858605-qbatyw956daj7yxnnqys1pjhh3tg2kq4dl6fscyp9g-rcn8g05z0ke7p9g9z0af7zneyejucs15x6xh2wi4pw.webp\" title=\"Frauen-sprechen-Generalkonferenz-e1589998858605-qbatyw956daj7yxnnqys1pjhh3tg2kq4dl6fscyp9g\" alt=\"Frauen-sprechen-Generalkonferenz-e1589998858605-qbatyw956daj7yxnnqys1pjhh3tg2kq4dl6fscyp9g\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3355ca elementor-widget elementor-widget-heading\" data-id=\"c3355ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Wird jeder wissen, dass ich ein Besucher bin?<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbb11d0 elementor-widget elementor-widget-text-editor\" data-id=\"dbb11d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Dies h\u00e4ngt wahrscheinlich von der Gr\u00f6\u00dfe des Zweiges oder der Versammlung ab, die Sie besuchen. Einige Gemeinden sind so gro\u00df (bis zu 600 Mitglieder), dass ihre regul\u00e4ren Mitglieder vielleicht erkennen, dass Sie ein Besucher sind. Andere sind so winzig, dass die Mitglieder sich alle kennen und einen Neuank\u00f6mmling auf jeden Fall erkennen und willkommen hei\u00dfen werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c0d2fe elementor-widget elementor-widget-heading\" data-id=\"0c0d2fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Muss ich Geld spenden?<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f0c7c0 elementor-widget elementor-widget-text-editor\" data-id=\"2f0c7c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nein. Wir bitten nicht um Spenden oder reichen einen Teller.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86059eb elementor-widget elementor-widget-heading\" data-id=\"86059eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Muss ich teilnehmen?<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-583cb3f elementor-widget elementor-widget-text-editor\" data-id=\"583cb3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nein. Besucher m\u00fcssen in keiner Weise teilnehmen. Sie k\u00f6nnen sich einfach zur\u00fccklehnen und den Service genie\u00dfen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45f608f elementor-widget elementor-widget-heading\" data-id=\"45f608f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Wie lange dauert die Kirche?<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e53c28 elementor-widget elementor-widget-text-editor\" data-id=\"2e53c28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Unser prim\u00e4rer Familiengottesdienst hei\u00dft Abendmahlsversammlung. Es findet sonntags in unseren Kapellen statt und dauert etwa eine Stunde. Sie k\u00f6nnen gerne alleine kommen oder Ihre Familie mitbringen; Kinder sind in praktisch allen unseren Gemeinden pr\u00e4sent.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21d4769 elementor-widget elementor-widget-image\" data-id=\"21d4769\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/elementor\/thumbs\/Last-Supper-Banner-qbapyouiodvw1megpwya0lkom0l8698lju3q94s1us-rcnayzxim6yhmba1mu993j0t6820hy9q3kgmk7l4dg.webp\" title=\"Letztes-Abendmahl-Banner-qbapyouiodvw1megpwya0lkom0l8698lju3q94s1us\" alt=\"Letztes-Abendmahl-Banner-qbapyouiodvw1megpwya0lkom0l8698lju3q94s1us\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-558e8ec elementor-widget elementor-widget-heading\" data-id=\"558e8ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Was passiert w\u00e4hrend der Abendmahlsversammlung?<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8e2bcf elementor-widget elementor-widget-text-editor\" data-id=\"b8e2bcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wir singen Lieder (Gesangb\u00fccher werden gestellt). Kirchenmitglieder sprechen Er\u00f6ffnungs- und Schlussgebete. Wir nehmen am Abendmahl (Kommunion) teil, das aus zubereitetem Brot und Wasser besteht, das von Priestertumstr\u00e4gern gesegnet und an die Mitglieder der Versammlung gereicht wird. Und wir h\u00f6ren zwei oder mehr Rednern zu, die normalerweise Mitglieder der Gemeinde sind.<\/p><p>Sie werden vielleicht \u00fcberrascht sein, dass wir nicht nur einen Pastor oder Prediger haben. Wir haben einen unbezahlten Bischof, der jeder Versammlung vorsteht (Gemeinde genannt).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-deb48ce elementor-widget elementor-widget-heading\" data-id=\"deb48ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 30px\">Gibt es sonntags noch andere Treffen?<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e6e164 elementor-widget elementor-widget-text-editor\" data-id=\"7e6e164\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Vor oder nach der Abendmahlsversammlung gibt es eine Vielzahl anderer altersgerechter Zusammenk\u00fcnfte, an denen Sie und Ihre Kinder teilnehmen k\u00f6nnen. Wenn Sie an diesen zus\u00e4tzlichen Treffen teilnehmen m\u00f6chten, fragen Sie jemanden nach dem Weg. Wenn sie es nicht wissen, finden sie jemanden, der es wei\u00df.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-870be27 e-flex e-con-boxed e-con e-parent\" data-id=\"870be27\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3e1b502 e-con-full e-flex e-con e-child\" data-id=\"3e1b502\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-368acfe elementor-widget elementor-widget-spacer\" data-id=\"368acfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c8a7cf4 e-flex e-con-boxed e-con e-parent\" data-id=\"c8a7cf4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e478252 e-con-full e-flex e-con e-child\" data-id=\"e478252\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e12ccd2 elementor-widget elementor-widget-html\" data-id=\"e12ccd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<div style=\"overflow-x:hidden;text-align: center; background: #ffffff; box-shadow: 0 4px 8px 0 rgba(0, 0, 0, 0.2), 0 6px 20px 0 rgba(0, 0, 0, 0.19); padding: 10px;  min-width: 330px; width:60%; margin: auto;\">\r\n<div style=\"overflow-x:hidden;text-align: center; font-size: 20px; line-height: 36px; width: 80%; margin: auto; padding-bottom: 19px; min-width: 315px; margin-bottom: 20px;\">\r\n\r\n<h3 style=\"overflow-x:hidden;font-weight:300px;font-size:24px;line-height:36px;letter-spacing:.16px;color:#3B3A3A;margin-top:20px;margin-bottom:10px;\">Komm und bete mit uns an!<\/h3>\r\n<p style=\"font-size:22px;color:#3B3A3A;padding-top:0px;margin-top:0px;\">F\u00fcr weitere Informationen wenden Sie sich bitte an das Besucherzentrum des Tempels:<\/p>\r\n<p style=\"font-size:22px;\"><i class=\"fa fa-phone\" style=\"color:#3B3A3A\"><\/i> <a href=\"tel:1-301-587-0144\">+1 (301) 587-0144<\/a><\/p>\r\n\r\n<em style=\"font-size:22px;color:#3B3A3A;\">Besucher willkommen. Kostenloses Parken.<\/em>\r\n\r\n<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1518da7 e-flex e-con-boxed e-con e-parent\" data-id=\"1518da7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7bdf3ea e-con-full e-flex e-con e-child\" data-id=\"7bdf3ea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e973be elementor-widget elementor-widget-spacer\" data-id=\"2e973be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>https:\/\/youtu.be\/nUfhknjT7do Come Join Us While members of The Church of Jesus Christ of Latter-day Saints do not attend Sunday worship services in the temple, you are invited to gather with us to sing hymns, hear sermons, and learn more about our Savior Jesus Christ at local meetinghouses. Church is a refuge from the chaos of [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6245","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sunday Service - DCTemple.org<\/title>\n<meta name=\"description\" content=\"Learn more about what Sunday Services of The Church of Jesus Christ of Latter-day Saints are like and find a meetinghouse near you today.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/de\/sunday-service\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sunday Service - DCTemple.org\" \/>\n<meta property=\"og:description\" content=\"Learn more about what Sunday Services of The Church of Jesus Christ of Latter-day Saints are like and find a meetinghouse near you today.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/de\/sunday-service\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T22:58:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dctemple.org\/wp-content\/uploads\/elementor\/thumbs\/Sunday-Worship-Service-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk-rcn8hjmg7si4q97pz69et3nm04yhyx5bstf3udrmkg.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/sunday-service\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/sunday-service\\\/\",\"name\":\"Sunday Service - DCTemple.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/sunday-service\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/sunday-service\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/Sunday-Worship-Service-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk-rcn8hjmg7si4q97pz69et3nm04yhyx5bstf3udrmkg.webp\",\"datePublished\":\"2022-07-28T20:57:34+00:00\",\"dateModified\":\"2026-02-11T22:58:12+00:00\",\"description\":\"Learn more about what Sunday Services of The Church of Jesus Christ of Latter-day Saints are like and find a meetinghouse near you today.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/sunday-service\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/sunday-service\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/sunday-service\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/Sunday-Worship-Service-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk-rcn8hjmg7si4q97pz69et3nm04yhyx5bstf3udrmkg.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/elementor\\\/thumbs\\\/Sunday-Worship-Service-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk-rcn8hjmg7si4q97pz69et3nm04yhyx5bstf3udrmkg.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/sunday-service\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sunday Service\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sonntagsgottesdienst - DCTemple.org","description":"Erfahren Sie mehr \u00fcber die Sonntagsgottesdienste der Kirche Jesu Christi der Heiligen der Letzten Tage und finden Sie noch heute ein Gemeindehaus in Ihrer N\u00e4he.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/de\/sunday-service\/","og_locale":"de_DE","og_type":"article","og_title":"Sunday Service - DCTemple.org","og_description":"Learn more about what Sunday Services of The Church of Jesus Christ of Latter-day Saints are like and find a meetinghouse near you today.","og_url":"https:\/\/dctemple.org\/de\/sunday-service\/","og_site_name":"DCTemple.org","article_modified_time":"2026-02-11T22:58:12+00:00","og_image":[{"url":"https:\/\/dctemple.org\/wp-content\/uploads\/elementor\/thumbs\/Sunday-Worship-Service-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk-rcn8hjmg7si4q97pz69et3nm04yhyx5bstf3udrmkg.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/sunday-service\/","url":"https:\/\/dctemple.org\/sunday-service\/","name":"Sunday Service - DCTemple.org","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dctemple.org\/sunday-service\/#primaryimage"},"image":{"@id":"https:\/\/dctemple.org\/sunday-service\/#primaryimage"},"thumbnailUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/elementor\/thumbs\/Sunday-Worship-Service-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk-rcn8hjmg7si4q97pz69et3nm04yhyx5bstf3udrmkg.webp","datePublished":"2022-07-28T20:57:34+00:00","dateModified":"2026-02-11T22:58:12+00:00","description":"Learn more about what Sunday Services of The Church of Jesus Christ of Latter-day Saints are like and find a meetinghouse near you today.","breadcrumb":{"@id":"https:\/\/dctemple.org\/sunday-service\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/sunday-service\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dctemple.org\/sunday-service\/#primaryimage","url":"https:\/\/dctemple.org\/wp-content\/uploads\/elementor\/thumbs\/Sunday-Worship-Service-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk-rcn8hjmg7si4q97pz69et3nm04yhyx5bstf3udrmkg.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/elementor\/thumbs\/Sunday-Worship-Service-Banner-e1589998887899-qbak8mo8fvsyv1pryueleliwh48gqz6yjxjqteb1wk-rcn8hjmg7si4q97pz69et3nm04yhyx5bstf3udrmkg.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/sunday-service\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"Sunday Service"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/6245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/comments?post=6245"}],"version-history":[{"count":0,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/6245\/revisions"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/media?parent=6245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":6145,"date":"2022-07-21T12:22:52","date_gmt":"2022-07-21T16:22:52","guid":{"rendered":"http:\/\/dctemple.org\/?page_id=6145"},"modified":"2026-02-11T17:59:56","modified_gmt":"2026-02-11T22:59:56","slug":"gallery-open-house","status":"publish","type":"page","link":"https:\/\/dctemple.org\/de\/galleries\/gallery-open-house\/","title":{"rendered":"Galerie \u2013 Tag der offenen T\u00fcr"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6145\" class=\"elementor elementor-6145\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c64031d e-con-full e-flex e-con e-parent\" data-id=\"c64031d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0ee0266 e-con-full e-flex e-con e-child\" data-id=\"0ee0266\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-92d2df3 elementor-widget elementor-widget-heading\" data-id=\"92d2df3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/de\/galleries\/\">&lt; Zur\u00fcck zu allen Galerien<\/a><\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b316d0 e-con-full e-flex e-con e-child\" data-id=\"6b316d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-371dc71 elementor-widget elementor-widget-heading\" data-id=\"371dc71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/dctemple.org\/de\/galleries\/temple-exterior-gallery\/\">Next Gallery &gt;<\/a><\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d4de52 e-con-full e-flex e-con e-parent\" data-id=\"3d4de52\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3d092f2 e-con-full e-flex e-con e-child\" data-id=\"3d092f2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5aba074 elementor-widget elementor-widget-heading\" data-id=\"5aba074\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Tempel-Galerie des offenen Hauses<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2536da elementor-widget elementor-widget-heading\" data-id=\"b2536da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Genie\u00dfen Sie die Fotografie des Washington DC Temple Open House. Klicken Sie auf ein Bild, um es zu erweitern.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecbfb32 elementor-widget elementor-widget-gallery\" data-id=\"ecbfb32\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;masonry&quot;,&quot;columns&quot;:3,&quot;lazyload&quot;:&quot;yes&quot;,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/005-OH119-IMG_1554-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE0OCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzAwNS1PSDExOS1JTUdfMTU1NC1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/005-OH119-IMG_1554-1024x804.webp\" data-width=\"800\" data-height=\"628\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/010-IMG_0343-Temple-sign-by-PageJohnson-Copy-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE0OSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzAxMC1JTUdfMDM0My1UZW1wbGUtc2lnbi1ieS1QYWdlSm9obnNvbi1Db3B5LXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/010-IMG_0343-Temple-sign-by-PageJohnson-Copy-1024x768.webp\" data-width=\"800\" data-height=\"600\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/020-IG76-20220427-BJohnson-IMG_2321-Temple-Tulips-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1MCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzAyMC1JRzc2LTIwMjIwNDI3LUJKb2huc29uLUlNR18yMzIxLVRlbXBsZS1UdWxpcHMtc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/020-IG76-20220427-BJohnson-IMG_2321-Temple-Tulips-1024x767.webp\" data-width=\"800\" data-height=\"599\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/030-IG43-20220422-RBrown-00045-Temple-Reflecting-Pool-no-people-Richard-Brown-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1MSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzAzMC1JRzQzLTIwMjIwNDIyLVJCcm93bi0wMDA0NS1UZW1wbGUtUmVmbGVjdGluZy1Qb29sLW5vLXBlb3BsZS1SaWNoYXJkLUJyb3duLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/030-IG43-20220422-RBrown-00045-Temple-Reflecting-Pool-no-people-Richard-Brown-683x1024.webp\" data-width=\"683\" data-height=\"1024\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/031-OH136-20220611-BJohnson-IMG_1156-Roof-View-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1MiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzAzMS1PSDEzNi0yMDIyMDYxMS1CSm9obnNvbi1JTUdfMTE1Ni1Sb29mLVZpZXctc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/031-OH136-20220611-BJohnson-IMG_1156-Roof-View-1024x602.webp\" data-width=\"800\" data-height=\"470\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/040-551EEDB5-6CA9-461E-B355-2DEFD849AE89-Dayana-Perez-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1MywidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzA0MC01NTFFRURCNS02Q0E5LTQ2MUUtQjM1NS0yREVGRDg0OUFFODktRGF5YW5hLVBlcmV6LXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/040-551EEDB5-6CA9-461E-B355-2DEFD849AE89-Dayana-Perez-1024x681.webp\" data-width=\"800\" data-height=\"532\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/060-20220422-BJohnson-IMG_2116-Annex-Stained-Glass-Close-up-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1NCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzA2MC0yMDIyMDQyMi1CSm9obnNvbi1JTUdfMjExNi1Bbm5leC1TdGFpbmVkLUdsYXNzLUNsb3NlLXVwLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/060-20220422-BJohnson-IMG_2116-Annex-Stained-Glass-Close-up-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/070-IG07-20220418-BJohnson-IMG_1616-Sharon-Eubank-and-Audience-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1NSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzA3MC1JRzA3LTIwMjIwNDE4LUJKb2huc29uLUlNR18xNjE2LVNoYXJvbi1FdWJhbmstYW5kLUF1ZGllbmNlLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/070-IG07-20220418-BJohnson-IMG_1616-Sharon-Eubank-and-Audience-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/080-IG09-HSzamosfalvi-IMG-12-hollie-szamosfalvi-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1NiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzA4MC1JRzA5LUhTemFtb3NmYWx2aS1JTUctMTItaG9sbGllLXN6YW1vc2ZhbHZpLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/080-IG09-HSzamosfalvi-IMG-12-hollie-szamosfalvi-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/090-IG12-HSzamosfalvi-IMG-81-hollie-szamosfalvi-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1NywidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzA5MC1JRzEyLUhTemFtb3NmYWx2aS1JTUctODEtaG9sbGllLXN6YW1vc2ZhbHZpLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/090-IG12-HSzamosfalvi-IMG-81-hollie-szamosfalvi-683x1024.webp\" data-width=\"683\" data-height=\"1024\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/100-IG11-HSzamosfalvi-IMG-73-hollie-szamosfalvi-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1OCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzEwMC1JRzExLUhTemFtb3NmYWx2aS1JTUctNzMtaG9sbGllLXN6YW1vc2ZhbHZpLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/100-IG11-HSzamosfalvi-IMG-73-hollie-szamosfalvi-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/110-IG72-_RBrown_00028_Alan-Ronkin-American-Jewish-Council-Breakfast-2-Richard-Brown-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE1OSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzExMC1JRzcyLV9SQnJvd25fMDAwMjhfQWxhbi1Sb25raW4tQW1lcmljYW4tSmV3aXNoLUNvdW5jaWwtQnJlYWtmYXN0LTItUmljaGFyZC1Ccm93bi1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/110-IG72-_RBrown_00028_Alan-Ronkin-American-Jewish-Council-Breakfast-2-Richard-Brown-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/120-IG48-CJohnson-CJ8B0752-Cheryl-Johnson-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2MCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzEyMC1JRzQ4LUNKb2huc29uLUNKOEIwNzUyLUNoZXJ5bC1Kb2huc29uLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/120-IG48-CJohnson-CJ8B0752-Cheryl-Johnson-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/130-HSzamosfalvi-IMG-117-hollie-szamosfalvi-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2MSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzEzMC1IU3phbW9zZmFsdmktSU1HLTExNy1ob2xsaWUtc3phbW9zZmFsdmktc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/130-HSzamosfalvi-IMG-117-hollie-szamosfalvi-683x1024.webp\" data-width=\"683\" data-height=\"1024\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/140-IG37-20220425-CJohnson-CJ8B0146-Cheryl-Johnson-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2MiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzE0MC1JRzM3LTIwMjIwNDI1LUNKb2huc29uLUNKOEIwMTQ2LUNoZXJ5bC1Kb2huc29uLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/140-IG37-20220425-CJohnson-CJ8B0146-Cheryl-Johnson-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/145-IG70-20220426_RBrown_00012_MD-Congressman-John-Sarbanes-1-Richard-Brown-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2MywidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzE0NS1JRzcwLTIwMjIwNDI2X1JCcm93bl8wMDAxMl9NRC1Db25ncmVzc21hbi1Kb2huLVNhcmJhbmVzLTEtUmljaGFyZC1Ccm93bi1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/145-IG70-20220426_RBrown_00012_MD-Congressman-John-Sarbanes-1-Richard-Brown-819x1024.webp\" data-width=\"800\" data-height=\"1000\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/150-20220422-volunteer-by-PageJohnson-IMG_0550-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2NCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzE1MC0yMDIyMDQyMi12b2x1bnRlZXItYnktUGFnZUpvaG5zb24tSU1HXzA1NTAtc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/150-20220422-volunteer-by-PageJohnson-IMG_0550-1024x768.webp\" data-width=\"800\" data-height=\"600\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/160-IG16-IMG_0545-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2NSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzE2MC1JRzE2LUlNR18wNTQ1LXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/160-IG16-IMG_0545-1024x799.webp\" data-width=\"800\" data-height=\"624\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/170-IG56-20220425-BJohnson-IMG_2145-Mauri-Introduction-in-Tent-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2NiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzE3MC1JRzU2LTIwMjIwNDI1LUJKb2huc29uLUlNR18yMTQ1LU1hdXJpLUludHJvZHVjdGlvbi1pbi1UZW50LXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/170-IG56-20220425-BJohnson-IMG_2145-Mauri-Introduction-in-Tent-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/180-OH077-IMG_1346-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2NywidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzE4MC1PSDA3Ny1JTUdfMTM0Ni1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/180-OH077-IMG_1346-1024x745.webp\" data-width=\"800\" data-height=\"582\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/190-OH071-_MReeder_IMG-7_100s-line-up-to-see-temple-Mark-Reeder-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2OCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzE5MC1PSDA3MS1fTVJlZWRlcl9JTUctN18xMDBzLWxpbmUtdXAtdG8tc2VlLXRlbXBsZS1NYXJrLVJlZWRlci1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/190-OH071-_MReeder_IMG-7_100s-line-up-to-see-temple-Mark-Reeder-1024x768.webp\" data-width=\"800\" data-height=\"600\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/195-OH096-20220528-BJohnson-IMG_0787-This-Way-to-the-Temple-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE2OSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzE5NS1PSDA5Ni0yMDIyMDUyOC1CSm9obnNvbi1JTUdfMDc4Ny1UaGlzLVdheS10by10aGUtVGVtcGxlLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/195-OH096-20220528-BJohnson-IMG_0787-This-Way-to-the-Temple-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/200-CJohnson-CJ8B0588-Cheryl-Johnson-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3MCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzIwMC1DSm9obnNvbi1DSjhCMDU4OC1DaGVyeWwtSm9obnNvbi1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/200-CJohnson-CJ8B0588-Cheryl-Johnson-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/205-OH010-20220429-BJohnson-IMG_0404-Entering-and-Leaving-Temple-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3MSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzIwNS1PSDAxMC0yMDIyMDQyOS1CSm9obnNvbi1JTUdfMDQwNC1FbnRlcmluZy1hbmQtTGVhdmluZy1UZW1wbGUtc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/205-OH010-20220429-BJohnson-IMG_0404-Entering-and-Leaving-Temple-1024x543.webp\" data-width=\"800\" data-height=\"424\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/210-JValentine-ADS_6300a-Neighbors-Jessica-Valentine-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3MiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzIxMC1KVmFsZW50aW5lLUFEU182MzAwYS1OZWlnaGJvcnMtSmVzc2ljYS1WYWxlbnRpbmUtc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/210-JValentine-ADS_6300a-Neighbors-Jessica-Valentine-1024x684.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/215-20220624-HSzamosfalvi-7-hollie-szamosfalvi-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3MywidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzIxNS0yMDIyMDYyNC1IU3phbW9zZmFsdmktNy1ob2xsaWUtc3phbW9zZmFsdmktc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/215-20220624-HSzamosfalvi-7-hollie-szamosfalvi-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/220-20220419-CJohnson-CJ8B9538-Cheryl-Johnson-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3NCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzIyMC0yMDIyMDQxOS1DSm9obnNvbi1DSjhCOTUzOC1DaGVyeWwtSm9obnNvbi1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/220-20220419-CJohnson-CJ8B9538-Cheryl-Johnson-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/230-OH046-20220507-Temple-foyer-by-PageJohnson-IMG_1292-2-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3NSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzIzMC1PSDA0Ni0yMDIyMDUwNy1UZW1wbGUtZm95ZXItYnktUGFnZUpvaG5zb24tSU1HXzEyOTItMi1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/230-OH046-20220507-Temple-foyer-by-PageJohnson-IMG_1292-2-1024x768.webp\" data-width=\"800\" data-height=\"600\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/240-CJohnson-CJ8B0779-Cheryl-Johnson-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3NiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzI0MC1DSm9obnNvbi1DSjhCMDc3OS1DaGVyeWwtSm9obnNvbi1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/240-CJohnson-CJ8B0779-Cheryl-Johnson-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/250-IG17-20220419-BJohnson-IMG_1750-Aburto-Group-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3NywidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzI1MC1JRzE3LTIwMjIwNDE5LUJKb2huc29uLUlNR18xNzUwLUFidXJ0by1Hcm91cC1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/250-IG17-20220419-BJohnson-IMG_1750-Aburto-Group-1024x685.webp\" data-width=\"800\" data-height=\"535\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/260-20220422-RBrown-00249-Elder-Sister-Bennett-UNICEF-group-Richard-Brown-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3OCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzI2MC0yMDIyMDQyMi1SQnJvd24tMDAyNDktRWxkZXItU2lzdGVyLUJlbm5ldHQtVU5JQ0VGLWdyb3VwLVJpY2hhcmQtQnJvd24tc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/260-20220422-RBrown-00249-Elder-Sister-Bennett-UNICEF-group-Richard-Brown-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/270-IG38-20220425-CJohnson-CJ8B0318-Cheryl-Johnson-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE3OSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzI3MC1JRzM4LTIwMjIwNDI1LUNKb2huc29uLUNKOEIwMzE4LUNoZXJ5bC1Kb2huc29uLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/270-IG38-20220425-CJohnson-CJ8B0318-Cheryl-Johnson-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/280-IG61-_RBrown_0010_US-Senators-Church-Leaders-Richard-Brown-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4MCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzI4MC1JRzYxLV9SQnJvd25fMDAxMF9VUy1TZW5hdG9ycy1DaHVyY2gtTGVhZGVycy1SaWNoYXJkLUJyb3duLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/280-IG61-_RBrown_0010_US-Senators-Church-Leaders-Richard-Brown-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/290-IG25-20220419-HSzamosfalvi-IMG_-55-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4MSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzI5MC1JRzI1LTIwMjIwNDE5LUhTemFtb3NmYWx2aS1JTUdfLTU1LXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/290-IG25-20220419-HSzamosfalvi-IMG_-55-683x1024.webp\" data-width=\"683\" data-height=\"1024\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/300-IG59-20220425-BJohnson-IMG_2225-Ambassador-Group-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4MiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzMwMC1JRzU5LTIwMjIwNDI1LUJKb2huc29uLUlNR18yMjI1LUFtYmFzc2Fkb3ItR3JvdXAtc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/300-IG59-20220425-BJohnson-IMG_2225-Ambassador-Group-1024x749.webp\" data-width=\"800\" data-height=\"585\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/305-20220624-HSzamosfalvi-13-hollie-szamosfalvi-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4MywidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzMwNS0yMDIyMDYyNC1IU3phbW9zZmFsdmktMTMtaG9sbGllLXN6YW1vc2ZhbHZpLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/305-20220624-HSzamosfalvi-13-hollie-szamosfalvi-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/310-OH030-20220505-volunteer-directing-cars-by-PageJohnson-MG_1176-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4NCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzMxMC1PSDAzMC0yMDIyMDUwNS12b2x1bnRlZXItZGlyZWN0aW5nLWNhcnMtYnktUGFnZUpvaG5zb24tTUdfMTE3Ni1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/310-OH030-20220505-volunteer-directing-cars-by-PageJohnson-MG_1176-1024x768.webp\" data-width=\"800\" data-height=\"600\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/315-IMG_4797-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4NSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzMxNS1JTUdfNDc5Ny1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/315-IMG_4797-1024x750.webp\" data-width=\"800\" data-height=\"586\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/320-OH005-20220428-BJohnson-IMG_2390-Senior-Living-Bus-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4NiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzMyMC1PSDAwNS0yMDIyMDQyOC1CSm9obnNvbi1JTUdfMjM5MC1TZW5pb3ItTGl2aW5nLUJ1cy1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/320-OH005-20220428-BJohnson-IMG_2390-Senior-Living-Bus-1024x625.webp\" data-width=\"800\" data-height=\"488\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/330-OH063-20220518-BJohnson-IMG_0861-St-Albans-Bus-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4NywidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzMzMC1PSDA2My0yMDIyMDUxOC1CSm9obnNvbi1JTUdfMDg2MS1TdC1BbGJhbnMtQnVzLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/330-OH063-20220518-BJohnson-IMG_0861-St-Albans-Bus-1024x495.webp\" data-width=\"800\" data-height=\"387\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/345-IMG_1332-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4OCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzM0NS1JTUdfMTMzMi1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6ImVjYmZiMzIifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/345-IMG_1332-1024x681.webp\" data-width=\"800\" data-height=\"532\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/350-OH025-5P2A7038-hollie-szamosfalvi-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE4OSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzM1MC1PSDAyNS01UDJBNzAzOC1ob2xsaWUtc3phbW9zZmFsdmktc2NhbGVkLndlYnAiLCJzbGlkZXNob3ciOiJlY2JmYjMyIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/350-OH025-5P2A7038-hollie-szamosfalvi-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/360-OH056-2022_05_11_RBrown_DC-Temple-Open-House_00020-Richard-Brown-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE5MCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzM2MC1PSDA1Ni0yMDIyXzA1XzExX1JCcm93bl9EQy1UZW1wbGUtT3Blbi1Ib3VzZV8wMDAyMC1SaWNoYXJkLUJyb3duLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/360-OH056-2022_05_11_RBrown_DC-Temple-Open-House_00020-Richard-Brown-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/370-OH066-2022_05_18_RBrown_Temple-Open-House_00006-Richard-Brown-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE5MSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzM3MC1PSDA2Ni0yMDIyXzA1XzE4X1JCcm93bl9UZW1wbGUtT3Blbi1Ib3VzZV8wMDAwNi1SaWNoYXJkLUJyb3duLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/370-OH066-2022_05_18_RBrown_Temple-Open-House_00006-Richard-Brown-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/380-OH051-2022_05_11_RBrown_DC-Temple-Open-House_00005-Richard-Brown-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE5MiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzM4MC1PSDA1MS0yMDIyXzA1XzExX1JCcm93bl9EQy1UZW1wbGUtT3Blbi1Ib3VzZV8wMDAwNS1SaWNoYXJkLUJyb3duLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/380-OH051-2022_05_11_RBrown_DC-Temple-Open-House_00005-Richard-Brown-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/390-OH064-2022_05_18_RBrown_Temple-Open-House_00002-Richard-Brown-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE5MywidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzM5MC1PSDA2NC0yMDIyXzA1XzE4X1JCcm93bl9UZW1wbGUtT3Blbi1Ib3VzZV8wMDAwMi1SaWNoYXJkLUJyb3duLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/390-OH064-2022_05_18_RBrown_Temple-Open-House_00002-Richard-Brown-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/400-OH086-20220626-HSzamosfalvi-22-hollie-szamosfalvi-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE5NCwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzQwMC1PSDA4Ni0yMDIyMDYyNi1IU3phbW9zZmFsdmktMjItaG9sbGllLXN6YW1vc2ZhbHZpLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/400-OH086-20220626-HSzamosfalvi-22-hollie-szamosfalvi-683x1024.webp\" data-width=\"683\" data-height=\"1024\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/410-20220626-HSzamosfalvi-hollie-szamosfalvi-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE5NSwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzQxMC0yMDIyMDYyNi1IU3phbW9zZmFsdmktaG9sbGllLXN6YW1vc2ZhbHZpLXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/410-20220626-HSzamosfalvi-hollie-szamosfalvi-1024x683.webp\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/510-OH137-20220611-BJohnson-IMG_1185-Roof-Sunset-Copy-scaled.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ecbfb32\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjE5NiwidXJsIjoiaHR0cHM6XC9cL2RjdGVtcGxlLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDdcLzUxMC1PSDEzNy0yMDIyMDYxMS1CSm9obnNvbi1JTUdfMTE4NS1Sb29mLVN1bnNldC1Db3B5LXNjYWxlZC53ZWJwIiwic2xpZGVzaG93IjoiZWNiZmIzMiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/07\/510-OH137-20220611-BJohnson-IMG_1185-Roof-Sunset-Copy-1024x676.webp\" data-width=\"800\" data-height=\"528\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>&lt; Back to All Galleries Next Gallery &gt; Temple Open House Gallery Enjoy photography of the Washington D.C. Temple Open House. Click on an image to expand.<\/p>","protected":false},"author":2,"featured_media":0,"parent":1209,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6145","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gallery \u2013 Open House - DCTemple.org<\/title>\n<meta name=\"description\" content=\"See a photography gallery from the 2022 Washington DC Temple Open House today and gain perspective from the House of the Lord.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/de\/galleries\/gallery-open-house\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gallery \u2013 Open House - DCTemple.org\" \/>\n<meta property=\"og:description\" content=\"See a photography gallery from the 2022 Washington DC Temple Open House today and gain perspective from the House of the Lord.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/de\/galleries\/gallery-open-house\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T22:59:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/galleries\\\/gallery-open-house\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/galleries\\\/gallery-open-house\\\/\",\"name\":\"Gallery \u2013 Open House - DCTemple.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"datePublished\":\"2022-07-21T16:22:52+00:00\",\"dateModified\":\"2026-02-11T22:59:56+00:00\",\"description\":\"See a photography gallery from the 2022 Washington DC Temple Open House today and gain perspective from the House of the Lord.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/galleries\\\/gallery-open-house\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/galleries\\\/gallery-open-house\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/galleries\\\/gallery-open-house\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galleries\",\"item\":\"https:\\\/\\\/dctemple.org\\\/galleries\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gallery \u2013 Open House\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gallery \u2013 Open House - DCTemple.org","description":"See a photography gallery from the 2022 Washington DC Temple Open House today and gain perspective from the House of the Lord.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/de\/galleries\/gallery-open-house\/","og_locale":"de_DE","og_type":"article","og_title":"Gallery \u2013 Open House - DCTemple.org","og_description":"See a photography gallery from the 2022 Washington DC Temple Open House today and gain perspective from the House of the Lord.","og_url":"https:\/\/dctemple.org\/de\/galleries\/gallery-open-house\/","og_site_name":"DCTemple.org","article_modified_time":"2026-02-11T22:59:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/galleries\/gallery-open-house\/","url":"https:\/\/dctemple.org\/galleries\/gallery-open-house\/","name":"Gallery \u2013 Open House - DCTemple.org","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"datePublished":"2022-07-21T16:22:52+00:00","dateModified":"2026-02-11T22:59:56+00:00","description":"See a photography gallery from the 2022 Washington DC Temple Open House today and gain perspective from the House of the Lord.","breadcrumb":{"@id":"https:\/\/dctemple.org\/galleries\/gallery-open-house\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/galleries\/gallery-open-house\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/galleries\/gallery-open-house\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"Galleries","item":"https:\/\/dctemple.org\/galleries\/"},{"@type":"ListItem","position":3,"name":"Gallery \u2013 Open House"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/6145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/comments?post=6145"}],"version-history":[{"count":0,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/6145\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/1209"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/media?parent=6145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":6067,"date":"2022-06-27T13:33:07","date_gmt":"2022-06-27T17:33:07","guid":{"rendered":"http:\/\/dctemple.org\/?page_id=6067"},"modified":"2025-10-03T04:53:59","modified_gmt":"2025-10-03T08:53:59","slug":"washington-d-c-temple","status":"publish","type":"page","link":"https:\/\/dctemple.org\/de\/washington-d-c-temple\/","title":{"rendered":"Washington DC Tempel"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6067\" class=\"elementor elementor-6067\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18c075f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18c075f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a520bb0\" data-id=\"a520bb0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3897822 elementor-widget elementor-widget-heading\" data-id=\"3897822\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Washington DC Tempel<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ade3876 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ade3876\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ce34aa elementor-widget elementor-widget-image\" data-id=\"3ce34aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"522\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2.webp\" class=\"attachment-full size-full wp-image-6069\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2.webp 1200w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2-300x131.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2-1024x445.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2-768x334.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2-18x8.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef670fb elementor-widget elementor-widget-text-editor\" data-id=\"ef670fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Der Washington-DC-Tempel wird von Mitgliedern der Kirche Jesu Christi der Heiligen der Letzten Tage als buchst\u00e4bliches Haus des Herrn betrachtet. Der Hauptzweck des Tempels besteht darin, den Mitgliedern im Raum Washington DC heilige Handlungen und Segnungen zu erteilen. Zu den heiligen Handlungen geh\u00f6ren das Endowment, die Eheschlie\u00dfung und die Taufe.<\/p><p>Besucher sind eingeladen, die G\u00e4rten, beruhigenden Springbrunnen und die Aussicht auf die atemberaubende Architektur zu genie\u00dfen. Besuchen Sie w\u00e4hrend Ihres Besuchs das Besucherzentrum f\u00fcr eine personalisierte Tour.<\/p><p>Viele Einheimische nennen ihn den Mormonen-Tempel, aber der eigentliche Name ist der Washington-DC-Tempel. Es geh\u00f6rt und wird betrieben von der Kirche Jesu Christi der Heiligen der Letzten Tage.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f98d1f7 elementor-widget elementor-widget-image\" data-id=\"f98d1f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"522\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-3.webp\" class=\"attachment-full size-full wp-image-6070\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-3.webp 1200w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-3-300x131.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-3-1024x445.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-3-768x334.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-3-18x8.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bf90db elementor-widget elementor-widget-text-editor\" data-id=\"1bf90db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Der Tempel befindet sich an einem prominenten Ort in Kensington und ist zu einem lokalen Wahrzeichen f\u00fcr Autofahrer geworden, die ihn mittlerweile den Umgehungstempel nennen.<\/p><p>Der Tempel ist nicht der Ort, an dem sich die Mitglieder zu Sonntagsgottesdiensten treffen. Tempel unterscheiden sich von den regul\u00e4ren Kapellen, die die Kirche \u00fcberall auf der Welt hat. Mitglieder der Kirche beten in Gemeindeh\u00e4usern auf der ganzen Welt und Besucher sind jederzeit willkommen, daran teilzunehmen. Auf dem Tempelgel\u00e4nde befinden sich mehrere Kapellen. <a href=\"https:\/\/clickly.org\/47wjv\" target=\"_blank\" rel=\"noopener\">Weitere Informationen zu Gottesdienstzeiten und -orten finden Sie hier.<\/a><\/p><p>Tempel sind ein \u201eOrt, an dem die h\u00f6chsten Sakramente des Glaubens\u201c geschehen k\u00f6nnen. Im Tempel erfahren Sie mehr \u00fcber den Erl\u00f6sungsplan und wie Sie dem vollkommenen Beispiel Christi folgen k\u00f6nnen. Gottes gr\u00f6\u00dfte Segnungen sind in seinen Tempeln verf\u00fcgbar. W\u00e4hrend drinnen tragen die Mitglieder <a href=\"https:\/\/www.youtube.com\/watch?v=bMutZrefILc\" target=\"_blank\" rel=\"noopener\">wei\u00dfe Kleidung, die sowohl Reinheit als auch Gleichheit symbolisiert.<\/a><\/p><p>Die Praxis des Tempelbaus geht in der Bibel auf das Alte und Neue Testament zur\u00fcck. Der Tempel in Washington DC ist einer von \u00fcber 166 modernen Tempeln, die von der Kirche Jesu Christi der Heiligen der Letzten Tage erbaut wurden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48db0f6 elementor-widget elementor-widget-video\" data-id=\"48db0f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/HX9K42SnQQQ?feature=shared&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ddb6cd elementor-widget elementor-widget-text-editor\" data-id=\"2ddb6cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nur Mitgliedern der Kirche Jesu Christi der Heiligen der Letzten Tage mit einem aktiven Tempelschein ist der Zutritt zum Washington DC-Tempel gestattet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b6cabf elementor-widget elementor-widget-image\" data-id=\"8b6cabf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"522\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1.webp\" class=\"attachment-full size-full wp-image-6058\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1.webp 1200w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1-300x131.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1-1024x445.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1-768x334.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1-18x8.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57a350d elementor-widget elementor-widget-text-editor\" data-id=\"57a350d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Jeder, unabh\u00e4ngig von seiner Religion, ist willkommen, das Tempelgel\u00e4nde zu besuchen, Gottesdienste in der Kapelle zu besuchen, das Besucherzentrum zu besichtigen und die anderen Einrichtungen zu nutzen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-055e3af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"055e3af\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ba650a\" data-id=\"7ba650a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea3f80b elementor-widget elementor-widget-heading\" data-id=\"ea3f80b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Ort der Ruhe und des Lernens<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d02098 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4d02098\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a89506 elementor-widget elementor-widget-text-editor\" data-id=\"6a89506\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>F\u00fcr die Mitglieder der Kirche soll der Tempel in Washington DC ein Ort des Lernens und ein Ort des Friedens sein. Es soll ein Ort sein, an dem die Mitglieder spirituelle F\u00fchrung f\u00fcr Entscheidungen in ihrem Leben erhalten k\u00f6nnen. Mitglieder, die in den Tempel gehen, haben die M\u00f6glichkeit, im himmlischen Raum zu sitzen \u2013 einem wundersch\u00f6nen Raum, der den Mitgliedern zum Nachdenken und Beten dient.<\/p><p>\u00a0<\/p><p>Mitglieder der Kirche Jesu Christi der Heiligen der Letzten Tage vollziehen mehrere heilige Handlungen im DC-Tempel. Verordnungen sind heilige Handlungen, die ein verbindliches Versprechen zwischen Gott und einer Person schaffen, die in Gottes Gegenwart zur\u00fcckkehren m\u00f6chte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-758bca0 elementor-widget elementor-widget-heading\" data-id=\"758bca0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ausstattung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e85fccf elementor-widget elementor-widget-image\" data-id=\"e85fccf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1775\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122348_LNilsson_Celestial_0729_Pano-scaled.webp\" class=\"attachment-full size-full wp-image-6072\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122348_LNilsson_Celestial_0729_Pano-scaled.webp 1920w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122348_LNilsson_Celestial_0729_Pano-300x277.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122348_LNilsson_Celestial_0729_Pano-1024x947.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122348_LNilsson_Celestial_0729_Pano-768x710.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122348_LNilsson_Celestial_0729_Pano-1536x1420.webp 1536w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122348_LNilsson_Celestial_0729_Pano-13x12.webp 13w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Der himmlische Raum im Washington-DC-Tempel<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efea154 elementor-widget elementor-widget-text-editor\" data-id=\"efea154\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die Endowmentverordnung \u201ebesteht aus einer Reihe von Anweisungen und beinhaltet B\u00fcndnisse, rechtschaffen zu leben und die Anforderungen des Evangeliums zu befolgen\u201c. Das Mitglied verspricht, den Grunds\u00e4tzen der Kirche Jesu Christi der Heiligen der Letzten Tage zu folgen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cf16b0 elementor-widget elementor-widget-heading\" data-id=\"1cf16b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Die Ehe<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-913dad0 elementor-widget elementor-widget-image\" data-id=\"913dad0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122351_LNilsson_Brides_0678-scaled.webp\" class=\"attachment-full size-full wp-image-6073\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122351_LNilsson_Brides_0678-scaled.webp 1920w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122351_LNilsson_Brides_0678-300x200.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122351_LNilsson_Brides_0678-1024x683.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122351_LNilsson_Brides_0678-768x512.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122351_LNilsson_Brides_0678-1536x1024.webp 1536w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122351_LNilsson_Brides_0678-18x12.webp 18w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122351_LNilsson_Brides_0678-930x620.webp 930w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Das Zimmer der Braut im Washington-DC-Tempel<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e506f1f elementor-widget elementor-widget-text-editor\" data-id=\"e506f1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ehen, die im Washington-DC-Tempel geschlossen werden, gelten als ewig und bestehen \u00fcber den Tod hinaus. Diese ewige Ehe ist jedoch an die Bedingung gekn\u00fcpft, dass Mann und Frau den Verhei\u00dfungen, die sie im Tempel geben, treu bleiben und die Ma\u00dfst\u00e4be der Lehren Christi einhalten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e237e78 elementor-widget elementor-widget-heading\" data-id=\"e237e78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Taufe<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6c0331 elementor-widget elementor-widget-image\" data-id=\"f6c0331\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122347_LNilsson_Baptistery_0657-scaled.webp\" class=\"attachment-full size-full wp-image-6071\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122347_LNilsson_Baptistery_0657-scaled.webp 1920w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122347_LNilsson_Baptistery_0657-300x200.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122347_LNilsson_Baptistery_0657-1024x683.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122347_LNilsson_Baptistery_0657-768x512.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122347_LNilsson_Baptistery_0657-1536x1024.webp 1536w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122347_LNilsson_Baptistery_0657-18x12.webp 18w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/20210729_122347_LNilsson_Baptistery_0657-930x620.webp 930w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Das Baptisterium im Washington-DC-Tempel<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e10ab6 elementor-widget elementor-widget-text-editor\" data-id=\"0e10ab6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Taufen im Washington-DC-Tempel werden im Namen der Vorfahren von Mitgliedern vollzogen, die verstorben sind und keine M\u00f6glichkeit hatten, sich taufen zu lassen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-95a1a9a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"95a1a9a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-00184f6\" data-id=\"00184f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8cbedba elementor-widget elementor-widget-heading\" data-id=\"8cbedba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">H\u00e4ufig gestellte Fragen<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9346929 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9346929\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9228667 elementor-widget elementor-widget-accordion\" data-id=\"9228667\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1531\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1531\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Kann ich den Washington DC Tempel betreten?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1531\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1531\"><p><iframe title=\"YouTube-Videoplayer\" src=\"https:\/\/www.youtube.com\/embed\/xSiwmYzSYTM\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/>Derzeit ist es nur Mitgliedern der Kirche Jesu Christi der Heiligen der Letzten Tage mit einem aktiven Tempelschein gestattet, das Innere des Washington DC-Tempels zu betreten.<\/p><p>Jeder, unabh\u00e4ngig von Religion, Herkunft oder Glauben, ist herzlich willkommen, die friedlichen Brunnen und G\u00e4rten zu genie\u00dfen, einen Rundgang durch das Besucherzentrum zu machen, anhand von Kunstwerken und Wandgem\u00e4lden mehr \u00fcber das Leben Christi zu erfahren und Andachten und Auff\u00fchrungen im Besucherzentrum beizuwohnen Besuchen Sie das Besucherzentrum und besuchen Sie uns am Sonntag zu erhebenden Gottesdiensten.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1532\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1532\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Was sind Tempel? Wie unterscheiden sie sich von einer Kirche?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1532\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1532\"><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/xkjUpbMebRU\" title=\"YouTube-Videoplayer\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\nTempel sind buchst\u00e4blich H\u00e4user des Herrn. Sie sind Orte, an die Menschen gehen k\u00f6nnen, um Gott heilige Versprechen zu geben, seinen Geist zu sp\u00fcren und den hektischen Anforderungen des Alltags zu entfliehen. Tempel gibt es schon lange. Mose hatte eine Stiftsh\u00fctte, Salomo baute einen wundersch\u00f6nen Tempel und Jesus lehrte im Tempel in Jerusalem. Heute werden Tempel auf der ganzen Welt gebaut. In Tempeln k\u00f6nnen Paare f\u00fcr die Ewigkeit heiraten, nicht nur \u201ebis der Tod euch scheidet\u201c. Mitglieder der Kirche k\u00f6nnen auch Taufen und andere heilige Handlungen f\u00fcr ihre Lieben vollziehen, die gestorben sind, ohne diese Segnungen erhalten zu haben. Mitglieder der Kirche beten in Gemeindeh\u00e4usern auf der ganzen Welt, und Besucher sind immer willkommen, daran teilzunehmen. Diese Geb\u00e4ude k\u00f6nnen eine Nachbarschaftskapelle oder sogar einen gemieteten Raum in einem Stadtgeb\u00e4ude umfassen. Auf jeden Fall sind diese Gemeindeh\u00e4user der Ort, an dem sich die Mitglieder der Kirche regelm\u00e4\u00dfig zu sonnt\u00e4glichen Gottesdiensten und w\u00f6chentlichen Aktivit\u00e4ten versammeln.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1533\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1533\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Kann ich den Tempel besuchen, wenn ich kein Mitglied bin?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1533\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1533\"><p>Ja. W\u00e4hrend Sie den Tempel selbst nicht betreten k\u00f6nnen, sind Sie herzlich willkommen, die Brunnen und G\u00e4rten zu genie\u00dfen, einen Rundgang durch das Besucherzentrum zu machen, anhand von Kunstwerken und Wandgem\u00e4lden mehr \u00fcber das Leben Christi zu erfahren und an Andachten und Auff\u00fchrungen teilzunehmen Besuchen Sie das Besucherzentrum und besuchen Sie uns am Sonntag f\u00fcr erhebende Gottesdienste.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1534\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1534\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Wie sieht es im Inneren des Tempels aus?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1534\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1534\"><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/mUYF1TX5RxM\" title=\"YouTube-Videoplayer\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1535\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1535\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Was sind Taufen f\u00fcr die Toten?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1535\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1535\"><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/RzCSrMJhWeQ\" title=\"YouTube-Videoplayer\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1536\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1536\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Was ist ein Tempel-Endowment?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1536\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1536\"><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/Fd8tVXN9y6Q\" title=\"YouTube-Videoplayer\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1537\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1537\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Wie l\u00e4uft eine Tempelhochzeit ab?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1537\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1537\"><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/gA6aTiMDYho\" title=\"YouTube-Videoplayer\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1538\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1538\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Was sind Tempelgew\u00e4nder?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1538\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1538\"><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/5vvN4qJRBM0\" title=\"YouTube-Videoplayer\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1539\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-1539\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Warum nennen es manche Leute den Mormonen-Tempel oder HLT-Tempel?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1539\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-1539\"><p>Ein gebr\u00e4uchlicher Spitzname f\u00fcr Mitglieder der Kirche Jesu Christi der Heiligen der Letzten Tage ist \u201eMormone\u201c. Ein weiterer gebr\u00e4uchlicher Spitzname ist \u201eLDS Church\u201c. Daher wird der Washington-DC-Tempel manchmal als \u201eMormonentempel\u201c oder \u201eHLT-Tempel\u201c bezeichnet.<\/p><p>Der Spitzname \u201eMormon\u201c stammt von einem Buch der Heiligen Schrift, das wir \u201eDas Buch Mormon: Ein weiterer Zeuge f\u00fcr Jesus Christus\u201c genannt haben. Lerne mehr \u00fcber <a href=\"https:\/\/www.churchofjesuschrist.org\/comeuntochrist\/believe\/book-of-mormon\/what-is-the-book-of-mormon#:~:text=The%20Book%20of%20Mormon%20is,and%20teachings%20of%20Jesus%20Christ.\">Das Buch Mormon.<\/a><\/p><p>Obwohl der Begriff \u201eMormonenkirche\u201c seit langem \u00f6ffentlich als Spitzname f\u00fcr die Kirche verwendet wird, handelt es sich nicht um einen autorisierten Titel, und die Kirche r\u00e4t von seiner Verwendung ab. Daher bitten wir alle, die Abk\u00fcrzung \u201eLDS\u201c oder den Spitznamen \u201eMormon\u201c nicht als Ersatz f\u00fcr den Namen der Kirche zu verwenden.<\/p><p>Wenn es um Mitglieder der Kirche geht, werden die Begriffe \u201eMitglieder der Kirche Jesu Christi der Heiligen der Letzten Tage\u201c oder \u201eHeilige der Letzten Tage\u201c bevorzugt.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23e438a elementor-widget elementor-widget-text-editor\" data-id=\"23e438a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/dctemple.org\/de\/about\/\">Erfahren Sie hier&gt;&gt; mehr \u00fcber die Geschichte des Washington DC Tempels<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Washington D.C. Temple The Washington D.C. Temple is considered a literal house of the Lord by members of The Church of Jesus Christ of Latter-Day Saints. The principal purpose of the temple is to provide ordinances and blessings to members in the Washington D.C. area. Ordinances include endowment, marriage, and baptism. Visitors are invited to [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"footnotes":""},"class_list":["post-6067","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Washington D.C. Temple - DCTemple.org<\/title>\n<meta name=\"description\" content=\"Discover the Washington D.C. Temple with its elaborate spires and gardens and about frequently asked questions, such as what happens inside.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/de\/washington-d-c-temple\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Washington D.C. Temple - DCTemple.org\" \/>\n<meta property=\"og:description\" content=\"Discover the Washington D.C. Temple with its elaborate spires and gardens and about frequently asked questions, such as what happens inside.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/de\/washington-d-c-temple\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-03T08:53:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/washington-d-c-temple\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/washington-d-c-temple\\\/\",\"name\":\"Washington D.C. Temple - DCTemple.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/washington-d-c-temple\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/washington-d-c-temple\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/DC-Banner-Series-2.webp\",\"datePublished\":\"2022-06-27T17:33:07+00:00\",\"dateModified\":\"2025-10-03T08:53:59+00:00\",\"description\":\"Discover the Washington D.C. Temple with its elaborate spires and gardens and about frequently asked questions, such as what happens inside.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/washington-d-c-temple\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/washington-d-c-temple\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/washington-d-c-temple\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/DC-Banner-Series-2.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/DC-Banner-Series-2.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/washington-d-c-temple\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Washington D.C. Temple\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Washington DC Tempel - DCTemple.org","description":"Entdecken Sie den Washington DC-Tempel mit seinen kunstvollen T\u00fcrmen und G\u00e4rten und erfahren Sie mehr \u00fcber h\u00e4ufig gestellte Fragen, beispielsweise was im Inneren passiert.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/de\/washington-d-c-temple\/","og_locale":"de_DE","og_type":"article","og_title":"Washington D.C. Temple - DCTemple.org","og_description":"Discover the Washington D.C. Temple with its elaborate spires and gardens and about frequently asked questions, such as what happens inside.","og_url":"https:\/\/dctemple.org\/de\/washington-d-c-temple\/","og_site_name":"DCTemple.org","article_modified_time":"2025-10-03T08:53:59+00:00","og_image":[{"url":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"6 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/washington-d-c-temple\/","url":"https:\/\/dctemple.org\/washington-d-c-temple\/","name":"Washington D.C. Temple - DCTemple.org","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dctemple.org\/washington-d-c-temple\/#primaryimage"},"image":{"@id":"https:\/\/dctemple.org\/washington-d-c-temple\/#primaryimage"},"thumbnailUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2.webp","datePublished":"2022-06-27T17:33:07+00:00","dateModified":"2025-10-03T08:53:59+00:00","description":"Discover the Washington D.C. Temple with its elaborate spires and gardens and about frequently asked questions, such as what happens inside.","breadcrumb":{"@id":"https:\/\/dctemple.org\/washington-d-c-temple\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/washington-d-c-temple\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dctemple.org\/washington-d-c-temple\/#primaryimage","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-2.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/washington-d-c-temple\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"Washington D.C. Temple"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/6067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/comments?post=6067"}],"version-history":[{"count":0,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/6067\/revisions"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/media?parent=6067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":6056,"date":"2022-06-27T12:18:40","date_gmt":"2022-06-27T16:18:40","guid":{"rendered":"http:\/\/dctemple.org\/?page_id=6056"},"modified":"2024-07-22T08:34:48","modified_gmt":"2024-07-22T12:34:48","slug":"expected-behavior-and-policies","status":"publish","type":"page","link":"https:\/\/dctemple.org\/de\/expected-behavior-and-policies\/","title":{"rendered":"Erwartetes Verhalten und Richtlinien"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6056\" class=\"elementor elementor-6056\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d939a77 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d939a77\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dbbac39\" data-id=\"dbbac39\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ecac13 elementor-widget elementor-widget-heading\" data-id=\"0ecac13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Erwartetes Kleid<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e749e32 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e749e32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a0aa39 elementor-widget elementor-widget-image\" data-id=\"2a0aa39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"522\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series.webp\" class=\"attachment-full size-full wp-image-6059\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series.webp 1200w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-300x131.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1024x445.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-768x334.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-18x8.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0df960 elementor-widget elementor-widget-text-editor\" data-id=\"d0df960\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Versuche einfach nett auszusehen. Du kannst gerne in jeder Kleidung kommen, in der du dich wohl f\u00fchlst, solange sie dezent und nicht freiz\u00fcgig ist.<\/p>\n<p>Hemden und Schuhe sind erforderlich.<\/p>\n<p>M\u00e4nner tragen Anz\u00fcge oder Hemden mit Kn\u00f6pfen und Krawatten, Frauen tragen normalerweise Kleider oder R\u00f6cke. Bei diesen Menschen handelt es sich in der Regel um Mitglieder der Kirche, die den Tempel betreten oder an einer Aktivit\u00e4t der Kirche teilnehmen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1684ecc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1684ecc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cb9fb0c\" data-id=\"cb9fb0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94d7789 elementor-widget elementor-widget-heading\" data-id=\"94d7789\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Erwartetes Verhalten<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1da52e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b1da52e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce629f2 elementor-widget elementor-widget-image\" data-id=\"ce629f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"522\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1.webp\" class=\"attachment-full size-full wp-image-6058\" alt=\"\" srcset=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1.webp 1200w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1-300x131.webp 300w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1-1024x445.webp 1024w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1-768x334.webp 768w, https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series-1-18x8.webp 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c047ccc elementor-widget elementor-widget-text-editor\" data-id=\"c047ccc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Das Tempelgel\u00e4nde in Washington DC gilt als heilig und sollte auch so behandelt werden. Bitte seien Sie respektvoll gegen\u00fcber den G\u00e4rten, Geb\u00e4uden und Menschen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ed49f6 elementor-widget elementor-widget-text-editor\" data-id=\"2ed49f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Generelle Richtlinien:<\/p>\n<p>Vermeiden Sie beleidigende oder unangemessene Sprache. Sei nett und h\u00f6flich zu anderen.<\/p>\n<p>Vermeiden Sie grobe Kommentare oder Phrasen. Eine gute Faustregel ist, Ihre Sprache mit PG zu bewerten.<\/p>\n<p>Die G\u00e4rtner geben sich viel M\u00fche, die Anlage sauber und sch\u00f6n zu halten. Bitte hinterlassen Sie keinen M\u00fcll und treten Sie nicht auf die Blumen.<\/p>\n<p>Kein Skateboarden, langes Boarden oder Inline-Skating auf dem Tempelgel\u00e4nde.<\/p>\n<p>Sie k\u00f6nnen gerne Fotos und Videos machen. Bitte seien Sie beim Fotografieren respektvoll gegen\u00fcber anderen und respektieren Sie deren Privatsph\u00e4re. Fragen Sie um Erlaubnis, bevor Sie Fotos von anderen Personen machen.<\/p>\n<p>Vermeiden Sie Schreien oder Schreien. Das Tempelgel\u00e4nde ist ein Ort der Ruhe und Meditation. Sie k\u00f6nnen frei sprechen, aber denken Sie an diejenigen um Sie herum, die kommen, um den Geist des Gel\u00e4ndes zu genie\u00dfen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Expected Dress Just try to look nice. You\u2019re welcome to come in any clothes you feel comfortable in as long as they are modest and not revealing. Shirts and shoes are required. You\u2019ll see men wear suits or button-up shirts and ties, women typically wear dresses or skirts. These people are generally members of the [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"footnotes":""},"class_list":["post-6056","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Expected Behavior and policies - DCTemple.org<\/title>\n<meta name=\"description\" content=\"See expected behavior and policies for visiting the Washington DC Temple grounds. All are welcome, so please be respectful during your visit.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/de\/expected-behavior-and-policies\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expected Behavior and policies - DCTemple.org\" \/>\n<meta property=\"og:description\" content=\"See expected behavior and policies for visiting the Washington DC Temple grounds. All are welcome, so please be respectful during your visit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/de\/expected-behavior-and-policies\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-22T12:34:48+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/expected-behavior-and-policies\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/expected-behavior-and-policies\\\/\",\"name\":\"Expected Behavior and policies - DCTemple.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/expected-behavior-and-policies\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/expected-behavior-and-policies\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/DC-Banner-Series.jpg\",\"datePublished\":\"2022-06-27T16:18:40+00:00\",\"dateModified\":\"2024-07-22T12:34:48+00:00\",\"description\":\"See expected behavior and policies for visiting the Washington DC Temple grounds. All are welcome, so please be respectful during your visit.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/expected-behavior-and-policies\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/expected-behavior-and-policies\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/expected-behavior-and-policies\\\/#primaryimage\",\"url\":\"http:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/DC-Banner-Series.jpg\",\"contentUrl\":\"http:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/DC-Banner-Series.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/expected-behavior-and-policies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Expected Behavior and policies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erwartetes Verhalten und Richtlinien - DCTemple.org","description":"Informieren Sie sich \u00fcber die Verhaltensregeln und Richtlinien f\u00fcr den Besuch des Washington DC-Tempelgel\u00e4ndes. Alle sind willkommen. Bitte verhalten Sie sich w\u00e4hrend Ihres Besuchs respektvoll.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/de\/expected-behavior-and-policies\/","og_locale":"de_DE","og_type":"article","og_title":"Expected Behavior and policies - DCTemple.org","og_description":"See expected behavior and policies for visiting the Washington DC Temple grounds. All are welcome, so please be respectful during your visit.","og_url":"https:\/\/dctemple.org\/de\/expected-behavior-and-policies\/","og_site_name":"DCTemple.org","article_modified_time":"2024-07-22T12:34:48+00:00","og_image":[{"url":"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/expected-behavior-and-policies\/","url":"https:\/\/dctemple.org\/expected-behavior-and-policies\/","name":"Expected Behavior and policies - DCTemple.org","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dctemple.org\/expected-behavior-and-policies\/#primaryimage"},"image":{"@id":"https:\/\/dctemple.org\/expected-behavior-and-policies\/#primaryimage"},"thumbnailUrl":"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series.jpg","datePublished":"2022-06-27T16:18:40+00:00","dateModified":"2024-07-22T12:34:48+00:00","description":"See expected behavior and policies for visiting the Washington DC Temple grounds. All are welcome, so please be respectful during your visit.","breadcrumb":{"@id":"https:\/\/dctemple.org\/expected-behavior-and-policies\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/expected-behavior-and-policies\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dctemple.org\/expected-behavior-and-policies\/#primaryimage","url":"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series.jpg","contentUrl":"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Banner-Series.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/expected-behavior-and-policies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"Expected Behavior and policies"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/6056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/comments?post=6056"}],"version-history":[{"count":0,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/6056\/revisions"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/media?parent=6056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":5961,"date":"2022-06-27T11:33:45","date_gmt":"2022-06-27T15:33:45","guid":{"rendered":"http:\/\/dctemple.org\/?page_id=5961"},"modified":"2024-07-23T09:28:31","modified_gmt":"2024-07-23T13:28:31","slug":"visit","status":"publish","type":"page","link":"https:\/\/dctemple.org\/de\/visit\/","title":{"rendered":"Besuch"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"5961\" class=\"elementor elementor-5961\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ff92c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ff92c4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf8521a\" data-id=\"bf8521a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6dd83fb elementor-widget elementor-widget-heading\" data-id=\"6dd83fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Dinge die zu tun sind<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0cb1aa elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c0cb1aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50a2120 elementor-widget elementor-widget-text-editor\" data-id=\"50a2120\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Alle Aktivit\u00e4ten sind familienfreundlich und offen f\u00fcr alle. Das Tempelgel\u00e4nde ist ein heiliger Ort. Wir lieben es zu lachen, zu l\u00e4cheln und Spa\u00df zu haben. Wir bitten darum, dass das Tempelgel\u00e4nde mit Freundlichkeit und Respekt behandelt wird. Weitere Informationen zu erwartetem Verhalten und Richtlinien finden Sie unter <a href=\"https:\/\/dctemple.org\/de\/expected-behavior-and-policies\/\" rel=\"noopener\">Klick hier.<\/a><\/p><p>Das Betreten des Tempels selbst ist nur Mitgliedern mit aktivem Tempelschein vorbehalten (<a href=\"https:\/\/dctemple.org\/de\/washington-d-c-temple\/\" rel=\"noopener\">Weitere Details hier<\/a>).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e76f345 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e76f345\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-08bb4ea\" data-id=\"08bb4ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fede4fd elementor-widget elementor-widget-pp-flipbox\" data-id=\"fede4fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-flipbox.default\">\n\t\t\t\t\t\t\t<div class=\"pp-flipbox-container pp-animate-flip pp-direction-right\">\n\t\t\t<div class=\"pp-flipbox-flip-card\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-front\">\n\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t<div class=\"pp-flipbox-icon-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-10.webp\" alt=\"DC-Flip-Card-Bilder (10)\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<h1 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\tKostenlose Touren\t\t\t\t\t<\/h1>\n\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"pp-flipbox-back\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\t\tBesichtigen Sie das Besucherzentrum und das Tempelgel\u00e4nde\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\tGenie\u00dfen Sie eine gef\u00fchrte Tour mit einem unserer freundlichen Freiwilligen. Auf der Tour erhalten Sie einen Einblick in die besten Aussichten, erkunden das Gel\u00e4nde, werden durch interaktive Displays gef\u00fchrt und haben eine erstaunliche Erfahrung mit Thorvaldsens Christus.\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-172c63a\" data-id=\"172c63a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0ed50c elementor-widget elementor-widget-pp-flipbox\" data-id=\"c0ed50c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-flipbox.default\">\n\t\t\t\t\t\t\t<div class=\"pp-flipbox-container pp-animate-flip pp-direction-right\">\n\t\t\t<div class=\"pp-flipbox-flip-card\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-front\">\n\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t<div class=\"pp-flipbox-icon-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-11.webp\" alt=\"DC-Flip-Card-Bilder (11)\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<h1 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\tInteraktiv<br> Anzeigen\t\t\t\t\t<\/h1>\n\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"pp-flipbox-back\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\t\tInteraktive Ausstellungen und Displays\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\tGenie\u00dfen Sie interaktive Ausstellungen, die Spa\u00df machen und familienfreundlich sind. Jede Ausstellung hilft Familien, etwas \u00fcber Gottes Plan, Gebet und andere erhebende Erfahrungen zu erfahren.<br> Neben Exponaten gibt es Videos f\u00fcr Familien zu genie\u00dfen. Videos und interaktive Exponate sind in mehreren Sprachen verf\u00fcgbar.\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5aadf1a\" data-id=\"5aadf1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9636aee elementor-widget elementor-widget-pp-flipbox\" data-id=\"9636aee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-flipbox.default\">\n\t\t\t\t\t\t\t<div class=\"pp-flipbox-container pp-animate-flip pp-direction-right\">\n\t\t\t<div class=\"pp-flipbox-flip-card\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-front\">\n\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t<div class=\"pp-flipbox-icon-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-9.webp\" alt=\"DC-Flip-Card-Bilder (9)\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<h1 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\tKunst &amp; Wandbilder\t\t\t\t\t<\/h1>\n\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"pp-flipbox-back\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\t\tLernen Sie Christus durch Kunst kennen\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\tVerfolgen Sie das Leben Christi durch Gem\u00e4lde im Geb\u00e4ude und interagieren Sie mit spannenden Exponaten. Denken Sie \u00fcber die Majest\u00e4t und das Wunder von Gottes Sch\u00f6pfungen nach und denken Sie \u00fcber die Einladung der ausgestreckten Arme von Thorvaldsens Christus nach, einer pr\u00e4chtigen 11-Fu\u00df-Statue des Erl\u00f6sers.\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7be44eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7be44eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dcb3d97\" data-id=\"dcb3d97\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4115c2 elementor-widget elementor-widget-pp-flipbox\" data-id=\"b4115c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-flipbox.default\">\n\t\t\t\t\t\t\t<div class=\"pp-flipbox-container pp-animate-flip pp-direction-right\">\n\t\t\t<div class=\"pp-flipbox-flip-card\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-front\">\n\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t<div class=\"pp-flipbox-icon-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-8.webp\" alt=\"DC-Flip-Card-Bilder (8)\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<h1 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\tKuratierte G\u00e4rten\t\t\t\t\t<\/h1>\n\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"pp-flipbox-back\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\t\tErkunden Sie die G\u00e4rten\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\tDer Washington-DC-Tempel befindet sich auf einem 52 Hektar gro\u00dfen H\u00fcgel mit W\u00e4ldern, Solit\u00e4rb\u00e4umen und wundersch\u00f6nen Blumeng\u00e4rten.<br>Die G\u00e4rten sollen ein friedlicher Ort zum Ausruhen, Nachdenken und gem\u00fctlichen Spazierengehen sein.\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e9adf30\" data-id=\"e9adf30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c754afd elementor-widget elementor-widget-pp-flipbox\" data-id=\"c754afd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-flipbox.default\">\n\t\t\t\t\t\t\t<div class=\"pp-flipbox-container pp-animate-flip pp-direction-right\">\n\t\t\t<div class=\"pp-flipbox-flip-card\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-front\">\n\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t<div class=\"pp-flipbox-icon-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-7.webp\" alt=\"DC-Flip-Card-Bilder (7)\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<h1 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\tInspirierende Ansichten\t\t\t\t\t<\/h1>\n\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"pp-flipbox-back\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\t\tPerspektive gewinnen\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\tDer Washington-DC-Tempel erhebt sich pr\u00e4chtig gegen den Himmel, entweder bei Tageslicht oder bei Nachtbeleuchtung. Genie\u00dfen Sie die Ruhe der G\u00e4rten, den flie\u00dfenden Springbrunnen und die inspirierende Aussicht.\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5155541\" data-id=\"5155541\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b71115d elementor-widget elementor-widget-pp-flipbox\" data-id=\"b71115d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-flipbox.default\">\n\t\t\t\t\t\t\t<div class=\"pp-flipbox-container pp-animate-flip pp-direction-right\">\n\t\t\t<div class=\"pp-flipbox-flip-card\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-front\">\n\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t<div class=\"pp-flipbox-icon-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-6.webp\" alt=\"DC-Flip-Card-Bilder (6)\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<h1 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\tFotografie\t\t\t\t\t<\/h1>\n\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"pp-flipbox-back\">\n\t\t\t\t\t\t<div class=\"pp-flipbox-overlay\">\n\t\t\t\t<div class=\"pp-flipbox-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"pp-flipbox-heading\">\n\t\t\t\t\t\t\tHalte den Moment fest\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-flipbox-content\">\n\t\t\t\t\t\tAtemberaubende Architektur, wundersch\u00f6ne G\u00e4rten und flie\u00dfende Springbrunnen machen den Washington DC Temple perfekt zum Fotografieren. Fotografen k\u00f6nnen das Gel\u00e4nde gerne f\u00fcr Fotoshootings nutzen. Es gibt keine Eintrittsgeb\u00fchr oder Fotogeb\u00fchr. \n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8991bbd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8991bbd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c752d05\" data-id=\"c752d05\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31d5f17 elementor-widget elementor-widget-heading\" data-id=\"31d5f17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Machen Sie eine Tour<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97fe432 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"97fe432\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5c111b elementor-widget elementor-widget-text-editor\" data-id=\"e5c111b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nehmen Sie an einer F\u00fchrung mit einer unserer Schwestermissionarinnen teil. Auf der Tour erhalten Sie einen Einblick in die sch\u00f6nsten Ausblicke, genie\u00dfen das friedliche Reflexionsbecken und die Springbrunnen, werden durch interaktive Ausstellungen gef\u00fchrt und erleben ein unvergessliches Erlebnis mit Thorvaldsen&#039;s <i>Christus.<\/i><\/p><p>Lernen Sie die besten Orte f\u00fcr Selfies und Fotoaufnahmen, die drei besten Ausblicke auf den Tempel und die verborgenen Sch\u00e4tze des Washington DC-Tempels kennen. Diese F\u00fchrungen sind kostenlos und es ist keine Terminvereinbarung erforderlich. Wenn Sie einen virtuellen Rundgang vereinbaren m\u00f6chten, klicken Sie bitte auf die Schaltfl\u00e4che unten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-121873d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"121873d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/clickly.org\/6go85\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Planen Sie eine virtuelle Tour<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4169678 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4169678\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-96433c5\" data-id=\"96433c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f2aa70 elementor-widget elementor-widget-spacer\" data-id=\"1f2aa70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0b3c86 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0b3c86\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-313e9e7\" data-id=\"313e9e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3eeca49 elementor-widget elementor-widget-html\" data-id=\"3eeca49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<h2 id=\"visitvc\" style=\"text-align:center;\">Besucherzentrum des Washington DC Tempels<\/h2>\n<center><hr style=\"width:6%;color:#FFD084;padding-bottom:15px;padding-top:15px;border-width:3.3px;\"><\/center>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a13abc elementor-widget elementor-widget-spacer\" data-id=\"7a13abc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7831ef0b elementor-section-content-middle elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7831ef0b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-18b2346d\" data-id=\"18b2346d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-110b3fdc elementor-widget elementor-widget-google_maps\" data-id=\"110b3fdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Washington%20D.C.%20Temple%20Visitors%27%20Center&#038;t=m&#038;z=17&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Besucherzentrum des Washington DC Tempels\"\n\t\t\t\t\taria-label=\"Besucherzentrum des Washington DC Tempels\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-50080dfd\" data-id=\"50080dfd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-145826f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"145826f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-33d58541\" data-id=\"33d58541\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-764a14b2 elementor-widget elementor-widget-heading\" data-id=\"764a14b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Ort<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3175dc77 elementor-widget elementor-widget-text-editor\" data-id=\"3175dc77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>9900 StoneybrookDr.\u00a0<br \/>Kensington, MD 20895<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2b2cdd65\" data-id=\"2b2cdd65\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ea4f26 elementor-widget elementor-widget-heading\" data-id=\"9ea4f26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Kontaktiere uns<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e0fd02c elementor-widget elementor-widget-text-editor\" data-id=\"2e0fd02c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tTelefon : <a href=\"tel:+1-301-587-0144\">+ 1 301 587 0144<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ed28bde elementor-widget elementor-widget-text-editor\" data-id=\"2ed28bde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Email : <a href=\"mailto:wdcvisitorscenter@gmail.com\">wdcvisitorscenter@gmail.com<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-377f1a21 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"377f1a21\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6b6a9ff5\" data-id=\"6b6a9ff5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54c0836f elementor-widget elementor-widget-heading\" data-id=\"54c0836f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Unsere Stunden<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31e4d55b elementor-widget elementor-widget-text-editor\" data-id=\"31e4d55b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tSieben Tage die Woche\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68648e0d elementor-widget elementor-widget-text-editor\" data-id=\"68648e0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>10:00 \u2013 21:00 Uhr<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-57a8034d\" data-id=\"57a8034d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5693c4a0 elementor-widget elementor-widget-heading\" data-id=\"5693c4a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Folge uns<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13d1b088 elementor-shape-square e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"13d1b088\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-animation-grow elementor-repeater-item-2d0da0c\" href=\"https:\/\/www.facebook.com\/dctemplevisitorscenter\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook-f\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M279.14 288l14.22-92.66h-88.91v-60.13c0-25.35 12.42-50.06 52.24-50.06h40.42V6.26S260.43 0 225.36 0c-73.22 0-121.08 44.38-121.08 124.72v70.62H22.89V288h81.39v224h100.17V288z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-grow elementor-repeater-item-af38224\" href=\"https:\/\/www.instagram.com\/dctemplevisitorscenter\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-envelope elementor-animation-grow elementor-repeater-item-914746e\" href=\"mailto:wdcvisitorscenter@gmail.com\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Umschlag<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.3 190.8c3.9-3.1 9.7-.2 9.7 4.7V400c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V195.6c0-5 5.7-7.8 9.7-4.7 22.4 17.4 52.1 39.5 154.1 113.6 21.1 15.4 56.7 47.8 92.2 47.6 35.7.3 72-32.8 92.3-47.6 102-74.1 131.6-96.3 154-113.7zM256 320c23.2.4 56.6-29.2 73.4-41.4 132.7-96.3 142.8-104.7 173.4-128.7 5.8-4.5 9.2-11.5 9.2-18.9v-19c0-26.5-21.5-48-48-48H48C21.5 64 0 85.5 0 112v19c0 7.4 3.4 14.3 9.2 18.9 30.6 23.9 40.7 32.4 173.4 128.7 16.8 12.2 50.2 41.8 73.4 41.4z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-animation-grow elementor-repeater-item-d138417\" href=\"https:\/\/www.youtube.com\/channel\/UCbTvEqM1-VcgfruzKbG9S9Q\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ad08e17 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad08e17\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-76cf388\" data-id=\"76cf388\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58c5919 elementor-widget elementor-widget-text-editor\" data-id=\"58c5919\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><em>Saubere Toiletten stehen im Besucherzentrum zur Verf\u00fcgung. <\/em><em>Gratis Parkpl\u00e4tze.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f654e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f654e2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b3a0686\" data-id=\"b3a0686\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd0d7ea elementor-widget elementor-widget-heading\" data-id=\"dd0d7ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bildergalerien<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-280c2a8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"280c2a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb24bba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb24bba\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3bd78f8\" data-id=\"3bd78f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e62bd3 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"1e62bd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-756de23 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"washington-dc-temple-spring-1160328-wallpaper cropped-27\"><\/div><div class=\"elementor-background-overlay\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/dctemple.org\/de\/temple-exterior-gallery\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-xs\">TEMPEL AUSSEN<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3150782\" data-id=\"3150782\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47d4acd elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"47d4acd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-756de23 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"20.01.29 DC Temple - celestial\"><\/div><div class=\"elementor-background-overlay\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/dctemple.org\/de\/interior-renderings\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">INNENRAUMWERTE<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1032f6c\" data-id=\"1032f6c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-271232e elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"271232e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-756de23 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Screenshot 29.12.2021 um 22:58:52 Uhr\"><\/div><div class=\"elementor-background-overlay\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/dctemple.org\/de\/history-gallery\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">GESCHICHTE<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-501faec\" data-id=\"501faec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1345b3d elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"1345b3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-756de23 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"The Morning Breaks Cropped 3-28\"><\/div><div class=\"elementor-background-overlay\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/dctemple.org\/de\/original-artwork\/\" target=\"_blank\"><div class=\"swiper-slide-contents\"><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">ORIGINALKUNST<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fecb8cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fecb8cf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4cea9b4\" data-id=\"4cea9b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe4c509 elementor-widget elementor-widget-spacer\" data-id=\"fe4c509\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a54875 elementor-widget elementor-widget-heading\" data-id=\"1a54875\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">H\u00e4ufig gestellte Fragen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75fccc3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"75fccc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8860e1 elementor-widget elementor-widget-global elementor-global-1724 elementor-widget-toggle\" data-id=\"e8860e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2431\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2431\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ist das der \u201eMormonen\u201c-Tempel auf der Umgehungsstra\u00dfe?\u200b<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2431\"><p>Dieses heilige Geb\u00e4ude wurde oft als \u201eMormonentempel\u201c bezeichnet. Im Jahr 2018 korrigierte der Prophet und Pr\u00e4sident der Kirche, Russell M. Nelson, jedoch jeden falschen Namen der Kirche Jesu Christi der Heiligen der Letzten Tage, einschlie\u00dflich der unangemessenen Bezugnahme auf die \u201eMormonenkirche\u201c. Mormon war ein gro\u00dfer Prophet, den wir ehren, aber die Kirche wurde nach unserem Erretter Jesus Christus benannt. Der korrekte Name der Kirche lautet: Die Kirche Jesu Christi der Heiligen der Letzten Tage. Daher ist der richtige Name des Tempels \u201eWashington DC Temple of The Church of Jesus Christ of Latter-day Saints\u201c.\u00a0<\/p><p>Der Hinweis auf \u201eHeilige\u201c im Namen der Kirche verweist auf die Verwendung des Apostels Paulus f\u00fcr Menschen, die versuchen, den Lehren Jesu Christi zu folgen.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2432\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2432\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ist der Washington DC Temple noch f\u00fcr F\u00fchrungen ge\u00f6ffnet? <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2432\"><p>Pers\u00f6nliche F\u00fchrungen durch das Innere des Washington-DC-Tempels endeten offiziell am 11. Juni 2022, aber es gibt noch viele M\u00f6glichkeiten, den Tempel zu besichtigen. Sie k\u00f6nnen eine nehmen <a href=\"https:\/\/www.youtube.com\/watch?v=BSV4BrjDJU4\">Virtueller 360-Grad-Rundgang<\/a> des Innenraums hier, nehmen Sie die <a href=\"https:\/\/www.youtube.com\/watch?v=mUYF1TX5RxM\">virtuelle Tour<\/a> hier, oder sehen Sie sich Bilder des Tempelinneren an <a href=\"https:\/\/dctemple.org\/de\/galleries\/temple-interior\/\">hier<\/a>. Sie k\u00f6nnen auch die Au\u00dfenseite und das Gel\u00e4nde des Tempels besichtigen und eine inspirierende Nachbildung davon genie\u00dfen <em>Christus<\/em> Statue, interaktive Ausstellungen, Aktivit\u00e4ten und Veranstaltungen, die familienfreundlich und kostenlos im Besucherzentrum des Tempels sind. Das Besucherzentrum ist das ganze Jahr \u00fcber von 10 bis 21 Uhr an sieben Tagen in der Woche f\u00fcr die \u00d6ffentlichkeit zug\u00e4nglich.<\/p><p>Zur Weihnachtszeit wird das Gel\u00e4nde w\u00e4hrend des Festival of Lights erleuchtet, das n\u00e4chtliche Konzerte, eine lebensgro\u00dfe Krippe und internationale Weihnachtskrippen bietet.<\/p><p><a href=\"https:\/\/dctemple.org\/de\/\">Abonnieren Sie unseren Newsletter<\/a> Seien Sie der Erste, der von unseren neuesten Veranstaltungen erf\u00e4hrt.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2433\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2433\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ich konnte nicht am Tag der offenen T\u00fcr teilnehmen. Gibt es eine virtuelle Tour-Option?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2433\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2433\"><p>Ja! <a href=\"https:\/\/www.youtube.com\/watch?v=mUYF1TX5RxM&amp;feature=emb_imp_woyt\">Hier klicken<\/a> f\u00fcr eine virtuelle Tour durch den Washington-DC-Tempel unter der Leitung von Elder und Schwester Stevenson und Elder und Schwester Renlund.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2434\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2434\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Hat das Besucherzentrum noch ge\u00f6ffnet?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2434\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2434\"><p>Das Besucherzentrum ist jetzt das ganze Jahr \u00fcber sieben Tage die Woche von 10 bis 21 Uhr f\u00fcr die \u00d6ffentlichkeit zug\u00e4nglich. Kommen Sie und genie\u00dfen Sie die Au\u00dfenfassade und das Gel\u00e4nde des Tempels und sehen Sie sich eine inspirierende Nachbildung des Tempels an <em>Christus<\/em> Statue und genie\u00dfen Sie interaktive Ausstellungen, Aktivit\u00e4ten und Veranstaltungen, die familienfreundlich und kostenlos sind.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2435\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2435\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wann ist das Lichterfest?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2435\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2435\"><p>Jedes Jahr um die Weihnachtszeit wird das Gel\u00e4nde w\u00e4hrend des Festival of Lights erleuchtet, das n\u00e4chtliche Konzerte, eine lebensgro\u00dfe Krippe und internationale Weihnachtskrippen bietet.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2436\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2436\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Warum werden Tempel gebaut und was passiert im Inneren?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2436\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2436\"><p>Besuchen Sie unser <a href=\"https:\/\/dctemple.org\/de\/about\/\">\u00dcber Seite<\/a> um alles dar\u00fcber zu erfahren, warum Tempel gebaut werden und was darin passiert.\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2437\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2437\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Warum bauen Heilige der Letzten Tage Tempel?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2437\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2437\"><p>Die Kirche Jesu Christi der Heiligen der Letzten Tage baut seit den 1830er Jahren Tempel. Tempel der Heiligen der Letzten Tage gelten als H\u00e4user Gottes, als ein Ort der Heiligkeit und des Friedens, der von den Sorgen der Welt getrennt ist. Sie bieten einen Ort, an dem die Mitglieder der Kirche Gott formelle Versprechen und Verpflichtungen eingehen. Sie sind auch der Ort, an dem die h\u00f6chsten Sakramente des Glaubens stattfinden \u2013 die Eheschlie\u00dfung von Paaren und die \u201eSiegelung\u201c der Familie f\u00fcr die Ewigkeit.<\/p><p>Erfahren Sie mehr auf der <a href=\"https:\/\/dctemple.org\/de\/about\/\">\u00dcber Seite.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2438\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-2438\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-down\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ich habe weitere Fragen, wie bekomme ich diese beantwortet? <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2438\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-2438\"><div>Bei weiteren Fragen schreiben Sie uns bitte an\u00a0<a href=\"mailto:wdcvisitorscenter@gmail.com\" target=\"_blank\" rel=\"noopener\">wdcvisitorscenter@gmail.com<\/a>. Wir werden so schnell wie m\u00f6glich antworten, voraussichtlich innerhalb von 24 Stunden.<\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e2e22d elementor-widget elementor-widget-spacer\" data-id=\"2e2e22d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Things To Do All activities are family-friendly and open to all. The temple grounds are a sacred place. We love to laugh, smile, and have fun. We ask that the temple grounds be treated with kindness and respect. For more information about expected behavior and policies, click here. Entering the temple itself is reserved only [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"footnotes":""},"class_list":["post-5961","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visit - DCTemple.org<\/title>\n<meta name=\"description\" content=\"Plan your visit to the Washington DC Temple and feel the peace of Jesus Christ as you stroll around the gardens and see the Visitors&#039; Center.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/de\/visit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visit - DCTemple.org\" \/>\n<meta property=\"og:description\" content=\"Plan your visit to the Washington DC Temple and feel the peace of Jesus Christ as you stroll around the gardens and see the Visitors&#039; Center.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/de\/visit\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-23T13:28:31+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-10.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/visit\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/visit\\\/\",\"name\":\"Visit - DCTemple.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/visit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/visit\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/DC-Flip-Card-Images-10.jpg\",\"datePublished\":\"2022-06-27T15:33:45+00:00\",\"dateModified\":\"2024-07-23T13:28:31+00:00\",\"description\":\"Plan your visit to the Washington DC Temple and feel the peace of Jesus Christ as you stroll around the gardens and see the Visitors' Center.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/visit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/visit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/visit\\\/#primaryimage\",\"url\":\"http:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/DC-Flip-Card-Images-10.jpg\",\"contentUrl\":\"http:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/DC-Flip-Card-Images-10.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/visit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Besuchen Sie - DCTemple.org","description":"Planen Sie Ihren Besuch im Washington DC-Tempel und sp\u00fcren Sie den Frieden Jesu Christi, w\u00e4hrend Sie durch die G\u00e4rten schlendern und das Besucherzentrum besichtigen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/de\/visit\/","og_locale":"de_DE","og_type":"article","og_title":"Visit - DCTemple.org","og_description":"Plan your visit to the Washington DC Temple and feel the peace of Jesus Christ as you stroll around the gardens and see the Visitors' Center.","og_url":"https:\/\/dctemple.org\/de\/visit\/","og_site_name":"DCTemple.org","article_modified_time":"2024-07-23T13:28:31+00:00","og_image":[{"url":"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-10.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"6 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/visit\/","url":"https:\/\/dctemple.org\/visit\/","name":"Visit - DCTemple.org","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dctemple.org\/visit\/#primaryimage"},"image":{"@id":"https:\/\/dctemple.org\/visit\/#primaryimage"},"thumbnailUrl":"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-10.jpg","datePublished":"2022-06-27T15:33:45+00:00","dateModified":"2024-07-23T13:28:31+00:00","description":"Plan your visit to the Washington DC Temple and feel the peace of Jesus Christ as you stroll around the gardens and see the Visitors' Center.","breadcrumb":{"@id":"https:\/\/dctemple.org\/visit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/visit\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dctemple.org\/visit\/#primaryimage","url":"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-10.jpg","contentUrl":"http:\/\/dctemple.org\/wp-content\/uploads\/2022\/06\/DC-Flip-Card-Images-10.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/visit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"Visit"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/5961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/comments?post=5961"}],"version-history":[{"count":0,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/5961\/revisions"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/media?parent=5961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":4260,"date":"2022-04-14T18:56:55","date_gmt":"2022-04-14T22:56:55","guid":{"rendered":"http:\/\/dctemple.org\/?page_id=4260"},"modified":"2024-07-19T13:16:18","modified_gmt":"2024-07-19T17:16:18","slug":"asl-tour","status":"publish","type":"page","link":"https:\/\/dctemple.org\/de\/asl-tour\/","title":{"rendered":"ASL-Tour"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4260\" class=\"elementor elementor-4260\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2120af7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2120af7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c7940fd\" data-id=\"c7940fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2298533 elementor-widget elementor-widget-text-editor\" data-id=\"2298533\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #000000;\">Sprache:<\/span> \u00a0<a href=\"https:\/\/dctemple.org\/asl-tour\/\">ASL\u00a0 <\/a><span style=\"color: #999999;\">|\u00a0<\/span> <a href=\"https:\/\/dctemple.org\/zh\/open-house-tour\/\">Chinesisch<\/a>\u00a0 <span style=\"color: #999999;\">|\u00a0<\/span> <a href=\"https:\/\/dctemple.org\/en\/open-house-tour\/\">Englisch\u00a0 <span style=\"color: #999999;\">|\u00a0<\/span><\/a>\u00a0\u00a0<a href=\"https:\/\/dctemple.org\/fr\/open-house-tour\/\">Franz\u00f6sisch<\/a><a href=\"https:\/\/www.youtube.com\/watch?v=pmarf921mkA\">\u00a0\u00a0<span style=\"color: #999999;\">|\u00a0<\/span><\/a>\u00a0\u00a0<a href=\"https:\/\/dctemple.org\/de\/open-house-tour\/\">Deutsch<\/a><a href=\"https:\/\/www.youtube.com\/watch?v=pmarf921mkA\">\u00a0\u00a0<span style=\"color: #999999;\">|\u00a0<\/span><\/a><a href=\"https:\/\/dctemple.org\/de\/open-house-tour\/\">\u00a0\u00a0<\/a><a href=\"https:\/\/dctemple.org\/ja\/open-house-tour\/\">japanisch<\/a><a href=\"https:\/\/www.youtube.com\/watch?v=pmarf921mkA\">\u00a0\u00a0<span style=\"color: #999999;\">|\u00a0<\/span><\/a><a href=\"https:\/\/dctemple.org\/de\/open-house-tour\/\">\u00a0\u00a0<\/a><a href=\"https:\/\/dctemple.org\/ko\/open-house-tour\/\">Koreanisch<\/a><a href=\"https:\/\/www.youtube.com\/watch?v=pmarf921mkA\">\u00a0\u00a0<span style=\"color: #999999;\">|\u00a0<\/span><\/a><a href=\"https:\/\/dctemple.org\/de\/open-house-tour\/\">\u00a0\u00a0<\/a><a href=\"https:\/\/dctemple.org\/fa\/open-house-tour\/\">persisch<\/a><a href=\"https:\/\/youtu.be\/xHtTp0UbBvE\"> <span style=\"color: #999999;\">|\u00a0<\/span><\/a> \u00a0<a href=\"https:\/\/dctemple.org\/pt\/open-house-tour\/\">Portugiesisch Brasilianisch <span style=\"color: #999999;\">|\u00a0<\/span><\/a>\u00a0\u00a0<a href=\"https:\/\/dctemple.org\/es\/open-house-tour\/\">Spanisch<\/a><a href=\"https:\/\/www.youtube.com\/watch?v=pmarf921mkA\">\u00a0\u00a0<span style=\"color: #999999;\">|\u00a0<\/span><\/a><a href=\"https:\/\/dctemple.org\/es\/open-house-tour\/\">\u00a0\u00a0<\/a><a href=\"https:\/\/dctemple.org\/tl\/open-house-tour\/\">Tagalog<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8d5b6eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8d5b6eb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41b0524\" data-id=\"41b0524\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e064bb elementor-widget elementor-widget-spacer\" data-id=\"0e064bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4a683e elementor-widget elementor-widget-text-editor\" data-id=\"a4a683e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #223661;\">DAS HAUS DES HERRN<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97cbacd elementor-widget elementor-widget-text-editor\" data-id=\"97cbacd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" contenteditable=\"true\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\">Washington D.C. Temple\u200b<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d199f8 elementor-widget elementor-widget-text-editor\" data-id=\"2d199f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #223661;\">DIE KIRCHE JESU CHRISTI DER HEILIGEN DER LETZTEN TAGE<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5e8009 elementor-widget elementor-widget-text-editor\" data-id=\"e5e8009\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #223661;\">American Sign Language <br \/>Self-Guided Tour<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1732572 elementor-widget elementor-widget-spacer\" data-id=\"1732572\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74007ed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74007ed\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-15d1bed\" data-id=\"15d1bed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42da297 elementor-widget elementor-widget-spacer\" data-id=\"42da297\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50e509e elementor-widget elementor-widget-heading\" data-id=\"50e509e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><h3 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\" style=\"letter-spacing: normal;text-align: center\">Einf\u00fchrung<\/h3><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9a7949 elementor-widget elementor-widget-video\" data-id=\"b9a7949\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/sbdQ4hoZlQA&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6969147 elementor-widget elementor-widget-text-editor\" data-id=\"6969147\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>As members of The Church of Jesus Christ of Latter-day Saints, we worship God and His Son, Jesus Christ. We come to the house of the Lord to learn about them and promise to follow their commandments. Like biblical temples, modern temples are places of peace, love and connection. Temples also are places where sacred religious ceremonies are performed<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28bec39 elementor-widget elementor-widget-spacer\" data-id=\"28bec39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c39f8a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c39f8a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22a247f\" data-id=\"22a247f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ece17d elementor-widget elementor-widget-spacer\" data-id=\"5ece17d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c2e869 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c2e869\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0651c85\" data-id=\"0651c85\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-affb8bb elementor-widget elementor-widget-heading\" data-id=\"affb8bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><h3 data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\" style=\"letter-spacing: normal\">1. Das Templescheinpult<\/h3><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9065c9 elementor-widget elementor-widget-video\" data-id=\"a9065c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/2UwYp0_vbg0&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a0c6ff elementor-widget elementor-widget-text-editor\" data-id=\"1a0c6ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 W\u00e4hrend des Tages der offenen T\u00fcr laden wir alle ein, in den Tempel zu kommen und sich \u00fcber seinen Zweck zu informieren.<\/p><p>\u2022 Sobald ein Tempel geweiht wurde, ist der Zutritt den Mitgliedern der Kirche vorbehalten, die gelobt haben, das Evangelium Jesu Christi zu leben, und bereit sind, an weiteren heiligen Handlungen teilzunehmen. An diesem Pult im Eingangsfoyer werden die Mitglieder begr\u00fc\u00dft, und sie legen eine kleine Karte vor, den sogenannten Tempelschein. Den Tempelschein stellt ihnen der f\u00fcr sie zust\u00e4ndige F\u00fchrungsbeamte der Kirche aus und best\u00e4tigt damit, dass sie bereit sind, in den Tempel zu gehen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0620507 elementor-widget elementor-widget-spacer\" data-id=\"0620507\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44adcd9 elementor-widget elementor-widget-heading\" data-id=\"44adcd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2. Baptistry\u200b<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-545734b elementor-widget elementor-widget-video\" data-id=\"545734b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/niHjsPVXbzo&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1543f0f elementor-widget elementor-widget-text-editor\" data-id=\"1543f0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Jesus Christus selbst wurde getauft und lehrte uns, dass die Taufe erforderlich ist, um in das Reich Gottes einzutreten (Johannes 3).<\/p><p>\u2022 In unseren kirchlichen Versammlungsh\u00e4usern werden Taufen f\u00fcr Lebende ab dem achten Lebensjahr vollzogen.<\/p><p>\u2022 Durch Familienforschung identifizieren wir auch unsere Vorfahren und f\u00fchren in ihrem Namen Taufen in unserem Tempel durch.<\/p><p>\u2022 Diese Taufe ist ein Opfer der Liebe. Wir glauben, dass es den Verstorbenen freisteht, dieses Geschenk der Taufe anzunehmen oder abzulehnen.<\/p><p>\u2022 In 1. Korinther 15:29 lehrt der Apostel Paulus das wir uns f\u00fcr Verstorbene taufen lassen k\u00f6nnen.<\/p><p>\u2022 Das Taufbecken \u00e4hnelt dem Taufbecken in Salomons Tempel, das in der Bibel beschrieben wird (1. K\u00f6nige 7:25).<\/p><p>\u2022 The 12 oxen symbolize the 12 tribes of Israel spoken about in the Old Testament<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26a5df7 elementor-widget elementor-widget-spacer\" data-id=\"26a5df7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad6de95 elementor-widget elementor-widget-heading\" data-id=\"ad6de95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3. Die Umkleider\u00e4ume<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4add4dd elementor-widget elementor-widget-video\" data-id=\"4add4dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/eyWra9VXnv8&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d33fd7 elementor-widget elementor-widget-text-editor\" data-id=\"1d33fd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Mitglieder wechseln im Tempel von Alltagskleidung zu wei\u00dfer Kleidung. Diese Kleidung ist ein Symbol daf\u00fcr, dass alle vor Gott gleich sind.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-443754b elementor-widget elementor-widget-spacer\" data-id=\"443754b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0418539 elementor-widget elementor-widget-heading\" data-id=\"0418539\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4. Das Brautzimmer<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f23cbe5 elementor-widget elementor-widget-video\" data-id=\"f23cbe5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/QzcnTAR0hg0&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3d375f elementor-widget elementor-widget-text-editor\" data-id=\"b3d375f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Dieser Raum dient als Warte- oder Versammlungsort f\u00fcr eine Braut vor ihrer Trauung, die in einem Siegelungsraum stattfindet. (Siehe #7)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69ca09a elementor-widget elementor-widget-spacer\" data-id=\"69ca09a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54b2548 elementor-widget elementor-widget-heading\" data-id=\"54b2548\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5.\tDer Unterweisungsraum<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07b21f0 elementor-widget elementor-widget-video\" data-id=\"07b21f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/gBhEPTxKFAs&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1357494 elementor-widget elementor-widget-text-editor\" data-id=\"1357494\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Die Mitglieder kommen in den Unterrichtsraum, um mehr \u00fcber die Mission Jesu Christi und Gottes Plan f\u00fcr uns zu erfahren.<\/p><p>\u2022 Durch eine audiovisuelle Pr\u00e4sentation erfahren wir, woher wir kommen, warum wir hier sind und wohin wir gehen, wenn wir sterben.<\/p><p>\u2022 Als Teil der Unterweisung geben die Mitglieder Versprechen ab, B\u00fcndnisse genannt, Gott zu folgen und seine Gebote zu halten.<\/p><p>\u2022 Tempelaltare, wie in diesem Raum, erinnern uns an Jesus Christus und die Erl\u00f6sung, die wir in ihm finden, wenn wir danach streben Gott nahe zu sein.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c48c450 elementor-widget elementor-widget-spacer\" data-id=\"c48c450\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0fae16 elementor-widget elementor-widget-heading\" data-id=\"f0fae16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">6. Celestial Room\u200b<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c4e6bc elementor-widget elementor-widget-video\" data-id=\"6c4e6bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/KwNztlLYBCA&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69c5a9c elementor-widget elementor-widget-text-editor\" data-id=\"69c5a9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Der Celestiale Raum ist einer der heiligsten Orte der Erde, und symbolisiert den Himmel und die Gegenwart Gottes.<\/p><p>\u2022 Der Celestiale Raum ist ein Ort des stillen Nachdenkens und Gebets, wo wir uns Gott nahe und verbunden f\u00fchlen k\u00f6nnen.<\/p><p>\u2022 Es finden keine Zeremonien in diesem heiligen Raum statt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-890baa6 elementor-widget elementor-widget-spacer\" data-id=\"890baa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64f7238 elementor-widget elementor-widget-heading\" data-id=\"64f7238\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">7. Sealing Room\u200b<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d95a75 elementor-widget elementor-widget-video\" data-id=\"5d95a75\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/-bhBw5hyjBI&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55e3778 elementor-widget elementor-widget-text-editor\" data-id=\"55e3778\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u2022 Im Siegelungsraum werden Trauungen oder Siegelungen vollzogen.<\/p><p>\u2022 Ein Paar kniet an einem Altar und wird aneinander gesiegelt, damit ihre Ehe \u00fcber dieses Leben hinaus und in die Ewigkeit dauern kann. Kinder k\u00f6nnen auch an ihre Eltern gesiegelt werden.<\/p><p>\u2022 Die Vollmacht, Familien f\u00fcr immer zu siegeln oder zu binden, wurde dem Apostel Petrus gegeben, wie im Neuen Testament erw\u00e4hnt (Mt 16,19).<\/p><p>\u2022 Wie andere Tempelzeremonien werden auch diese heiligen Handlungen f\u00fcr unsere verstorbenen Vorfahren vollzogen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-739a740 elementor-widget elementor-widget-heading\" data-id=\"739a740\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Virtual Tour (CC)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-138f3ed elementor-widget elementor-widget-text-editor\" data-id=\"138f3ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Erfahren Sie mehr dar\u00fcber, was im Tempel passiert, bei einer virtuellen Tour durch den Washington-DC-Tempel mit Elder und Schwester Stevenson und Elder und Schwester Renlund.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af7eebd elementor-widget elementor-widget-video\" data-id=\"af7eebd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=mUYF1TX5RxM&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d64e960 elementor-widget elementor-widget-spacer\" data-id=\"d64e960\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-161fbbf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"161fbbf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c76692f\" data-id=\"c76692f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89567dd elementor-widget elementor-widget-spacer\" data-id=\"89567dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee2bb05 elementor-widget elementor-widget-heading\" data-id=\"ee2bb05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">To Learn about our Washington D.C. ASL Congregation<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e3fd39 elementor-widget elementor-widget-text-editor\" data-id=\"9e3fd39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\">Besuchen Sie unser\u00a0<a href=\"https:\/\/www.facebook.com\/FollowersofJesusChristinDC.ASL\">Facebook page<\/a>\u00a0or email\u00a0<a href=\"mailto:info@dctemple.org\">info@dctemple.org\u00a0<\/a>with the subject &#8220;ASL Congregation&#8221;<\/span><\/p><p>\u00a0<\/p><p><span style=\"color: #ffffff;\">Erfahren Sie mehr \u00fcber den Washington DC Tempel:<\/span> <a href=\"http:\/\/dctemple.org\/de\/about\/\">dctemple.org\/about<\/a><\/p><p><span style=\"color: #ffffff;\">Erfahren Sie mehr dar\u00fcber, was in Tempeln passiert<\/span> <a href=\"https:\/\/www.churchofjesuschrist.org\/comeuntochrist\/article\/what-happens-inside-latter-day-saint-temples\">hier<\/a><\/p><p><a href=\"https:\/\/clickly.org\/e0s88\">www.kirchejesuchrist.org<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b450c4 elementor-widget elementor-widget-spacer\" data-id=\"0b450c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Language: \u00a0ASL\u00a0 |\u00a0 Chinese\u00a0 |\u00a0 English\u00a0 |\u00a0\u00a0\u00a0French\u00a0\u00a0|\u00a0\u00a0\u00a0German\u00a0\u00a0|\u00a0\u00a0\u00a0Japanese\u00a0\u00a0|\u00a0\u00a0\u00a0Korean\u00a0\u00a0|\u00a0\u00a0\u00a0Persian |\u00a0 \u00a0Portuguese Brazilian |\u00a0\u00a0\u00a0Spanish\u00a0\u00a0|\u00a0\u00a0\u00a0Tagalog THE HOUSE OF THE LORD Washington D.C. Temple\u200b THE CHURCH OF JESUS CHRIST OF LATTER-DAY SAINTS American Sign Language Self-Guided Tour Introduction https:\/\/youtu.be\/sbdQ4hoZlQA As members of The Church of Jesus Christ of Latter-day Saints, we worship God and His Son, Jesus Christ. We come [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-4260","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ASL Tour - DCTemple.org<\/title>\n<meta name=\"description\" content=\"With ASL translations available, tour different rooms in the Washington D.C. Temple of The Church of Jesus Christ of Latter-day Saints today.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dctemple.org\/de\/asl-tour\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASL Tour - DCTemple.org\" \/>\n<meta property=\"og:description\" content=\"With ASL translations available, tour different rooms in the Washington D.C. Temple of The Church of Jesus Christ of Latter-day Saints today.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dctemple.org\/de\/asl-tour\/\" \/>\n<meta property=\"og:site_name\" content=\"DCTemple.org\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-19T17:16:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/asl-tour\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/asl-tour\\\/\",\"name\":\"ASL Tour - DCTemple.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\"},\"datePublished\":\"2022-04-14T22:56:55+00:00\",\"dateModified\":\"2024-07-19T17:16:18+00:00\",\"description\":\"With ASL translations available, tour different rooms in the Washington D.C. Temple of The Church of Jesus Christ of Latter-day Saints today.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/asl-tour\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dctemple.org\\\/asl-tour\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/asl-tour\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dctemple.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASL Tour\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#website\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"name\":\"DCTemple.org\",\"description\":\"Washington D.C. Temple Visitors&#039; Center\",\"publisher\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#organization\",\"name\":\"DCTemple.org\",\"url\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"contentUrl\":\"https:\\\/\\\/dctemple.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/dctemple.org-Logo-e1711558754953.webp\",\"width\":1000,\"height\":400,\"caption\":\"DCTemple.org\"},\"image\":{\"@id\":\"https:\\\/\\\/dctemple.org\\\/fa\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASL Tour - DCTemple.org","description":"With ASL translations available, tour different rooms in the Washington D.C. Temple of The Church of Jesus Christ of Latter-day Saints today.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dctemple.org\/de\/asl-tour\/","og_locale":"de_DE","og_type":"article","og_title":"ASL Tour - DCTemple.org","og_description":"With ASL translations available, tour different rooms in the Washington D.C. Temple of The Church of Jesus Christ of Latter-day Saints today.","og_url":"https:\/\/dctemple.org\/de\/asl-tour\/","og_site_name":"DCTemple.org","article_modified_time":"2024-07-19T17:16:18+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dctemple.org\/asl-tour\/","url":"https:\/\/dctemple.org\/asl-tour\/","name":"ASL Tour - DCTemple.org","isPartOf":{"@id":"https:\/\/dctemple.org\/fa\/#website"},"datePublished":"2022-04-14T22:56:55+00:00","dateModified":"2024-07-19T17:16:18+00:00","description":"With ASL translations available, tour different rooms in the Washington D.C. Temple of The Church of Jesus Christ of Latter-day Saints today.","breadcrumb":{"@id":"https:\/\/dctemple.org\/asl-tour\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dctemple.org\/asl-tour\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dctemple.org\/asl-tour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dctemple.org\/"},{"@type":"ListItem","position":2,"name":"ASL Tour"}]},{"@type":"WebSite","@id":"https:\/\/dctemple.org\/fa\/#website","url":"https:\/\/dctemple.org\/fa\/","name":"DCTemple.org","description":"Washington D.C. Temple Visitors&#039; Center","publisher":{"@id":"https:\/\/dctemple.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dctemple.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dctemple.org\/fa\/#organization","name":"DCTemple.org","url":"https:\/\/dctemple.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","contentUrl":"https:\/\/dctemple.org\/wp-content\/uploads\/2021\/12\/dctemple.org-Logo-e1711558754953.webp","width":1000,"height":400,"caption":"DCTemple.org"},"image":{"@id":"https:\/\/dctemple.org\/fa\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/4260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/comments?post=4260"}],"version-history":[{"count":0,"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/pages\/4260\/revisions"}],"wp:attachment":[{"href":"https:\/\/dctemple.org\/de\/wp-json\/wp\/v2\/media?parent=4260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}]